{"id":12028,"date":"2026-01-06T16:11:44","date_gmt":"2026-01-06T14:11:44","guid":{"rendered":"https:\/\/www.ferembach.com\/cestquilescreas\/?p=12028"},"modified":"2026-01-07T16:23:57","modified_gmt":"2026-01-07T14:23:57","slug":"campese-lefevre","status":"publish","type":"post","link":"https:\/\/www.ferembach.com\/cestquilescreas\/team\/campese-lefevre\/","title":{"rendered":"David Campese &amp; Julien Lef\u00e8vre"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"421\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/david-campese-julien-lefevre-1024x421.jpg\" alt=\"\" class=\"wp-image-12035\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/david-campese-julien-lefevre-980x403.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/david-campese-julien-lefevre-480x197.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<div style=\"height:47px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color has-large-font-size wp-elements-3670e1c2bdc0954aec7fbb26fba20b2d wp-block-paragraph\"><strong>Bonjour messieurs,quels ont \u00e9t\u00e9 vos parcours \u00e9tudiant\/pro ?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8211; <\/strong> <strong>David (<\/strong>en blanc sur la photo, le CR\/DC)<br>J\u2019ai commenc\u00e9 par un doctorat de Philosophie, sp\u00e9cialit\u00e9 \u00e9pist\u00e9mologie et philosophie des sciences et techniques, \u00e0 l\u2019Universit\u00e9 d\u2019Aix-en-Provence. Autrement dit, je passais mes journ\u00e9es \u00e0 questionner la r\u00e9alit\u00e9 des mouvements elyptiques des plan\u00e8tes et de la lune chez Descartes, la monadologie de Leibniz\u2026 avant de me retrouver dans un autre m\u00e9tier o\u00f9 l\u2019on r\u00e9invente la r\u00e9alit\u00e9 tous les jours : la publicit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8211; <\/strong> <strong>Julien <\/strong>(en noir sur la photo le DA\/DC)<br>Salut Gregory ! Apr\u00e8s un bac STI Arts-Appliqu\u00e9s, j\u2019ai fait les Arts-D\u00e9coratifs, puis les Beaux-Arts de Paris. C\u2019\u00e9taient surtout des ann\u00e9es rythm\u00e9es par beaucoup de graffiti et la production d\u2019albums de beats de hip-hop. \u00c0 la fin des Beaux-Arts, j\u2019en ai eu marre de la supercherie de l\u2019art contemporain. Du coup, j\u2019ai pr\u00e9f\u00e9r\u00e9 quitter ce milieu pour rester fid\u00e8le \u00e0 mon engagement artistique et apprendre un m\u00e9tier dans la communication.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u2019ai commenc\u00e9 la pub par un stage dans une petite agence qui s\u2019appelle Monsieur White. Je n\u2019avais aucune exp\u00e9rience mais j\u2019\u00e9tais super motiv\u00e9, et j\u2019ai eu la chance que le boss de cette agence me fasse confiance. Tr\u00e8s vite, j\u2019ai r\u00e9alis\u00e9 que l\u2019univers de la pub que je m\u00e9prisais quelques mois plus t\u00f4t aux Beaux-Arts \u00e9tait en r\u00e9alit\u00e9 passionnant; que je pouvais bosser dix heures par jour avec des amis et qu\u2019on me payait pour faire ce que j\u2019aimais le plus au monde : trouver des id\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ensuite, j\u2019ai fait un an de free avec mon premier r\u00e9dac, puis, quand il est parti chez Ogilvy, je suis rentr\u00e9 chez BETC. L\u00e0, je me suis pris une \u00e9norme claque cr\u00e9ative, du coup j\u2019ai boss\u00e9 jour et nuit pour essayer de sortir des trucs et avoir acc\u00e8s \u00e0 quelques briefs cr\u00e9atifs. Au bout de sept ans, j\u2019ai ressenti un plafond de verre pour \u00e9voluer, du coup Nick Bakshi, qui quittait Milan pour revenir \u00e0 Paris, m\u2019a aid\u00e9 \u00e0 rentrer chez Le Pub \u00e0 Milan. J\u2019ai ensuite fait un petit virage par la Belgique chez Mutant Agency, et maintenant je continue encore de voyager en \u00e9tant \u00e0 New York, chez McCann, un r\u00eave de gosse.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color has-large-font-size wp-elements-2015478691d96969a144a9d98a0e58a7 wp-block-paragraph\"><strong>Comment avez-vous d\u00e9cid\u00e9 de bosser ensemble ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>David<br><\/strong>On pourrait dire que tout a commenc\u00e9 de fa\u00e7on presque mondaine dans les festivals. Je blague car c\u2019est pas vraiment notre truc, mais pas tant que \u00e7a. Fin 2018, on se croisait plus souvent dans les festivals parisiens que dans les couloirs infinis de BETC. \u00c0 force, on a fini par se parler. Puis par se marrer. Puis par r\u00e9aliser qu\u2019on partageait la m\u00eame passion pour les bonnes id\u00e9es et la m\u00eame allergie aux moyennes. Un brief Air France, quelques proacs, et sans trop s\u2019en rendre compte, on \u00e9tait devenus une team. Six ans plus tard, nous voil\u00e0 apr\u00e8s les flammes de Milan \u00e0 New York. Comme quoi, les hasards ont parfois un tres bon sens du timing.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color has-large-font-size wp-elements-eaba635ff7a08a364f6c5882299515c9 wp-block-paragraph\"><strong>Pourquoi \u00eatre parti de Milan au bout d\u2019un an\u202f?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>David <\/strong><br>En r\u00e9alit\u00e9, c\u2019\u00e9tait plut\u00f4t un an et neuf mois. Et chaque mois compte dans une agence comme Le Pub. Apr\u00e8s Cannes, les opportunit\u00e9s sont arriv\u00e9es tr\u00e8s vite. Quand New York se pr\u00e9sente, on ne dit pas \u201cje vais y r\u00e9fl\u00e9chir\u201d, on fait les valises. C\u2019\u00e9tait un r\u00eave, j\u2019ai simplement r\u00e9pondu pr\u00e9sent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Julien <\/strong><br>On est plus proches des deux ans (un an et neuf mois), mais disons qu\u2019on a fait le tour du Pub et de Milan. Apr\u00e8s les r\u00e9compenses de PubSuccession \u00e0 Cannes, les opportunit\u00e9s se sont tr\u00e8s vite pr\u00e9sent\u00e9es, et quand une agence iconique comme McCann NYC te propose de la rejoindre, tu ne peux pas dire non.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color has-large-font-size wp-elements-c4145e56f9bdacb5050fa62ba15b5d0c wp-block-paragraph\"><strong>Pourquoi la publicit\u00e9\u202f?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>David<\/strong><br>Franchement ? Le hasard total. \u00c0 la base, je cherchais un endroit pour faire mon post-doc de philo, mais je voulais le faire en entreprise, histoire de sortir de ma biblioth\u00e8que. Et c\u2019est l\u00e0 qu\u2019un ami r\u00e9alisateur, ancien DA, St\u00e9phane Barbato, a \u00e9t\u00e9 d\u00e9terminant en me parlant d\u2019Havas Marseille. Et l\u00e0, je d\u00e9couvre un monde compl\u00e8tement diff\u00e9rent. Un endroit o\u00f9 on rigole beaucoup, o\u00f9 les id\u00e9es fusent, et o\u00f9 aucune journ\u00e9e ne se ressemble.<br>J\u2019y ai surtout rencontr\u00e9 des gens incroyables. Julien Meurisse, le CR, qui m\u2019a litt\u00e9ralement ouvert les portes du m\u00e9tier. \u00c9ric Guilloux, le boss, qui aimait la cr\u00e9a sinc\u00e8rement, pas juste en discours. Et surtout Philippe Marchon-Arnaud, DA talentueux et v\u00e9ritable encyclop\u00e9die vivante de la cr\u00e9ation. Et \u00e0 ce moment-l\u00e0, je me suis dit un truc tr\u00e8s simple : \u201cOK\u2026 c\u2019est peut-\u00eatre l\u00e0 que je m\u2019amuse le plus. Et c\u2019est peut-\u00eatre l\u00e0 que je veux \u00eatre.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Julien <\/strong><br>Mon m\u00e9moire aux Beaux-Arts portait sur le pouvoir de la publicit\u00e9 et des m\u00e9dias dans la culture populaire. En le r\u00e9digeant, j\u2019ai d\u00e9couvert la \u201cbonne\u201d publicit\u00e9 : Droga, Wieden+Kennedy, les grandes ann\u00e9es de BETC\u2026 et franchement, \u00e7a faisait r\u00eaver. Alors quand j\u2019ai d\u00e9cid\u00e9 de quitter les Beaux-Arts, c\u2019est tout de suite le premier univers cr\u00e9atif qui m\u2019est venu en t\u00eate.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color has-large-font-size wp-elements-a4bf1a8119f25f9ba4b51858cbba33a0 wp-block-paragraph\"><strong>Sinon, vous auriez fait quoi\u202f?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>David C<\/strong><br>Prof de philo, chercheur surement\u2026 ou rock star mais ce plan B n\u2019a jamais \u00e9t\u00e9 tr\u00e8s raisonnable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Julien <\/strong><br>Plus ou moins le m\u00eame m\u00e9tier : graphiste, illustrateur\u2026 Depuis tout petit, je veux \u00eatre illustrateur et inventeur. La seule chose qui aurait pu me faire changer de voie, c\u2019est mon amour pour les chiens.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color has-large-font-size wp-elements-2ade63e49726a09959714ac7f3e70394 wp-block-paragraph\"><strong>Quels sont vos passions\/side projects ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>David <\/strong><br>De la musique rock, garage et surtout bluegrass. Je joue du banjo \u00e0 cinq cordes. J\u2019ai d\u00e9couvert cette culture populaire, ce sens du partage et l\u2019humilit\u00e9 de grands musiciens un peu m\u00e9pris\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toujours plong\u00e9 dans des id\u00e9es de documentaires comme celui que j\u2019avais r\u00e9alis\u00e9 \u201cFrankenstream, cemonstre qui nous d\u00e9vore\u201d au sujet de la pollution du stream pour Art <\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_IRSAml6J8EQ\"><div id=\"lyte_IRSAml6J8EQ\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FIRSAml6J8EQ%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/IRSAml6J8EQ\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FIRSAml6J8EQ%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je passe pas mal de temps aussi \u00e0 bricoler des compositions banjo-guitare, d\u2019enregistrer des trucs et de bidouiller avec de vieilles bo\u00eetes \u00e0 rythmes. Pour \u00e7a je fouine sur eBay, Reverb et Leboncoin pour agrandir ma collection d\u2019instruments des ann\u00e9es 60. Et puis, j\u2019ai un int\u00e9r\u00eat presque addictif pour la \u201ct\u00e9l\u00e9 poubelle\u201d. La t\u00e9l\u00e9r\u00e9alit\u00e9, pour moi, c\u2019est un zoo social\u202f: fascinant, souvent absurde, impossible \u00e0 l\u00e2cher, compl\u00e8tement addictif\u2026 et incroyablement passionnant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Julien L <\/strong><br>J\u2019aime plein de choses : le graffiti (pas le street-art, hein, le graffiti), le graphisme et l\u2019illustration, je digg beaucoup de sons de rap et de hip-hop, le bushcraft, le kigumi (menuiserie japonaise), le bricolage (j\u2019ai achet\u00e9 un appartement que j\u2019ai enti\u00e8rement refait), le design et l\u2019architecture, la montagne, je joue beaucoup aux \u00e9checs et \u00e0 Fortnite, j\u2019ai une grosse passion pour Secrets d\u2019Histoire, le tennis\u2026<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color has-large-font-size wp-elements-11fcc1971f4559b845030864a9c92e3b wp-block-paragraph\"><strong>Parlez-nous de vos campagnes :<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>David <br><\/strong>La premi\u00e8re, c\u2019\u00e9tait pour le Black Renovator de Decolor Stop.<strong> <\/strong>Je venais tout juste d\u2019arriver \u00e0 Paris avec cette id\u00e9e de prints pour le renovateur de couleurs, mes croquis sous le bras, et ce principe de tampons dont le noir se d\u00e9grade pour raconter une histoire. Et me voil\u00e0 \u00e0 2h du matin chez Andrea Stillacci, chez H\u00e9r\u00e9zie, pendant un creative run o\u00f9 tu pouvais simplement venir montrer ton travail. Assez irr\u00e9el comme d\u00e9but.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ensuite, en arrivant chez BETC, il y a eu Game Changers pour l\u2019UNICEF. L\u2019id\u00e9e \u00e9tait presque trop simple : et si le temps o\u00f9 les gamers ne jouent pas devenait du don ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">On a donc cr\u00e9\u00e9 des pools de minage Ethereum qui s\u2019activaient quand ils \u00e9taient AFK. Leur puissance de calcul g\u00e9n\u00e9rait de l\u2019argent, revers\u00e9 \u00e0 l\u2019UNICEF, sans jamais demander un centime aux gens.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019\u00e9tait une p\u00e9riode assez folle, la crypto \u00e9tait encore un territoire inconnu. Et clairement, sans St\u00e9phane Xiberras, qui a eu le courage de dire oui quand personne ne comprenait vraiment, le projet ne serait jamais sorti.<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_nZOo4Ug5PTU\"><div id=\"lyte_nZOo4Ug5PTU\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FnZOo4Ug5PTU%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/nZOo4Ug5PTU\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FnZOo4Ug5PTU%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\"><strong>Il y a eu aussi Orangina avec le spot Lucha Libre. <\/strong>Un tournage dans les montagnes mexicaines o\u00f9, tr\u00e8s vite, tout le village s\u2019est retrouv\u00e9 \u00e0 faire le film. Figurants, assistants, techniciens improvis\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pas un tournage classique, plut\u00f4t une f\u00eate collective. Beaucoup d\u2019\u00e9nergie, beaucoup de joie, et ce sentiment rare que la pub se fabrique avec les gens, pas \u00e0 c\u00f4t\u00e9 d\u2019eux.<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_p0l9yN12x4w\"><div id=\"lyte_p0l9yN12x4w\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2Fp0l9yN12x4w%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/p0l9yN12x4w\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2Fp0l9yN12x4w%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">Puis&nbsp; des frigos dans le d\u00e9sert marocain, l\u00e0 o\u00f9 l\u2019\u00e9lectricit\u00e9 n\u2019existe pas avec Bud Cooler.<strong> <\/strong>C&rsquo;\u00e9tait pas pour faire joli, mais pour aider les commer\u00e7ants des petits villages \u00e0 garder leurs boissons fra\u00eeches. Une id\u00e9e simple, hyper concr\u00e8te, o\u00f9 la marque arr\u00eate de parler et commence \u00e0 \u00eatre utile.<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_E_8HacAzELE\"><div id=\"lyte_E_8HacAzELE\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FE_8HacAzELE%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/E_8HacAzELE\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FE_8HacAzELE%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">L\u2019ann\u00e9e derni\u00e8re, au Pub \u00e0 Milan, on a eu la chance de d\u00e9fendre une id\u00e9e assez folle : Pub Succession. \u00c7a part d\u2019une histoire tr\u00e8s simple, tr\u00e8s vraie. Un pub irlandais, celui de Josie McLaughlin, \u00e9tait sur le point de dispara\u00eetre parce qu\u2019il n\u2019y avait plus personne pour le reprendre. Et plut\u00f4t que de voir, encore une fois, un McDo pousser \u00e0 la place, on s\u2019est pos\u00e9 une question tr\u00e8s directe : et si on essayait vraiment de le sauver ? Mais le sauver pour de vrai, pas juste \u00e0 travers une activation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">On a donc lanc\u00e9 un appel mondial pour lui trouver un successeur. Pourquoi ? Parce qu\u2019il y a aujourd\u2019hui plus d\u2019Irlandais exil\u00e9s dans le monde que sur le sol irlandais, et parce qu\u2019il existe une loi irlandaise du XIX\u1d49 si\u00e8cle qui stipule que le propri\u00e9taire d\u2019un pub doit porter le m\u00eame nom que celui inscrit au-dessus de la porte. \u00c0 partir de l\u00e0, tout est devenu fou. On est partis \u00e0 la recherche d\u2019un McLaughlin partout dans le monde. Jusqu\u2019\u00e0 Times Square, litt\u00e9ralement. Et \u00e0 ce moment-l\u00e0, tu comprends que ce n\u2019est plus juste une id\u00e9e d&rsquo;activation. C\u2019est une aventure humaine, ancr\u00e9e dans l\u2019histoire, qui parle \u00e0 la fois du pass\u00e9, du pr\u00e9sent et du futur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se battre pour un pub, c\u2019est sauver une culture populaire, un lieu de rencontre quotidien, une m\u00e9moire collective o\u00f9 les gens se retrouvent.<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_Cu0FLBdZrcM\"><div id=\"lyte_Cu0FLBdZrcM\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FCu0FLBdZrcM%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/Cu0FLBdZrcM\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FCu0FLBdZrcM%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Julien <\/strong><br>Le film The Little Duck pour Disneyland (Alban Gall\u00e9e \u00e0 la r\u00e9dac) :<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_G4qMqbL9ACo\"><div id=\"lyte_G4qMqbL9ACo\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FG4qMqbL9ACo%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/G4qMqbL9ACo\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FG4qMqbL9ACo%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">Des lunettes super moches mais qui enl\u00e8vent le mal des transports. Dans la vie, faut parfois faire un choix entre le beau et l\u2019utile, d\u00e9sol\u00e9 :<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_j7jD_n_-73s\"><div id=\"lyte_j7jD_n_-73s\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2Fj7jD_n_-73s%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/j7jD_n_-73s\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2Fj7jD_n_-73s%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">On a remplac\u00e9 les tourniquets du m\u00e9tro par des \u00e9oliennes pour produire l\u2019\u00e9nergie des stations de m\u00e9tro gr\u00e2ce au passage des usagers :<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_j-hCfL3HF6k\"><div id=\"lyte_j-hCfL3HF6k\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2Fj-hCfL3HF6k%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/j-hCfL3HF6k\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2Fj-hCfL3HF6k%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">On a d\u00e9velopp\u00e9 avec les ing\u00e9nieurs de Frog Design un frigo qui marche sans \u00e9lectricit\u00e9 (assez fou, mais ce n\u2019est pas un ghost) :<br><a href=\"https:\/\/www.youtube.com\/watch?v=E_8HacAzELE\">https:\/\/www.youtube.com\/watch?v=E_8HacAzELE<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">On a fait un film d\u2019animation compl\u00e8tement illisible pour Hennessy avec Ugo Gattoni, qui ne reprend une forme normale qu\u2019\u00e0 travers un verre de cognac :<br><a href=\"https:\/\/www.dandad.org\/work\/d-ad-awards-archive\/hennesscreen\">https:\/\/www.dandad.org\/work\/d-ad-awards-archive\/hennesscreen<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">On a particip\u00e9 \u00e0 un hack gigantesque de la loi Evin pour le lancement de Budweiser en France pendant la coupe du monde :<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"VersionFR_BUDWEISER\" src=\"https:\/\/player.vimeo.com\/video\/881293757?dnt=1&amp;app_id=122963\" width=\"1080\" height=\"608\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">On a exp\u00e9riment\u00e9 la premi\u00e8re g\u00e9n\u00e9ration d\u2019outils d\u2019IA g\u00e9n\u00e9ratifs pour montrer \u00e0 quel point les innovations permettent d\u2019\u00e9liminer la barri\u00e8re de l\u2019inaccessibilit\u00e9 \u00e0 certains emplois pour les personnes porteuses de handicap :<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"LADAPT - case ST\" src=\"https:\/\/player.vimeo.com\/video\/906901287?dnt=1&amp;app_id=122963\" width=\"1080\" height=\"608\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">On a rendu hommage aux pionniers de la marche des fiert\u00e9s en France en leur permettant de continuer \u00e0 assister au d\u00e9fil\u00e9 malgr\u00e9 leur \u00e2ge en 2024 :<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_rSvKynk_Qhg\"><div id=\"lyte_rSvKynk_Qhg\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FrSvKynk_Qhg%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/rSvKynk_Qhg\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FrSvKynk_Qhg%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">On a cr\u00e9\u00e9 un monde dans Minecraft avec Axel Bierne en renversant les codes du jeu pour aider les dyslexiques \u00e0 \u00eatre d\u00e9pist\u00e9s sans se sentir jug\u00e9s comme quelqu\u2019un de diff\u00e9rent :<br><a href=\"https:\/\/www.dandad.org\/work\/d-ad-awards-archive\/mindcraft\">https:\/\/www.dandad.org\/work\/d-ad-awards-archive\/mindcraft<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et enfin, on a aid\u00e9 les patrons de pubs irlandais \u00e0 trouver des repreneurs pour \u00e9viter de voir dispara\u00eetre un de leurs embl\u00e8mes nationaux  (\u00e0 voir un peu plus haut dans la s\u00e9lection de David)<br><a href=\"https:\/\/youtu.be\/Cu0FLBdZrcM\">https:\/\/youtu.be\/Cu0FLBdZrcM<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color has-large-font-size wp-elements-fa9634659bd96408165e315f77fda1d0 wp-block-paragraph\"><strong>Quels sont vos meilleurs ou pires souvenirs d\u2019agence<\/strong> ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>David C: Il y a eu les meilleurs souvenirs de tournage. Sans h\u00e9siter, BETC et les tournages sauvages pour BUUUUD dans les gares parisiennes, le m\u00e9tro, la rue, les bars, les \u00e9piceries\u2026<\/strong> C\u2019\u00e9tait de l\u2019adr\u00e9naline pure, cette sensation de faire quelque chose d\u2019un peu interdit. Franchement, c\u2019\u00e9tait trop bien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il y a eu aussi ce Tour de France en van pour Bouygues. <\/strong>Pendant deux semaines, on a travers\u00e9 toute la France pour tester la qualit\u00e9 du r\u00e9seau comme de vrais explorateurs num\u00e9riques, toujours en mouvement, \u00e0 la merci du terrain. Et en parall\u00e8le, on d\u00e9couvrait les Airbnb les plus improbables : des \u00e9glises, des chalets chelous, des petits ch\u00e2teaux\u2026 Une vraie aventure.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Et puis Orangina au Mexique. <\/strong>L\u00e0, on \u00e9tait clairement dans l\u2019exp\u00e9rience hors norme. Tlayacapan, ce village perdu dans les montagnes, ces gens incroyables\u2026 le genre de tournage qui te marque \u00e0 vie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Apr\u00e8s, m\u00eame dans les pires moments, il y a aussi BUUUUD.<\/strong> Le retrait de la campagne \u00e0 Cannes pour des raisons juridiques, apr\u00e8s des mois de travail sous une \u00e9norme tension, a \u00e9t\u00e9 un coup tr\u00e8s violent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Et puis l\u2019ann\u00e9e derni\u00e8re, encore un tournage Desperados annul\u00e9 juste apr\u00e8s avoir \u00e9t\u00e9 vendu, au moment m\u00eame o\u00f9 j\u2019arrivais dans la bo\u00eete.<\/strong> On avait un super film et tout s\u2019est arr\u00eat\u00e9 net. Autant dire une entr\u00e9e en mati\u00e8re assez brutale \u00e0 Milan, mais assez symptomatique du Pub.<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_IifWczSADy4\"><div id=\"lyte_IifWczSADy4\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FIifWczSADy4%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/IifWczSADy4\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FIifWczSADy4%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\"><strong>Julien L<\/strong><br>Il y a eu pas mal de shoots incroyables, mais ce que je retiens surtout, ce sont les rencontres avec des gens passionn\u00e9s et inspirants, crois\u00e9es au fil des diff\u00e9rents projets. Les gens anim\u00e9s par quelque chose, je trouve \u00e7a fascinant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il y a aussi eu beaucoup de pires moments, mais je crois qu\u2019on ne peut pas faire ce m\u00e9tier sans aimer se faire plaisir dans la douleur.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color has-large-font-size wp-elements-47fb7909f57fc6c9c025b589b1d97c36 wp-block-paragraph\"><strong>C\u2019est qui ta g\u00e9n\u00e9ration de cr\u00e9as, ceux avec qui tu grandis ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>David <\/strong><br><strong> Je viens clairement de l\u2019\u00e9cole BETC, donc forc\u00e9ment, beaucoup de mes r\u00e9f\u00e9rences viennent de l\u00e0.<\/strong> J\u2019ai grandi aupr\u00e8s de mentors comme St\u00e9phane Xiberras, R\u00e9mi Babinet, David Soussan ou Marie-\u00c8ve Shoettl, qui m\u2019ont appris \u00e0 penser la cr\u00e9ation comme quelque chose de beaucoup plus large que juste \u201cune bonne id\u00e9e\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et puis il y a tous ceux dont j\u2019ai pu admirer le travail de tr\u00e8s pr\u00e8s, comme Crystel Jung ou Mathieu Bouillot, et ceux avec qui j\u2019ai eu la chance de bosser, comme David Martin, Nicolas Dumesnil, Chris Oldcorn &amp; Kais Brami, Alexandre Toso, Patrice Dumas ou JC Royer. Ce qui m&rsquo;a nourrit chez eux, c\u2019est cette obsession commune pour l\u2019id\u00e9e et pour la mani\u00e8re de la raconter. Ne jamais s\u00e9parer le fond de la forme, la strat\u00e9gie de l\u2019\u00e9motion. Grandir \u00e0 leurs c\u00f4t\u00e9s, \u00e7a m\u2019a appris que la cr\u00e9ation, ce n\u2019est pas juste trouver un truc malin, c\u2019est construire un point de vue, une \u00e9criture, presque une mise en sc\u00e8ne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Julien <\/strong><br><strong> <\/strong>Je pense que je fais partie de la g\u00e9n\u00e9ration de cr\u00e9as \u00e0 qui l\u2019on a demand\u00e9 de r\u00e9imaginer les formats classiques de la pub avec l\u2019arriv\u00e9e du digital, des r\u00e9seaux sociaux et des activations.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color has-large-font-size wp-elements-4635ba2c7842fd32e7816717e3a23a88 wp-block-paragraph\"><strong>Quels sont tes pubs pr\u00e9f\u00e9r\u00e9es, tes classiques<\/strong> ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>David <\/strong><br><strong>Les spots du Festival du film ind\u00e9pendant de Buenos Aires m\u2019ont marqu\u00e9es profond\u00e9ment. <\/strong>C&rsquo;est juste, \u00e7a parle sans langue de bois des films de ce genre, de leur libert\u00e9 radicale et aussi du cot\u00e9 un peu de leur cot\u00e9 sectaire mais avec cette capacit\u00e9 \u00e0 surprendre avec un chat qui fume la pipe, \u00e0 jouer avec les codes avec des moustaches qui ne parlent qu&rsquo;\u00e0 certains, \u00e0 raconter des histoires avec peu de moyens mais beaucoup de justesse. Il y avait cette \u00e9nergie qui m\u2019inspire encore aujourd\u2019hui dans de nombreux projets.<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_sL6jX2TTSZg\"><div id=\"lyte_sL6jX2TTSZg\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FsL6jX2TTSZg%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/sL6jX2TTSZg\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FsL6jX2TTSZg%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_KNEaSf4_0Jc\"><div id=\"lyte_KNEaSf4_0Jc\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FKNEaSf4_0Jc%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/KNEaSf4_0Jc\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FKNEaSf4_0Jc%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_JVAAoOCYIA4\"><div id=\"lyte_JVAAoOCYIA4\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FJVAAoOCYIA4%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/JVAAoOCYIA4\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FJVAAoOCYIA4%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\"><strong>Mais si je devais choisir le graal absolu, c\u2019est Moldy Burger. <\/strong>La perfection du bizarre ma\u00eetris\u00e9. Je n&rsquo;en reviens toujours pas de cette campagne. Elle est tellement provocante pour l&rsquo;industrie et pour nous tous en tant que conso. C&rsquo;est beau cette v\u00e9rit\u00e9, ce m\u00e9lange de surprise et d&rsquo;audace pour parler de notre mani\u00e8re de consommer : on ressent \u00e0 la fois l\u2019audace et le contr\u00f4le, le fun et la ma\u00eetrise qui sont au service de BK certes mais qui va plus loin.<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_LzKX-_PiJ5Q\"><div id=\"lyte_LzKX-_PiJ5Q\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FLzKX-_PiJ5Q%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/LzKX-_PiJ5Q\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FLzKX-_PiJ5Q%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\"><strong>Dans la m\u00eame veine, la campagne des bi\u00e8res Tecate avec Gulf Of Mexico m\u2019a profond\u00e9ment parl\u00e9 cette ann\u00e9e, mais pour une raison diff\u00e9rente : elle portait un message engag\u00e9. <\/strong>L\u2019industrie publicitaire emprunte beaucoup aux cultures des diff\u00e9rents pays pour ses visuels et son storytelling, mais trop souvent sans s\u2019engager vraiment pour ces cultures lorsque c\u2019est n\u00e9cessaire. Cette campagne envoyait un signal clair \u00e0 notre profession, un message pousse \u00e0 r\u00e9fl\u00e9chir.<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_oO9cLnswwq0\"><div id=\"lyte_oO9cLnswwq0\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FoO9cLnswwq0%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/oO9cLnswwq0\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FoO9cLnswwq0%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">Franchement, il y a un spot que j\u2019ai trouv\u00e9 compl\u00e8tement dingue l\u2019ann\u00e9e derni\u00e8re. On y voit un chimpanz\u00e9 qui chante de l\u2019op\u00e9ra, un air italien de L\u2019elisir d\u2019amore de Donizetti. Et pendant qu\u2019il chante, le film te fait traverser 3 milliards d\u2019ann\u00e9es d\u2019histoire naturelle en \u00e0 peine 3 minutes. C\u2019est hyper fort visuellement, tr\u00e8s \u00e9mouvant, presque hypnotique. <strong>Et en fait, c\u2019est une campagne pour le Royal Ontario Museum, le mus\u00e9e d\u2019histoire naturelle de Toronto, au Canada.<\/strong> Ce que j\u2019adore, c\u2019est le contraste d&rsquo;un singe humanis\u00e9 fa\u00e7on Kubrick qui chante de l\u2019op\u00e9ra pour raconter l\u2019histoire du vivant mais aussi en particulier la notre \u00e0 travers l&rsquo;art. C\u2019est inattendu, po\u00e9tique, et \u00e7a te rappelle \u00e0 quel point le temps et la nature nous d\u00e9passent.<br><\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_JwtoQf6RLlM\"><div id=\"lyte_JwtoQf6RLlM\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FJwtoQf6RLlM%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/JwtoQf6RLlM\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FJwtoQf6RLlM%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\"><strong>Ces campagnes me parlent et m&rsquo;accompagnent pour des raisons diff\u00e9rentes\u202f: <\/strong>certaines pour leur libert\u00e9 cr\u00e9ative et leur ma\u00eetrise du bizarre, d\u2019autres pour la conscience sociale et culturelle int\u00e9gr\u00e9e \u00e0 la cr\u00e9ativit\u00e9. Elles r\u00e9sument parfaitement ce que j\u2019aime dans ce m\u00e9tier\u202f: surprendre, toucher, et laisser un impact qui d\u00e9passe les id\u00e9es r\u00e9chauff\u00e9es autour d\u2019un produit.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Julien <\/strong><br>Ikea &#8211; Lamp<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_dBqhIVyfsRg\"><div id=\"lyte_dBqhIVyfsRg\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FdBqhIVyfsRg%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/dBqhIVyfsRg\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FdBqhIVyfsRg%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">Responsibly &#8211; The Beer<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_tGD3yg_lqC4\"><div id=\"lyte_tGD3yg_lqC4\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FtGD3yg_lqC4%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/tGD3yg_lqC4\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FtGD3yg_lqC4%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">Cadbury &#8211; Mum&rsquo;s Birthday<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_TfMt3HN8tuY\"><div id=\"lyte_TfMt3HN8tuY\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FTfMt3HN8tuY%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/TfMt3HN8tuY\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FTfMt3HN8tuY%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">Suntory &#8211; High Blood Pressure<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_-LxbqKe-UWA\"><div id=\"lyte_-LxbqKe-UWA\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2F-LxbqKe-UWA%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/-LxbqKe-UWA\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2F-LxbqKe-UWA%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">Aeromexico &#8211; DNA Discounts<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_X42SW5FDebs\"><div id=\"lyte_X42SW5FDebs\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FX42SW5FDebs%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/X42SW5FDebs\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FX42SW5FDebs%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">Peugeot &#8211; Playtime is Over<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_R5r7b7eMtmI\"><div id=\"lyte_R5r7b7eMtmI\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FR5r7b7eMtmI%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/R5r7b7eMtmI\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FR5r7b7eMtmI%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">Pepsi&nbsp; &#8211; Vending Machine<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_XINImbZzU7I\"><div id=\"lyte_XINImbZzU7I\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FXINImbZzU7I%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/XINImbZzU7I\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FXINImbZzU7I%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">Air France &#8211; L\u2019envol<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_ivYr-eQJxUA\"><div id=\"lyte_ivYr-eQJxUA\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FivYr-eQJxUA%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/ivYr-eQJxUA\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FivYr-eQJxUA%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">Take 5 Car Wash &#8211; The Official Pigeon<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_ZqvJByf0kkg\"><div id=\"lyte_ZqvJByf0kkg\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FZqvJByf0kkg%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/ZqvJByf0kkg\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FZqvJByf0kkg%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color has-large-font-size wp-elements-33c1beeb956bb6f9dcc5f34dce173cc2 wp-block-paragraph\"><strong>Vous avez des mod\u00e8les dans, ou hors pub ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>David <\/strong><br>Gabriel Gaultier pour la plume, Pollock pour la libert\u00e9 et la foi, Will Ferrell pour l\u2019absurde, Julian Casablancas pour l\u2019attitude, John Hartford pour le banjo. <br>Au cin\u00e9ma\u202f: les fr\u00e8res Coen. Et puis les Kairas et les Frates marseillais de la t\u00e9l\u00e9r\u00e9alit\u00e9\u202f! L\u2019inspiration vient aussi des marges.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/Capture-decran-2026-01-06-a-14.58.59-1024x504.png\" alt=\"\" class=\"wp-image-12032\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Julien <\/strong><br>Ayant fait mes armes chez BETC, j\u2019ai \u00e9norm\u00e9ment de respect pour l\u2019ambition et l\u2019excellence cr\u00e9ative de St\u00e9phane Xiberras, pour la vision de R\u00e9mi Babinet, qui a cass\u00e9 les cloisons entre publicit\u00e9, art et culture tout au long de sa carri\u00e8re, et pour les combats et l\u2019engagement de Mercedes Erra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u2019admire beaucoup le travail de cr\u00e9as comme Alexis Benbehe et Pierre Mathonat, Andrey Tyukavkin, Xavier Blais, S\u00e9bastien Rouvi\u00e8re, les BNF chez Ogilvy &amp; Mather, et David Martin, avec qui j\u2019ai eu la chance de collaborer plus tard.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hors pub, je suis aussi tr\u00e8s inspir\u00e9 par Sebasti\u00e3o Salgado, qui nous a quitt\u00e9s cette ann\u00e9e. Je trouve son travail photographique incroyable, et tout ce qu\u2019il a accompli en parall\u00e8le est tout aussi impressionnant.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"529\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/Capture-decran-2026-01-06-a-14.57.53-1024x529.png\" alt=\"\" class=\"wp-image-12031\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/Capture-decran-2026-01-06-a-14.57.53-980x506.png 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/Capture-decran-2026-01-06-a-14.57.53-480x248.png 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color has-large-font-size wp-elements-e6745002bbf0f4cf4776140de15b7c1b wp-block-paragraph\"><strong>On peut reprocher quoi aux agences<\/strong> ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>David<\/strong><br>Parfois de compliquer ce qui devrait rester simple. D&rsquo;oublier l&rsquo;\u00e9motion. Confondre process et cr\u00e9ativit\u00e9. Courir apr\u00e8s les deadlines au lieu de courir apr\u00e8s les bonnes id\u00e9es et l\u2019audace.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Julien <\/strong><br>Je n\u2019ai aucun reproche \u00e0 faire aux agences, m\u00eame si j\u2019ai moi aussi des frustrations.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je pense qu\u2019il faut encourager ceux qui tiennent encore la barre en d\u00e9fendant un peu d\u2019intelligence et de cr\u00e9ativit\u00e9 dans un contexte aussi hostile, et f\u00e9liciter ceux qui arrivent encore \u00e0 sortir de (vrais) beaux projets.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color has-large-font-size wp-elements-2d26c1ad2ec8b8c811f6d612d72a9c2f wp-block-paragraph\"><strong>Si vous deviez donner des conseils pour bien d\u00e9marrer dans ce m\u00e9tier, ce serait ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>David <\/strong><br><strong>Soyez curieux, soyez culott\u00e9, trouvez votre bande\u2026 comme le UDGE par exemple et faites en sorte que les id\u00e9es soient plus fortes que les slides<\/strong>. N\u2019h\u00e9sitez pas \u00e0 bouger, \u00e0 traverser les villes, les pays, le monde, l\u00e0 o\u00f9 les opportunit\u00e9s se pr\u00e9sentent. Allez chercher ce qui vous fait vibrer, pas seulement ce qui rassure. Et j\u2019ai un message aux IA, aidez-nous \u00e0 aller plus vite, \u00e0 aller plus loin\u2026 mais laissez-nous l\u2019audace, le doute et l\u2019intuition. Parce qu\u2019au final, les id\u00e9es qui comptent naissent encore d\u2019une \u00e9tincelle tr\u00e8s tr\u00e8s imparfaite et humaine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Julien <\/strong><br>Je ne sais pas si je peux donner un conseil, mais voici 2-3 trucs que je me dis \u00e0 moi-m\u00eame :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ne sois jamais satisfait, oublie ton ego, bats-toi pour tes convictions si c\u2019est justifi\u00e9, ne fais pas de choix de carri\u00e8re pour l\u2019argent, ne pr\u00e9sente pas un projet pour lequel tu n\u2019es pas pr\u00eat \u00e0 sacrifier six mois de ta vie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour messieurs,quels ont \u00e9t\u00e9 vos parcours \u00e9tudiant\/pro ?&nbsp; &#8211; David (en blanc sur la photo, le CR\/DC)J\u2019ai commenc\u00e9 par un doctorat de Philosophie, sp\u00e9cialit\u00e9 \u00e9pist\u00e9mologie et philosophie des sciences et techniques, \u00e0 l\u2019Universit\u00e9 d\u2019Aix-en-Provence. Autrement dit, je passais mes journ\u00e9es \u00e0 questionner la r\u00e9alit\u00e9 des mouvements elyptiques des plan\u00e8tes et de la lune chez Descartes, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":12034,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_uag_custom_page_level_css":"","footnotes":""},"categories":[5,25,6,36],"tags":[],"class_list":["post-12028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-directeurs-artistiques","category-directeur-de-creation","category-redacteur","category-team"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>David Campese &amp; Julien Lef\u00e8vre &#8226; C&#039;est qui les Cr\u00e9as ?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ferembach.com\/cestquilescreas\/team\/campese-lefevre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"David Campese &amp; Julien Lef\u00e8vre &#8226; C&#039;est qui les Cr\u00e9as ?\" \/>\n<meta property=\"og:description\" content=\"Bonjour messieurs,quels ont \u00e9t\u00e9 vos parcours \u00e9tudiant\/pro ?&nbsp; &#8211; David (en blanc sur la photo, le CR\/DC)J\u2019ai commenc\u00e9 par un doctorat de Philosophie, sp\u00e9cialit\u00e9 \u00e9pist\u00e9mologie et philosophie des sciences et techniques, \u00e0 l\u2019Universit\u00e9 d\u2019Aix-en-Provence. Autrement dit, je passais mes journ\u00e9es \u00e0 questionner la r\u00e9alit\u00e9 des mouvements elyptiques des plan\u00e8tes et de la lune chez Descartes, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ferembach.com\/cestquilescreas\/team\/campese-lefevre\/\" \/>\n<meta property=\"og:site_name\" content=\"C&#039;est qui les Cr\u00e9as ?\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CestquilesCreas\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-06T14:11:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-07T14:23:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"626\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gregory ferembach\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"gregory ferembach\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/team\\\/campese-lefevre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/team\\\/campese-lefevre\\\/\"},\"author\":{\"name\":\"gregory ferembach\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/person\\\/228b651374249a02f20a1921f0e2516b\"},\"headline\":\"David Campese &amp; Julien Lef\u00e8vre\",\"datePublished\":\"2026-01-06T14:11:44+00:00\",\"dateModified\":\"2026-01-07T14:23:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/team\\\/campese-lefevre\\\/\"},\"wordCount\":3943,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/team\\\/campese-lefevre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/campese-lefevre.jpg\",\"articleSection\":[\".Directeur Artistique\",\".Directeur de Cr\u00e9ation\",\".R\u00e9dacteur\",\".Team\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/team\\\/campese-lefevre\\\/\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/team\\\/campese-lefevre\\\/\",\"name\":\"David Campese &amp; Julien Lef\u00e8vre &#8226; C&#039;est qui les Cr\u00e9as ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/team\\\/campese-lefevre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/team\\\/campese-lefevre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/campese-lefevre.jpg\",\"datePublished\":\"2026-01-06T14:11:44+00:00\",\"dateModified\":\"2026-01-07T14:23:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/team\\\/campese-lefevre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/team\\\/campese-lefevre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/team\\\/campese-lefevre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/campese-lefevre.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/campese-lefevre.jpg\",\"width\":900,\"height\":626},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/team\\\/campese-lefevre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"David Campese &amp; Julien Lef\u00e8vre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#website\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\",\"name\":\"C'est qui les Cr\u00e9as ?\",\"description\":\"D\u00e9couvrez les cr\u00e9atifs, leurs parcours et leurs (en)vies...\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\",\"name\":\"C'est qui les Cr\u00e9as ?\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-cqlc-1024x368-3.png\",\"contentUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-cqlc-1024x368-3.png\",\"width\":1024,\"height\":368,\"caption\":\"C'est qui les Cr\u00e9as ?\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CestquilesCreas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/person\\\/228b651374249a02f20a1921f0e2516b\",\"name\":\"gregory ferembach\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"caption\":\"gregory ferembach\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"David Campese &amp; Julien Lef\u00e8vre &#8226; C&#039;est qui les Cr\u00e9as ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ferembach.com\/cestquilescreas\/team\/campese-lefevre\/","og_locale":"fr_FR","og_type":"article","og_title":"David Campese &amp; Julien Lef\u00e8vre &#8226; C&#039;est qui les Cr\u00e9as ?","og_description":"Bonjour messieurs,quels ont \u00e9t\u00e9 vos parcours \u00e9tudiant\/pro ?&nbsp; &#8211; David (en blanc sur la photo, le CR\/DC)J\u2019ai commenc\u00e9 par un doctorat de Philosophie, sp\u00e9cialit\u00e9 \u00e9pist\u00e9mologie et philosophie des sciences et techniques, \u00e0 l\u2019Universit\u00e9 d\u2019Aix-en-Provence. Autrement dit, je passais mes journ\u00e9es \u00e0 questionner la r\u00e9alit\u00e9 des mouvements elyptiques des plan\u00e8tes et de la lune chez Descartes, [&hellip;]","og_url":"https:\/\/www.ferembach.com\/cestquilescreas\/team\/campese-lefevre\/","og_site_name":"C&#039;est qui les Cr\u00e9as ?","article_publisher":"https:\/\/www.facebook.com\/CestquilesCreas\/","article_published_time":"2026-01-06T14:11:44+00:00","article_modified_time":"2026-01-07T14:23:57+00:00","og_image":[{"width":900,"height":626,"url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre.jpg","type":"image\/jpeg"}],"author":"gregory ferembach","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"gregory ferembach","Dur\u00e9e de lecture estim\u00e9e":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/team\/campese-lefevre\/#article","isPartOf":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/team\/campese-lefevre\/"},"author":{"name":"gregory ferembach","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/person\/228b651374249a02f20a1921f0e2516b"},"headline":"David Campese &amp; Julien Lef\u00e8vre","datePublished":"2026-01-06T14:11:44+00:00","dateModified":"2026-01-07T14:23:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/team\/campese-lefevre\/"},"wordCount":3943,"publisher":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/team\/campese-lefevre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre.jpg","articleSection":[".Directeur Artistique",".Directeur de Cr\u00e9ation",".R\u00e9dacteur",".Team"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/team\/campese-lefevre\/","url":"https:\/\/www.ferembach.com\/cestquilescreas\/team\/campese-lefevre\/","name":"David Campese &amp; Julien Lef\u00e8vre &#8226; C&#039;est qui les Cr\u00e9as ?","isPartOf":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/team\/campese-lefevre\/#primaryimage"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/team\/campese-lefevre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre.jpg","datePublished":"2026-01-06T14:11:44+00:00","dateModified":"2026-01-07T14:23:57+00:00","breadcrumb":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/team\/campese-lefevre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ferembach.com\/cestquilescreas\/team\/campese-lefevre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/team\/campese-lefevre\/#primaryimage","url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre.jpg","contentUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre.jpg","width":900,"height":626},{"@type":"BreadcrumbList","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/team\/campese-lefevre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ferembach.com\/cestquilescreas\/"},{"@type":"ListItem","position":2,"name":"David Campese &amp; Julien Lef\u00e8vre"}]},{"@type":"WebSite","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#website","url":"https:\/\/www.ferembach.com\/cestquilescreas\/","name":"C'est qui les Cr\u00e9as ?","description":"D\u00e9couvrez les cr\u00e9atifs, leurs parcours et leurs (en)vies...","publisher":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ferembach.com\/cestquilescreas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization","name":"C'est qui les Cr\u00e9as ?","url":"https:\/\/www.ferembach.com\/cestquilescreas\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/logo\/image\/","url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2020\/02\/logo-cqlc-1024x368-3.png","contentUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2020\/02\/logo-cqlc-1024x368-3.png","width":1024,"height":368,"caption":"C'est qui les Cr\u00e9as ?"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CestquilesCreas\/"]},{"@type":"Person","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/person\/228b651374249a02f20a1921f0e2516b","name":"gregory ferembach","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","caption":"gregory ferembach"}}]}},"uagb_featured_image_src":{"full":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre.jpg",900,626,false],"thumbnail":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre-120x120.jpg",120,120,true],"medium":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre-60x42.jpg",60,42,true],"medium_large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre-768x534.jpg",768,534,true],"large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre.jpg",900,626,false],"1536x1536":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre.jpg",900,626,false],"2048x2048":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre.jpg",900,626,false],"et-pb-post-main-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre-400x250.jpg",400,250,true],"et-pb-post-main-image-fullwidth":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre.jpg",900,626,false],"et-pb-portfolio-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre-400x284.jpg",400,284,true],"et-pb-portfolio-module-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre-510x382.jpg",510,382,true],"et-pb-portfolio-image-single":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre.jpg",900,626,false],"et-pb-gallery-module-image-portrait":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre-400x516.jpg",400,516,true],"et-pb-post-main-image-fullwidth-large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre.jpg",900,626,false],"et-pb-image--responsive--desktop":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre.jpg",900,626,false],"et-pb-image--responsive--tablet":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre.jpg",792,551,false],"et-pb-image--responsive--phone":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2026\/01\/campese-lefevre-480x334.jpg",388,270,true]},"uagb_author_info":{"display_name":"gregory ferembach","author_link":"https:\/\/www.ferembach.com\/cestquilescreas\/author\/gregoryferembach\/"},"uagb_comment_info":0,"uagb_excerpt":"Bonjour messieurs,quels ont \u00e9t\u00e9 vos parcours \u00e9tudiant\/pro ?&nbsp; &#8211; David (en blanc sur la photo, le CR\/DC)J\u2019ai commenc\u00e9 par un doctorat de Philosophie, sp\u00e9cialit\u00e9 \u00e9pist\u00e9mologie et philosophie des sciences et techniques, \u00e0 l\u2019Universit\u00e9 d\u2019Aix-en-Provence. Autrement dit, je passais mes journ\u00e9es \u00e0 questionner la r\u00e9alit\u00e9 des mouvements elyptiques des plan\u00e8tes et de la lune chez Descartes,\u2026","_links":{"self":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts\/12028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/comments?post=12028"}],"version-history":[{"count":8,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts\/12028\/revisions"}],"predecessor-version":[{"id":12043,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts\/12028\/revisions\/12043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/media\/12034"}],"wp:attachment":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/media?parent=12028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/categories?post=12028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/tags?post=12028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}