{"id":2043,"date":"2011-11-09T20:10:06","date_gmt":"2011-11-09T18:10:06","guid":{"rendered":"http:\/\/www.ferembach.com\/cestquilescreas\/?p=2043"},"modified":"2015-03-17T12:21:15","modified_gmt":"2015-03-17T10:21:15","slug":"christophe-perruchas","status":"publish","type":"post","link":"https:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/christophe-perruchas\/","title":{"rendered":"Christophe Perruchas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2048\" title=\"perruchas\" src=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/perruchas-600x210.jpg\" alt=\"\" width=\"600\" height=\"210\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/perruchas-600x210.jpg 600w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/perruchas.jpg 1000w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><span style=\"color: #5cc5ed;\">Bonjour Christophe, tu es CR\/DC chez Publicis quel a \u00e9t\u00e9 ton parcours ?<\/span><br \/>\nJ\u2019ai d\u00e9couvert la publicit\u00e9 sur le tard\u00a0: en 1995 en me promenant sur les internets \u00e0 la fac de Nantes ou je finissais de m\u2019ennuyer.<br \/>\nLe site Publicis proposait un concours qui consistait \u00e0 inventer la suite de la saga Nescaf\u00e9 avec des gens qui ne parvenaient jamais vraiment \u00e0 divorcer.<br \/>\nJ\u2019\u00e9cris, j\u2019envoie, une jeune personne de nationalit\u00e9 fran\u00e7aise mais qui s\u2019exprimait en anglais dans la vie courante m\u2019appelle pour me dire que j\u2019\u00e9tais \u00ab\u00a0right on time and right on the ball\u00a0\u00bb et que j\u2019avais gagn\u00e9 une semaine de stage sur les Champs Elys\u00e9es.<br \/>\nJ\u2019ach\u00e8te un pull, je prends un train et je d\u00e9couvre un m\u00e9tier ou tu peux arriver tard, mettre les pieds sur la table et chercher des id\u00e9es.<br \/>\nConcepteur-R\u00e9dacteur.<br \/>\nDossier, stages, Pascale Chadenat chez BDDP, restage, Altmann et BDDP et Fils qui commence.<br \/>\nEnsuite il y aura Publicis Conseil sur Renault, Springer et Jacoby, Les Ouvriers du Paradis, Lowestrat\u00e9us. Et du digital en parall\u00e8le (je sais, c\u2019est moche) avec Duke. Apr\u00e8s quelques ann\u00e9es et des jolies choses (Lion de bronze pour PSP, Amnesty contre la peine de mort\u2026), je d\u00e9cide de passer du c\u00f4t\u00e9 2.0 de la force \u00e0 l\u2019invitation de De Lesseux puis je pars m&rsquo;occuper du digital sur Renault chez Publicis.<br \/>\nEn 2014 je prend la direction de cr\u00e9ation de l&rsquo;agence Change.<br \/>\nEt voil\u00e0.<\/p>\n<p><span style=\"color: #5cc5ed;\">Depuis combien d&rsquo;ann\u00e9es travailles-tu dans le milieu de la publicit\u00e9 ?<\/span><br \/>\nUne grosse dizaine d\u2019ann\u00e9es. Petite quinzaine. Grosse dizaine. Treize.<\/p>\n<p><span style=\"color: #5cc5ed;\">En ce moment tu travailles avec qui et sur quoi ?<\/span><br \/>\nNous avons peu de clients, une dizaine, Nissan, Nike, ING Direct, Intel, le CIO, Levi\u2019s\u2026<br \/>\nJ\u2019essaie de faire de la p\u00e9dagogie, de sortir le digital du web, de faire prendre de l\u2019avance \u00e0 nos marques. De souder cr\u00e9ation et technologie.<br \/>\nLe digital permet de passer du performatif \u00e0 la preuve, de ne plus se contenter du discours mais de faire.<br \/>\nAct, not ads, comme on dit.<br \/>\nCe qui revient in fine \u00e0 faire de la publicit\u00e9, c\u2019est juste la nature de ce que nous communiquons qui change. Il y a plus que jamais besoin d\u2019id\u00e9es pour le faire, d\u2019autant plus que maintenant ce sont les cibles qui choisissent leurs fl\u00e8ches.<\/p>\n<p><span style=\"color: #5cc5ed;\">Parles nous de deux trois choses que tu as faites <\/span><br \/>\nJ\u2019ai fait des choses que j\u2019aurais du mal \u00e0 refaire aujourd\u2019hui, notamment la campagne Seamply avec Andr\u00e9a Leupold.<br \/>\nUne saga Vrai avec Caroline de Vibraye tr\u00e8s nature, un La Poste avec entre autres, Charles Guillemant.<br \/>\nDes annonces typos avec Amnesty. SNCF Homer, c\u2019\u00e9tait les d\u00e9buts chez Duke.<br \/>\nJusqu\u2019\u00e0 Nike 10 K la semaine derni\u00e8re. Le d\u00e9but de ce que la technologie peut apporter \u00e0 la cr\u00e9ation et aux marques.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2060\" title=\"-2\" src=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/2-600x386.jpg\" alt=\"\" width=\"600\" height=\"386\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/2-600x386.jpg 600w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/2.jpg 920w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2061\" title=\"-1\" src=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/1-442x600.jpg\" alt=\"\" width=\"442\" height=\"600\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/1-442x600.jpg 442w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/1.jpg 676w\" sizes=\"auto, (max-width: 442px) 100vw, 442px\" \/><\/p>\n<p>(Directrice Artistique\u00a0 : Caroline de Vibraye)<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2059\" title=\"-3\" src=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/3-440x600.jpg\" alt=\"\" width=\"440\" height=\"600\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/3-440x600.jpg 440w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/3.jpg 690w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2058\" title=\"-4\" src=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/4-444x600.jpg\" alt=\"\" width=\"444\" height=\"600\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/4-444x600.jpg 444w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/4.jpg 682w\" sizes=\"auto, (max-width: 444px) 100vw, 444px\" \/><br \/>\n(Directrice Artistique Renault : Estelle Pinet)<br \/>\n.<br \/>\n<iframe loading=\"lazy\" title=\"sncf\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/8nRf_jlhrkQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><br \/>\n.<br \/>\n<iframe loading=\"lazy\" title=\"seamply1\" width=\"1080\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/uwnbYbLoy2Q?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><br \/>\n.<br \/>\n<iframe loading=\"lazy\" title=\"la poste\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/qvSYPCCoVok?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><br \/>\n.<br \/>\n<iframe loading=\"lazy\" title=\"vrai Assemblage\" width=\"1080\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/lSmxMozSLmE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><br \/>\n.<br \/>\n<iframe loading=\"lazy\" title=\"nike_10km.mp4\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/9_AJg_XRTAc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><br \/>\n(Cr\u00e9atifs Nike : Hanna Mansson + Hugues de Noyelle + Guillaume Rebbot)<\/p>\n<p>.<\/p>\n<p><span style=\"color: #5cc5ed;\"> Tu as h\u00e9sit\u00e9 \u00e0 faire de la pub ?<\/span><br \/>\nNon seulement je n\u2019ai pas h\u00e9sit\u00e9, mais je l\u2019ai voulu tr\u00e8s fortement.<br \/>\nC\u2019\u00e9tait \u00e7a ou prof de fran\u00e7ais en Vend\u00e9e.<\/p>\n<p><span style=\"color: #5cc5ed;\">Tu fais quelque chose en parall\u00e8le de ton m\u00e9tier, des centres d&rsquo;int\u00e9r\u00eats ?<\/span><br \/>\nJe lis pas mal, je suis cens\u00e9 aussi tenir <a href=\"http:\/\/tinyurl.com\/lachronique\" target=\"_blank\">lachroniquedepoche <\/a> sur Facebook, une chronique qui r\u00e9sume un livre de poche dans les 420 caract\u00e8res d\u2019un statut.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2063\" title=\"perruchas blog\" src=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/Capture-d\u2019\u00e9cran-2011-11-09-\u00e0-19.10.26-600x301.png\" alt=\"\" width=\"600\" height=\"301\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/Capture-d\u2019\u00e9cran-2011-11-09-\u00e0-19.10.26-600x301.png 600w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/Capture-d\u2019\u00e9cran-2011-11-09-\u00e0-19.10.26.png 797w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Je m\u2019applique aussi, avec pas mal de succ\u00e8s, \u00e0 devenir \u00e9crivain rat\u00e9.<\/p>\n<p><span style=\"color: #5cc5ed;\">As tu des anecdotes sur la vie \u00e0 l\u2019agence ?<\/span><br \/>\nJe me souviens des soir\u00e9es de chez fils, mais on ne peut pas en parler ici. A cause de la police.<\/p>\n<p><span style=\"color: #5cc5ed;\">Dans ton m\u00e9tier quel est ton meilleur souvenir ? et le pire ?<\/span><br \/>\nLes meilleurs souvenirs, forc\u00e9ment c\u2019est quand tu gagnes des prix, l\u2019annonce d\u2019un Lion au t\u00e9l\u00e9phone, c\u2019est pas mal.<\/p>\n<p>Les moins meilleurs, c\u2019est par exemple la premi\u00e8re fois que tu te retrouves devant 40 cr\u00e9atifs chez Duke\/Razorfish, 40 types et typesses avec parfois des m\u00e9tiers dont tu ignores m\u00eame l\u2019existence. Que tu viens de la publicit\u00e9 classique (une plume et du goudron) et que c\u2019est toi leur patron.<\/p>\n<p><span style=\"color: #5cc5ed;\">Le truc qui t\u2019a fait le plus halluciner ? Ce que tu pensais pas faire un jour ?<\/span><br \/>\nJe ne pensais pas attendre une nuit enti\u00e8re dans un hangar qu\u2019une chouette accepte de foncer sur la cam\u00e9ra en poussant son cri de chouette (Renault M\u00e9gane), je ne pensais pas non plus mettre des cochons dans un bain \u00e0 bulles, leur faire prendre une douche (H\u00e9naff)&#8230;<br \/>\nEn fait, ce qui me surprend le plus (en dehors des femmes), ce sont les animaux.<\/p>\n<p><span style=\"color: #5cc5ed;\">Quelle sont historiquement, les pubs qui t\u2019ont le plus marqu\u00e9es ?<\/span><br \/>\nLa Berlitz (what are you thinking about) qui fonctionne encore et encore.<br \/>\n<iframe loading=\"lazy\" title=\"German Coastguard Sinking - Learn English Commercial\" width=\"1080\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/gmOTpIVxji8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Une saga MTV de la fin des 90, d\u00e9but des 00. Que je ne retrouve pas mais qui finissait par une fess\u00e9e-logo \u00e0 la raquette de ping-pong sur les fesses d\u2019une personne de petite taille.<\/p>\n<p>A Week pour Globo, une pub que je n\u2019ai jamais revue et qui m\u2019avait chairdepoulis\u00e9 \u00e0 Cannes. Si quelqu\u2019un l\u2019a, je prends.<\/p>\n<p>Manix, l\u2019empreinte digitale (Delhomme, <a title=\"Damien Bellon\" href=\"http:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/damien-bellon\/\" target=\"_blank\">Bellon<\/a>), parce qu\u2019on est sur de la preuve factuelle et que c\u2019est parfaitement r\u00e9alis\u00e9, bande son comprise.<br \/>\n<iframe loading=\"lazy\" title=\"Manix - l&#039;empreinte\" width=\"1080\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/hnAZQkem0LI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Un film Caisse d\u2019Epargne (Altmann et De Lestrade\u00a0?) la retraite c\u2019est formidable. Un sujet pas glamour \u00e0 priori mais trait\u00e9 sharp. Que je ne retrouve pas non plus.<\/p>\n<p>Et parce que l\u2019histoire, c\u2019est aussi l\u2019histoire r\u00e9cente\u00a0:<br \/>\n<a href=\"http:\/\/www.joelapompe.net\/2011\/07\/22\/building-blocks-rasti-lego-canneslions-gold\/\" target=\"_blank\">Le print Lego <\/a>de cette ann\u00e9e, que je trouve tr\u00e8s malin, m\u00eame si j\u2019apprends qu\u2019il n\u2019est pas tr\u00e8s exclusif.<br \/>\n<a href=\"http:\/\/www.joelapompe.net\/2011\/07\/22\/building-blocks-rasti-lego-canneslions-gold\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2051\" title=\"lego\" src=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/Capture-d\u2019\u00e9cran-2011-11-08-\u00e0-20.27.57-600x300.png\" alt=\"\" width=\"600\" height=\"300\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/Capture-d\u2019\u00e9cran-2011-11-08-\u00e0-20.27.57-600x300.png 600w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/Capture-d\u2019\u00e9cran-2011-11-08-\u00e0-20.27.57-1024x512.png 1024w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/Capture-d\u2019\u00e9cran-2011-11-08-\u00e0-20.27.57.png 1132w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Le Tesco de 2011, parce que c\u2019est un tournant que \u00e7a fait avancer les gens dans leur t\u00eate.<br \/>\n<iframe loading=\"lazy\" title=\"Tesco Homeplus Virtual Subway Store in South Korea\" width=\"1080\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/fGaVFRzTTP4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Et tr\u00e8s derni\u00e8rement, le \u00ab\u00a0Blood Relation\u00a0\u00bb invent\u00e9 (cocorico) par Jean-Christophe Royer dans le cadre du\u00a0Brief Impossible lan\u00e7\u00e9 par BBR Saatchi &amp; Saatchi Isra\u00ebl.<br \/>\n<iframe loading=\"lazy\" title=\"Blood Relations - The Israeli Palestinian Blood Donation Project\" width=\"1080\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/3GZxLcGSCow?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Malin aussi, l\u2019op\u00e9ration de Memac Ogilvy Label pour Engagement Citoyen qui met en sc\u00e8ne le retour de Ben Ali \u00e0 Tunis.<br \/>\n<iframe loading=\"lazy\" title=\"The Return of Dictator Ben Ali (Original video)\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/yxWvgASA_Q4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Et bien s\u00fbr Super Timor, le num\u00e9ro 1.<br \/>\n<iframe loading=\"lazy\" title=\"Super Timor - Le num\u00e9ro 1!\" width=\"1080\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/exQ4zjR0qOA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>J\u2019aime aussi la publicit\u00e9 en morceaux, \u2018il ne triche pas\u2019, \u2018c\u2019est le jeu ma pauvre lucette\u2019, \u2018Wassssss\u2019up\u2019\u2026<br \/>\n<iframe loading=\"lazy\" title=\"Bud - wazaa\" frameborder=\"0\" width=\"1080\" height=\"810\" src=\"https:\/\/www.dailymotion.com\/embed\/video\/x2lu6y\" allowfullscreen allow=\"autoplay\"><\/iframe><\/p>\n<p><span style=\"color: #5cc5ed;\">Celle que tu aurais aim\u00e9 faire ? <\/span><br \/>\nLes m\u00eames sauf Super Timor (ou alors en la signant <a title=\"Patrice Lucet\" href=\"http:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/patrice-lucet\/\" target=\"_blank\">Patrice Luce<\/a>t).<\/p>\n<p><span style=\"color: #5cc5ed;\">Tu as des mod\u00e8les de cr\u00e9atifs dans la publicit\u00e9 ? des gens qui t\u2019inspirent ?<\/span><br \/>\nJ\u2019ai eu la chance de d\u00e9buter l\u00e0 o\u00f9 \u00e7a se passait, je n\u2019ai pas de mod\u00e8les \u00e0 proprement parler, mais un tas d\u2019influences.<br \/>\nLes cr\u00e9atifs avec lesquels j\u2019ai commenc\u00e9, dans le d\u00e9sordre\u00a0: Tricot, Altmann, Couradjut, Delhomme, Tapiro, <a title=\"Damien Bellon\" href=\"http:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/damien-bellon\/\" target=\"_blank\">Bellon<\/a>, <a title=\"\u00c9ric H\u00e9lias\" href=\"http:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/eric-helias\/\" target=\"_blank\">H\u00e9lias<\/a>, <a title=\"Jorge Carre\u00f1o\" href=\"http:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/jorge-carreno\/\" target=\"_blank\">Carreno<\/a>, <a title=\"Olivier Camensuli\" href=\"http:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/olivier-camensuli\/\" target=\"_blank\">Camensuli<\/a>, Leupold.<br \/>\n(Tu noteras qu\u2019il y a un intrus dans la liste pr\u00e9c\u00e9dente).<br \/>\nCeux que j\u2019ai crois\u00e9 plus tard\u00a0: Fichard, Behaeghel.<\/p>\n<p>Et puis, plus largement, tous ceux qui d\u00e9cloisonnent, qui ouvrent. Des gens comme Peter Brook qui peuvent prendre comme mat\u00e9riau des chroniques m\u00e9dicales pour en faire un ailleurs, \u00e7a me parle. Je me sers quasiment tous les jours des <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Strat%C3%A9gies_obliques\" target=\"_blank\">Strategies Obliques<\/a> d&rsquo;Eno et Schmidt.<\/p>\n<p><span style=\"color: #5cc5ed;\">Si tu commen\u00e7ais la pub aujourd\u2019hui, tu irais o\u00f9?<\/span><br \/>\nDans une agence post digitale, ni On, ni Off. Une agence qui embrasse tous les aspects de la cr\u00e9ation, sur la base d\u2019une strat\u00e9gie de marque. Pas forc\u00e9ment en France, ni m\u00eame en Europe. Peut-\u00eatre je serais oblig\u00e9 d\u2019aller jusqu\u2019en 2015.<\/p>\n<p><span style=\"color: #5cc5ed;\">Tu vois quoi comme changement entre tes d\u00e9buts et maintenant ?<\/span><br \/>\nOn est pass\u00e9 de Caramail \u00e0 Facebook, de War Craft \u00e0 Farmville, de l\u2019\u00e9clatement de la bulle internet aux subprimes et \u00e0 la crise de la dette (attention, peinture fra\u00eeche). Des 30 secondes aux case studies.<\/p>\n<p>Deux bouleversements majeurs (en dehors de la technologie qui les rend possibles) la fin du mod\u00e8le \u00e9metteur\/r\u00e9cepteur et cons\u00e9quemment la fin du discours performatif. La naissance de la fameuse Brand Utility. On doit faire pour et faire avec les clients, prospects, personnes, gens. Et un autre truc a chang\u00e9 aussi, il y a moins d\u2019argent pour faire, penser, cr\u00e9er. Moins de temps donc.<\/p>\n<p>Une cons\u00e9quence de l\u2019irruption du mod\u00e8le digital\u00a0? Le mood aussi a chang\u00e9, les choses sont moins l\u00e9g\u00e8res. Un truc qui n\u2019a pas chang\u00e9, c\u2019est l\u2019influence des agences m\u00e9dias et leur manque d\u2019imagination qui contribue largement \u00e0 spammer les internets par exemple.<\/p>\n<p><span style=\"color: #5cc5ed;\">Tu penses que le milieu va \u00e9voluer de quelle mani\u00e8re ?<\/span><br \/>\nJe pense qu\u2019on va devoir globalement faire plus attention \u00e0 nos messages, pas par \u00e9thique, mais \u00e0 cause de l\u2019effet boomerang dans ta face. On est, et c\u2019est plut\u00f4t enthousiasmant, en train de chercher un nouveau mod\u00e8le, une nouvelle fa\u00e7on de faire. T\u00e2tonnons.<br \/>\nJe pense que tout va devenir digital, connect\u00e9, du mobile au retail (c\u2019est Siri qui me l\u2019a dit), je pense qu\u2019on va sortir des cadres, m\u00ealer l\u2019espace physique et digital, qu\u2019\u00e0 terme on va m\u00eame modifier nos corps, les augmenter, je pense que le web est moribond sous sa couche de maquillage, que le spam va lui coller des gros boutons. Je pense que c\u2019est bien fait.<\/p>\n<p>L\u2019autre jour j\u2019ai voulu voir le dernier spot <a href=\"http:\/\/www.youtube.com\/watch?v=zDOi3Hudmmc\" target=\"_blank\">Canal + l&rsquo;Ours<\/a> sur Facebook. Avant de voir ce film de publicit\u00e9 (qui passe aussi sur les \u00e9crans t\u00e9l\u00e9), j\u2019ai d\u00fb m\u2019en cogner un autre, captif et furieux, beaucoup moins dr\u00f4le, de 30 secondes.<br \/>\nOn a laiss\u00e9 la radio devenir un robinet \u00e0 promo, on peut encore sauver le web. Peut-\u00eatre il faut cr\u00e9er une page pour \u00e7a.<\/p>\n<p><span style=\"color: #5cc5ed;\">Que dirais tu \u00e0 un team de stagiaire qui veut percer dans le milieu<\/span><span style=\"color: #5cc5ed;\"> publicitaire ?<\/span><br \/>\nCouchez. Ca aide.<br \/>\nEt si votre physique vous l\u2019interdit, marrez-vous, kiffez ce que vous faites.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour Christophe, tu es CR\/DC chez Publicis quel a \u00e9t\u00e9 ton parcours ? J\u2019ai d\u00e9couvert la publicit\u00e9 sur le tard\u00a0: en 1995 en me promenant sur les internets \u00e0 la fac de Nantes ou je finissais de m\u2019ennuyer. Le site Publicis proposait un concours qui consistait \u00e0 inventer la suite de la saga Nescaf\u00e9 avec [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_uag_custom_page_level_css":"","footnotes":""},"categories":[25,6,52],"tags":[],"class_list":["post-2043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-directeur-de-creation","category-redacteur","category-change"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Christophe Perruchas &#8226; C&#039;est qui les Cr\u00e9as ?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/christophe-perruchas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Christophe Perruchas &#8226; C&#039;est qui les Cr\u00e9as ?\" \/>\n<meta property=\"og:description\" content=\"Bonjour Christophe, tu es CR\/DC chez Publicis quel a \u00e9t\u00e9 ton parcours ? J\u2019ai d\u00e9couvert la publicit\u00e9 sur le tard\u00a0: en 1995 en me promenant sur les internets \u00e0 la fac de Nantes ou je finissais de m\u2019ennuyer. Le site Publicis proposait un concours qui consistait \u00e0 inventer la suite de la saga Nescaf\u00e9 avec [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/christophe-perruchas\/\" \/>\n<meta property=\"og:site_name\" content=\"C&#039;est qui les Cr\u00e9as ?\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CestquilesCreas\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-11-09T18:10:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-03-17T10:21:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"472\" \/>\n\t<meta property=\"og:image:height\" content=\"472\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gregory ferembach\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"gregory ferembach\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/redacteur\\\/christophe-perruchas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/redacteur\\\/christophe-perruchas\\\/\"},\"author\":{\"name\":\"gregory ferembach\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/person\\\/228b651374249a02f20a1921f0e2516b\"},\"headline\":\"Christophe Perruchas\",\"datePublished\":\"2011-11-09T18:10:06+00:00\",\"dateModified\":\"2015-03-17T10:21:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/redacteur\\\/christophe-perruchas\\\/\"},\"wordCount\":1788,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/redacteur\\\/christophe-perruchas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2011\\\/11\\\/IMG_7229.jpg\",\"articleSection\":[\".Directeur de Cr\u00e9ation\",\".R\u00e9dacteur\",\"change\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/redacteur\\\/christophe-perruchas\\\/\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/redacteur\\\/christophe-perruchas\\\/\",\"name\":\"Christophe Perruchas &#8226; C&#039;est qui les Cr\u00e9as ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/redacteur\\\/christophe-perruchas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/redacteur\\\/christophe-perruchas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2011\\\/11\\\/IMG_7229.jpg\",\"datePublished\":\"2011-11-09T18:10:06+00:00\",\"dateModified\":\"2015-03-17T10:21:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/redacteur\\\/christophe-perruchas\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/redacteur\\\/christophe-perruchas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/redacteur\\\/christophe-perruchas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2011\\\/11\\\/IMG_7229.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2011\\\/11\\\/IMG_7229.jpg\",\"width\":\"472\",\"height\":\"472\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/redacteur\\\/christophe-perruchas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Christophe Perruchas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#website\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\",\"name\":\"C'est qui les Cr\u00e9as ?\",\"description\":\"D\u00e9couvrez les cr\u00e9atifs, leurs parcours et leurs (en)vies...\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\",\"name\":\"C'est qui les Cr\u00e9as ?\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-cqlc-1024x368-3.png\",\"contentUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-cqlc-1024x368-3.png\",\"width\":1024,\"height\":368,\"caption\":\"C'est qui les Cr\u00e9as ?\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CestquilesCreas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/person\\\/228b651374249a02f20a1921f0e2516b\",\"name\":\"gregory ferembach\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"caption\":\"gregory ferembach\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Christophe Perruchas &#8226; C&#039;est qui les Cr\u00e9as ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/christophe-perruchas\/","og_locale":"fr_FR","og_type":"article","og_title":"Christophe Perruchas &#8226; C&#039;est qui les Cr\u00e9as ?","og_description":"Bonjour Christophe, tu es CR\/DC chez Publicis quel a \u00e9t\u00e9 ton parcours ? J\u2019ai d\u00e9couvert la publicit\u00e9 sur le tard\u00a0: en 1995 en me promenant sur les internets \u00e0 la fac de Nantes ou je finissais de m\u2019ennuyer. Le site Publicis proposait un concours qui consistait \u00e0 inventer la suite de la saga Nescaf\u00e9 avec [&hellip;]","og_url":"https:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/christophe-perruchas\/","og_site_name":"C&#039;est qui les Cr\u00e9as ?","article_publisher":"https:\/\/www.facebook.com\/CestquilesCreas\/","article_published_time":"2011-11-09T18:10:06+00:00","article_modified_time":"2015-03-17T10:21:15+00:00","og_image":[{"width":472,"height":472,"url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg","type":"image\/jpeg"}],"author":"gregory ferembach","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"gregory ferembach","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/christophe-perruchas\/#article","isPartOf":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/christophe-perruchas\/"},"author":{"name":"gregory ferembach","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/person\/228b651374249a02f20a1921f0e2516b"},"headline":"Christophe Perruchas","datePublished":"2011-11-09T18:10:06+00:00","dateModified":"2015-03-17T10:21:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/christophe-perruchas\/"},"wordCount":1788,"commentCount":1,"publisher":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/christophe-perruchas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg","articleSection":[".Directeur de Cr\u00e9ation",".R\u00e9dacteur","change"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/christophe-perruchas\/","url":"https:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/christophe-perruchas\/","name":"Christophe Perruchas &#8226; C&#039;est qui les Cr\u00e9as ?","isPartOf":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/christophe-perruchas\/#primaryimage"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/christophe-perruchas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg","datePublished":"2011-11-09T18:10:06+00:00","dateModified":"2015-03-17T10:21:15+00:00","breadcrumb":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/christophe-perruchas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/christophe-perruchas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/christophe-perruchas\/#primaryimage","url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg","contentUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg","width":"472","height":"472"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/christophe-perruchas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ferembach.com\/cestquilescreas\/"},{"@type":"ListItem","position":2,"name":"Christophe Perruchas"}]},{"@type":"WebSite","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#website","url":"https:\/\/www.ferembach.com\/cestquilescreas\/","name":"C'est qui les Cr\u00e9as ?","description":"D\u00e9couvrez les cr\u00e9atifs, leurs parcours et leurs (en)vies...","publisher":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ferembach.com\/cestquilescreas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization","name":"C'est qui les Cr\u00e9as ?","url":"https:\/\/www.ferembach.com\/cestquilescreas\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/logo\/image\/","url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2020\/02\/logo-cqlc-1024x368-3.png","contentUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2020\/02\/logo-cqlc-1024x368-3.png","width":1024,"height":368,"caption":"C'est qui les Cr\u00e9as ?"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CestquilesCreas\/"]},{"@type":"Person","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/person\/228b651374249a02f20a1921f0e2516b","name":"gregory ferembach","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","caption":"gregory ferembach"}}]}},"uagb_featured_image_src":{"full":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg",472,472,false],"thumbnail":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229-290x290.jpg",120,120,true],"medium":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg",60,60,false],"medium_large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg",472,472,false],"large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg",472,472,false],"1536x1536":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg",472,472,false],"2048x2048":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg",472,472,false],"et-pb-post-main-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg",250,250,false],"et-pb-post-main-image-fullwidth":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg",472,472,false],"et-pb-portfolio-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg",284,284,false],"et-pb-portfolio-module-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg",382,382,false],"et-pb-portfolio-image-single":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg",472,472,false],"et-pb-gallery-module-image-portrait":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg",400,400,false],"et-pb-post-main-image-fullwidth-large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg",472,472,false],"et-pb-image--responsive--desktop":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg",472,472,false],"et-pb-image--responsive--tablet":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg",472,472,false],"et-pb-image--responsive--phone":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/11\/IMG_7229.jpg",270,270,false]},"uagb_author_info":{"display_name":"gregory ferembach","author_link":"https:\/\/www.ferembach.com\/cestquilescreas\/author\/gregoryferembach\/"},"uagb_comment_info":1,"uagb_excerpt":"Bonjour Christophe, tu es CR\/DC chez Publicis quel a \u00e9t\u00e9 ton parcours ? J\u2019ai d\u00e9couvert la publicit\u00e9 sur le tard\u00a0: en 1995 en me promenant sur les internets \u00e0 la fac de Nantes ou je finissais de m\u2019ennuyer. Le site Publicis proposait un concours qui consistait \u00e0 inventer la suite de la saga Nescaf\u00e9 avec\u2026","_links":{"self":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts\/2043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/comments?post=2043"}],"version-history":[{"count":0,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts\/2043\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/media\/2046"}],"wp:attachment":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/media?parent=2043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/categories?post=2043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/tags?post=2043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}