{"id":3560,"date":"2015-04-07T11:06:10","date_gmt":"2015-04-07T09:06:10","guid":{"rendered":"http:\/\/www.ferembach.com\/cestquilescreas\/?p=3560"},"modified":"2015-04-07T11:28:49","modified_gmt":"2015-04-07T09:28:49","slug":"guillaume-rebbot","status":"publish","type":"post","link":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/guillaume-rebbot\/","title":{"rendered":"Guillaume Rebbot"},"content":{"rendered":"<p><a href=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/rebbot.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3563\" src=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/rebbot.jpg\" alt=\"rebbot\" width=\"800\" height=\"279\" \/><\/a><\/p>\n<p><span style=\"color: #5cc5ed;\">Bonjour Guillaume, quel a \u00e9t\u00e9 ton parcours pro\/tes \u00e9tudes ?<br \/>\n<\/span>DEUG de droit, licence et ma\u00eetrise de sciences politiques, suivi un DESS de management des entreprises de communication et multimedia \u00e0 Dauphine. Je viens d\u2019une \u00e9poque ou l\u2019internet s\u2019appelait multim\u00e9dia ou \u00ab nouvelles technologies \u00bb .Apr\u00e8s mon DESS, j\u2019ai encha\u00een\u00e9 sur un stage de fin d\u2019\u00e9tude catastrophique chez M6 pour Zone interdite comme assistant de production ( ou plut\u00f4t \u00ab larbin exploit\u00e9 \u00bb de production). J\u2019y ai appris \u00e0 classer des Beta num par ordre alphab\u00e9tique, porter un sac avec une cam\u00e9ra dedans ou booker des restaurants pour Bernard de La Villardi\u00e8re. Bref plein de truc qu\u2019on n\u2019apprend pas forc\u00e9ment \u00e0 Dauphine et qui sont vraiment utiles pour la suite. Je n\u2019ai pas fini ce stage, et je suis rentr\u00e9 dans la pub juste apr\u00e8s en 2005, chez Devarrieuxvillaret.<br \/>\nEnsuite, Un court passage chez Australie et je suis arriv\u00e9e \u00e0 LaChose \u00e0 sa cr\u00e9ation. J\u2019y ai rencontr\u00e9 plein de cr\u00e9atifs tops qui sont rest\u00e9s mes amis ensuite et qui font plein de belles choses aujourd\u2019hui. On avait un super groupe. On \u00e9tait hyper responsabilis\u00e9 pour des juniors (il n\u2019y avait pas vraiment de seniors), on pouvait toucher \u00e0 des sujet qu\u2019on aurait jamais laiss\u00e9 \u00e0 des juniors ailleurs. Ensuite Duke interactive et aujourd\u2019hui BETC.<\/p>\n<p><span style=\"color: #00ccff;\">Si tu pouvais refaire tes \u00e9tudes, tu les changerais ? Un moyen plus rapide, efficace ?<br \/>\n<\/span>Je ne changerai rien, \u00e7a m\u2019a ouvert un peu l\u2019esprit, et \u00e7a m\u2019a apport\u00e9 un peu de m\u00e9thodologie et une autre culture que la culture publicitaire. Une fois que tu es dans la pub tu ne parles plus que de pub. Au moins j\u2019aurai vu d\u2019autres choses avant\u2026<\/p>\n<p><span style=\"color: #00ccff;\">Depuis combien d\u2019ann\u00e9es travailles-tu dans le milieu de la publicit\u00e9 ?<br \/>\n<\/span>10 ans tout rond.<\/p>\n<p><span style=\"color: #00ccff;\">C\u2019est quoi l\u2019intitul\u00e9 de ton poste ?<\/span><\/p>\n<p>Je suis chef de groupe cr\u00e9atif. \u00c7a permet d\u2019avoir plus d\u2019autonomie et je peux g\u00e9rer des sujets seul avec des juniors. Je le fais essentiellement sur des sujets digitaux.<br \/>\nBien s\u00fbr, il y a toujours les gros DC qui veillent derri\u00e8re. C\u2019est quand m\u00eame cool la publicit\u00e9, on est toujours chef ou directeur de quelque chose.<\/p>\n<p><span style=\"color: #00ccff;\">Tu as h\u00e9sit\u00e9 \u00e0 faire de la pub ?<br \/>\n<\/span>Oui et non, j\u2019ai toujours gard\u00e9 la pub dans un coin de ma t\u00eate. De 13 \u00e0 17 ans j\u2019habitais Avenue Morizet \u00e0 Boulogne. Ma chambre avait une vue imprenable sur le parking de Young &amp; Rubicam. Je voyais tous les jours des gars de 30 ans habill\u00e9s trop cools arriver au boulot a 11h en Vespa (Fr\u00e9d\u00e9ric Beigbeder entre autres) .En 2001, j\u2019avais fait un boulot d\u2019\u00e9tudiant chez Euro RSCG (j\u2019\u00e9tais la bas pendant le 11 septembre) je collais des enveloppes pour les mailings (l\u2019anc\u00eatre de la newsletter) j\u2019avais trouv\u00e9 l\u2019ambiance et les gens tr\u00e8s sympa. Apr\u00e8s j\u2019ai fait coursier pour les agences, pendant les \u00e9t\u00e9s 2003 et 2004.Je connaissais les halls de pas mal d\u2019agences et je voyais les gars faire du Ping Pong et du flipper. Ca avait \u2018air plus d\u00e9tendu que les autres bo\u00eetes. Et puis comme tout le monde, avant le film \u00e9rotique du dimanche soir sur M6, je jetais \u00e0 un \u0153il \u00e0 Culture pub et je voyais des campagnes d\u00e9mentes de partout dans le monde. Donc apr\u00e8s mon exp\u00e9rience rat\u00e9e \u00e0 la t\u00e9l\u00e9, quand mon ami Thomas Sabatier m\u2019a propos\u00e9 de cr\u00e9er \u00ab un team \u00bb j\u2019ai dit oui tout de suite.<\/p>\n<p><span style=\"color: #00ccff;\">Tu travailles avec qui et sur quoi ?<br \/>\n<\/span>Je ne suis pas en team. Je travaille avec des AD seul aussi au coup par coup selon la campagne et le client. Je fais pas mal de digital, et dans ce domaine, le fait d\u2019\u00eatre seul donne pas mal de souplesse. Je travaille sur des sujets extr\u00eamement vari\u00e9s. Chez BETC, J\u2019ai boss\u00e9 sur Vuitton, Lacoste, Canal+, Air France, Ibis, La fran\u00e7aise des jeux ou Disney entre autres. Le luxe peut exiger des comp\u00e9tences tr\u00e8s sp\u00e9cifiques pour un AD, surtout en digital, donc ne pas \u00eatre \u00ab maqu\u00e9 \u00bb apporte pas mal d\u2019avantages. \u00c7a permet de travailler avec la personne la plus adapt\u00e9e en fonction du projet.<\/p>\n<p><span style=\"color: #00ccff;\">Ton post existe dans d\u2019autres agences ou c\u2019est propre \u00e0 la structure de Betc dans laquelle tu as \u00e9volu\u00e9s ?<br \/>\n<\/span>Je pense que c\u2019est propre \u00e0 BETC, c\u2019est tellement gros que les big boss ne peuvent pas \u00eatre partout, sur tous le sujets. Mais \u00e7a doit peut \u00eatre exist\u00e9 ailleurs dans le monde dans les tr\u00e8s grosses agences.<\/p>\n<p><span style=\"color: #00ccff;\">Parles nous de deux trois choses que tu as faites :<br \/>\n<\/span>Cette ann\u00e9e, j\u2019ai travaill\u00e9 sur deux projets digitaux qui m\u2019ont bien plu. \u00ab Dans la peau de l\u2019ours \u00bb de Canal+ et le projet \u00ab Ultimate sleep \u00bb pour Ibis. Deux projets difficiles mais ultra motivant qui mixent un vrai storytelling avec de la technologie. Ce sont les projets que je pr\u00e9f\u00e8re. Le digital, \u00e7a n\u2019est pas forc\u00e9ment un truc qui se fait avec 10 euros sur fond vert dans le sous sol d\u2019une agence. Il y a un vrai boulot en amont avec le client pour le convaincre de mettre un peu moins en t\u00e9l\u00e9 et un eu plus sur le digital pour avoir un truc quali.<br \/>\nC\u2019est tr\u00e8s courant \u00e0 l\u2019\u00e9tranger mais pas encore assez en France. Pourtant c\u2019est vers \u00e7a que nous allons. Le probl\u00e8me c\u2019est qu\u2019expliquer l\u2019interactivit\u00e9 \u00e0 un client c\u2019est tr\u00e8s compliqu\u00e9, alors quand il doit mettre 300 K sur la table, il faut \u00eatre tr\u00e8s p\u00e9dagogue et y aller doucement. Il faut qu\u2019il y ait une vraie relation de confiance entre l\u2019agence et l\u2019annonceur. Pour Ibis, on avait d\u00e9j\u00e0 fait le projet \u00ab Sleep art \u00bb, \u00e7a avait bien plu et on a pu continu\u00e9 sur notre lanc\u00e9. En interne il y a eu une vraie collaboration entre les \u00e9quipes digitales et le off, tout le monde a boss\u00e9 ensemble malgr\u00e9 les diff\u00e9rences de culture.<br \/>\nC\u2019\u00e9tait vraiment enrichissant.<br \/>\nSi on remonte plus loin en arri\u00e8re j\u2019ai eu la chance de travailler sur des marques top : Nike et Levi\u2019s quand j\u2019\u00e9tais chez Duke ou Ikea \u00e0 la chose. \u00c7a m\u2019a permis de me faire un dossier correct et d\u2019avoir un vrai plus en digital, pour rentrer chez BETC apr\u00e8s.<\/p>\n<p>IBIS ULTIMATE SLEEP :<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/player.vimeo.com\/video\/91783545?dnt=1&amp;app_id=122963\" width=\"1080\" height=\"608\" frameborder=\"0\" allow=\"autoplay; fullscreen\" allowfullscreen><\/iframe><\/p>\n<p>DANS LA PEAU DE L\u2019OURS :<br \/>\n<iframe loading=\"lazy\" title=\"CANAL+ | BEING THE BEAR\" src=\"https:\/\/player.vimeo.com\/video\/109605467?dnt=1&amp;app_id=122963\" width=\"1080\" height=\"608\" frameborder=\"0\" allow=\"autoplay; fullscreen\" allowfullscreen><\/iframe><\/p>\n<p>IBIS SLEEP ART :<br \/>\n<iframe loading=\"lazy\" title=\"IBIS | Sleep art\" src=\"https:\/\/player.vimeo.com\/video\/57558483?dnt=1&amp;app_id=122963\" width=\"638\" height=\"360\" frameborder=\"0\" allow=\"autoplay; fullscreen\" allowfullscreen><\/iframe><\/p>\n<p><span style=\"color: #00ccff;\">Tu fais quelque chose en parall\u00e8le de ton m\u00e9tier, des projets ?<br \/>\n<\/span>Je suis associ\u00e9 dans un studio de production digitale : Lumini, c\u2019est bien de voir comment fonctionne une petite bo\u00eete et \u00e7a me permet de comprendre toutes les difficult\u00e9s que rencontre une prod digitale. Du coup, je sais \u00e0 peu pr\u00e8s ce qui est faisable, faisable mais compliqu\u00e9 et ce qui rel\u00e8ve de la science fiction sauf si le client peut investir 10 millions de dollars sur 3 ans. C\u2019est \u00e7a qui est compliqu\u00e9 dans le digital : avoir des id\u00e9es \u00ab faisables \u00bb. Tout le monde arrive avec des id\u00e9es d\u2019appli ou de site r\u00e9volutionnaire sur le papier mais totalement surr\u00e9aliste en terme de prod. On travaille dans une agence de pub, pas chez Google. Nous n\u2019avons ni les m\u00eame d\u00e9lais, ni les m\u00eame budgets en R&amp;D, ni les m\u00eames ing\u00e9nieurs. Une bonne appli \u00e7a n\u2019est pas qu\u2019une interface bien craft\u00e9e. Il faut un gros back office derri\u00e8re pour faire fonctionner le service qui va avec et \u00e7a on a tous tendance a un peu l\u2019oublier. Mon exp\u00e9rience avec Lumini m\u2019a \u00e9t\u00e9 hyper utile. En plus quand un d\u00e9veloppeur me dit que c\u2019est \u00ab impossible \u00bb j\u2019arrive \u00e0 peu pr\u00e8s \u00e0 savoir si il dit la v\u00e9rit\u00e9 ou s\u2019il veut juste rentr\u00e9 t\u00f4t chez lui.<br \/>\nSinon en terme de projet, j\u2019aimerai bien refaire ma salle de bain et avoir des enfants.<\/p>\n<p><span style=\"color: #00ccff;\">Tu es associ\u00e9 depuis longtemps ? Au d\u00e9but pourquoi tu t\u2019\u00e9tais lanc\u00e9 dans ce projet ? La boite est grosse ? Pourquoi ne pas faire que cela ?<br \/>\n<\/span>Je suis associ\u00e9 depuis 7 ans, la bo\u00eete compte une quinzaine de personnes. Je me suis lanc\u00e9 dans ce projet avec un ami, Areski Ferhat, qui \u00e9tait mon moniteur de colonie de vacances pour la petite histoire. C\u2019est lui qui l\u2019a mont\u00e9 et il m\u2019a propos\u00e9 de prendre des parts. Il a eu l\u2019id\u00e9e de monter ce projet car \u00e0 l\u2019\u00e9poque, en France, il n\u2019y avait quasiment pas de prod digitale. Areski venait de l\u2019image et il y avait tr\u00e8s peu de boite qui faisait \u00e0 la fois la partie vid\u00e9o et la partie interactive. Aujourd\u2019hui Lumini a travaill\u00e9 avec quasiment toutes les agences de Paris. Ils sont franchement tr\u00e8s fort techniquement.<br \/>\nJe ne pourrais pas faire cela car \u00e7a n\u2019est pas mon m\u00e9tier premier. Ce sont vraiment des dev, des profils techniques et des D.A. La conception vient des agences. C\u2019est vraiment de la prod digitale, ils font assez peu de conception. Ce sont des \u00ab faiseurs \u00bb comme on dit.<\/p>\n<p><span style=\"color: #00ccff;\">Dans ton m\u00e9tier quel est ton meilleur souvenir ? Et le pire ?<br \/>\n<\/span>Les meilleurs souvenirs, ce sont sans aucun doute les souvenirs de tournage, il y en a plein, mais ca n\u2019int\u00e9resserait pas grand monde de les d\u00e9tailler tous ici. Le pire, je pense que ce sont mes derniers mois chez Duke. La bo\u00eete n\u2019allait vraiment pas bien et avec le directeur de cr\u00e9ation Christophe Perruchas on se battait pour continuer a essayer de faire de la bonne cr\u00e9a mais on \u00e9tait toujours rattrap\u00e9 par les probl\u00e8mes politiques. Pourtant on continuer vraiment \u00e0 proposer des trucs qui nous plaisaient sans baisser les bras. Malheureusement \u00e7a n\u2019a pas suffi. Mais je suis rest\u00e9 vraiment ami avec Christophe depuis cette p\u00e9riode.<\/p>\n<p>L\u2019autre abominable souvenir, c\u2019\u00e9tait \u00e0 LACHOSE. Je me suis fait escroqu\u00e9 par un cabinet de chasseur de t\u00eate qui m\u2019avait fait miroiter un poste de dingue dans une \u00ab nouvelle structure internationale \u00bb avec des profils de dingues venues des meilleurs agences parisiennes. J\u2019ai d\u00e9missionn\u00e9. Et je me suis retrouv\u00e9 dans une pauvre SSII (soci\u00e9t\u00e9 de service informatique) qui vendait des sites e-commerce Lowcost. Quand je suis arriv\u00e9 le premier jour, j\u2019ai compris l\u2019arnaque, je suis rentr\u00e9 et j\u2019ai pleur\u00e9, tout simplement. J\u2019ai appel\u00e9 Pascal Gr\u00e9goire et Eric Tong Cuong pour leur expliquer la situation. Ils se sont marr\u00e9s et ils m\u2019ont repris \u00e0 LaChose, ils ont \u00e9t\u00e9 vraiment cool sur ce coup la. Par contre, je me suis fait vanner pendant 1 an.<\/p>\n<p><span style=\"color: #00ccff;\">Le truc qui t&rsquo;as fait le plus halluciner ? Que tu ne pensais pas faire un jour ?<br \/>\n<\/span>Quand j\u2019\u00e9tais \u00e0 LaChose on a du partir 1 semaine au Bahamas pour tourner des banni\u00e8res pour Lasminute.com, le truc improbable. Sinon pour Ulimate sleep on a du poser un lit avec un h\u00e9licopt\u00e8re sur la plus haute falaise du monde au fin fond du Venezuela. Tout le tournage a \u00e9t\u00e9 \u00e9pique, on \u00e9tait avec l\u2019\u00e9quipe de Vice. Il y avait des moments hyper chaud. On a du faire traverser au lit une cascade de 20 m\u00e8tres de haut avec une tyrolienne fabriqu\u00e9e \u00e0 l\u2019arrache par les indiens qui nous accompagnaient, c\u2019\u00e9tait vraiment dingue.<br \/>\nJe ne serai jamais all\u00e9 au Venezuela sans ce projet, \u00e7a aurait \u00e9t\u00e9 bien dommage car c\u2019est un pays absolument sublime. Sinon quand j\u2019\u00e9tais chez Duke, Nike nous avait offert un \u00e9quipement de running complet et on participait \u00e0 des s\u00e9ances d\u2019entrainements avec le client, j\u2019ai donc fait du sport, et c\u2019est franchement quelque chose que je ne pensais pas faire un jour.<\/p>\n<p><span style=\"color: #00ccff;\">Quelles sont les pubs qui t&rsquo;ont le plus marqu\u00e9es ?<br \/>\n<\/span>En film, si je devais citer un top 3, je dirais \u00ab Impossible Dream \u00bb de Honda parce que je pense que je ne me lasserai jamais de la voir. \u00ab Le gorille \u00bb de Cadbury parce que je me poserai toute ma vie la question : \u00ab Comment est ce que tu racontes ce script a ton DC ? Comment tu le vends \u00e0 un client ? Comment est ce qu\u2019on peut avoir une id\u00e9e comme \u00e7a et r\u00e9ussir a aller jusqu\u2019au bout avec ?<br \/>\nSinon, mais \u00e7a c\u2019est tr\u00e8s personnel, j\u2019ai une passion pour la campagne Bavaria \u00ab life is life \u00bb, on a tous un film de pub culte, le mien c\u2019est clairement celui la.<\/p>\n<p>En digital, il y a en a des tonnes mais si je devais en cit\u00e9 deux je citerai \u00ab Nike chalkbot \u00bb et \u00ab old spice response \u00bbparce que ce sont deux \u00abgame changers\u00bb. Plus r\u00e9cemment \u00ab sound of senna \u00bb qui \u00e9tait ultra impressionnante et bien sur tout ce que fait Volvo pour vendre ses camions. Ce sont des briefs B- to-be \u00e0 la base, et ils ont r\u00e9ussi a en faire un ph\u00e9nom\u00e8ne mondial. \u00c7a donnerait presque envie de s\u2019acheter un camion.<\/p>\n<p>En film :<\/p>\n<p>HONDA IMPOSSIBLE DREAM :<br \/>\n<iframe loading=\"lazy\" title=\"Honda Impossible Dream\" width=\"1080\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/fB_1gPRCLCo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>LE GORILLE DE CADBURY :<br \/>\n<iframe loading=\"lazy\" title=\"Cadbury&#039;s Gorilla Advert Aug 31st 2007\" width=\"1080\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/TnzFRV1LwIo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>BAVARIA LIFE IS LIFE<br \/>\nhttps:\/\/www.youtube.com\/watch?v=FTMQ643iYwU<\/p>\n<p>En digital :<\/p>\n<p>NIKE CHALKBOT :<br \/>\n<iframe loading=\"lazy\" title=\"Nike Livestrong - The Chalkbot\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/oNg-rQR6z84?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>OLD SPICE RESPONSE :<br \/>\nhttps:\/\/www.youtube.com\/watch?v=fD1WqPGn5Ag<\/p>\n<p>SOUND OF SENNA \/ HONDA<br \/>\nhttps:\/\/www.youtube.com\/watch?v=_0ZTPCoQ4jI<\/p>\n<p>VOLVO LIVE TEST SERIES<br \/>\n<iframe loading=\"lazy\" title=\"VOLVO TRUCK - LIVE TEST SERIES INTEGRATED CAMPAIGN case study\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/mgAkh61v1Nc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><span style=\"color: #00ccff;\">Il y a des mod\u00e8les de cr\u00e9atifs dans la publicit\u00e9 ? Des gens qui t&rsquo;inspirent ?<br \/>\n<\/span>J\u2019ai eu pas mal de chance depuis le d\u00e9but. J\u2019ai commenc\u00e9 chez Beno\u00eet Devarrieux, il y a pire pour apprendre. J\u2019ai encha\u00een\u00e9 avec Eric tong Cuong, Pascale Gr\u00e9goire et aujourd\u2019hui St\u00e9phane Xiberras, Remi Babinet ou <a title=\"Olivier Apers\" href=\"http:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/olivier-apers\/\" target=\"_blank\">Olivier Apers<\/a>. J\u2019ai pu apprendre de chacun, je continue \u00e0 apprendre plein de chose, je ne me plains pas. Annick Teboul aussi, chez BETC. Une directrice de cr\u00e9ation discr\u00e8te mais avec laquelle j\u2019adore travailler, qui m\u2019a fait confiance d\u00e8s le d\u00e9but et de qui je continue d\u2019apprendre. Sinon \u00e0 l\u2019\u00e9tranger, je vais donner les m\u00eame noms que tout le monde , David Droga, les boulots qui sortent de Wieden, ou tout ce qu\u2019a fait Marcello Serpa\u2026Ce sont des gens avec qui je ne travaillerai surement jamais mais que j\u2019admire \u00e0 distance comme tout le monde.<\/p>\n<p><span style=\"color: #00ccff;\">Et en dehors de la pub ?<br \/>\n<\/span>Michael Jackson et Martin Scorsese, j\u2019ai des go\u00fbts hyper originaux\u2026<\/p>\n<p><span style=\"color: #00ccff;\">Tu vois quoi comme changement entre tes d\u00e9buts et maintenant ?<br \/>\n<\/span>Attention je vais l\u00e2cher une r\u00e9v\u00e9lation hallucinante : le digital a tout chang\u00e9. Les agences qui n\u2019ont pas pris le virage sont mortes ou en train de mourir. Mais le vrai truc c\u2019est que le digital oblige tout le monde a courir plus vite. Une id\u00e9e digitale est p\u00e9rim\u00e9e dans les 6 mois. Quand une nouvelle techno appara\u00eet, c\u2019est le premier qui d\u00e9gaine qui gagne.<br \/>\nLes agences commencent \u00e0 le comprendre, les clients beaucoup moins. \u00c7a les oblige \u00e0 \u00eatre hyper r\u00e9actif alors qu\u2019ils ne sont pas forc\u00e9ment organis\u00e9s pour \u00e7a. Je grossis le trait mais dans les tr\u00e8s grosses bo\u00eetes c\u2019est souvent comme \u00e7a.<br \/>\nL\u2019autre gros changement qu\u2019\u00e0 apporter le digital, c\u2019est la fa\u00e7on de travailler. Avant il y avait un team et le DC, aujourd\u2019hui sur un sujet digital, il faut int\u00e9grer les chefs de projets, le creative technologist, voir m\u00eame la prod en amont. On travail en \u00e9quipe avec des profils techno et des profils cr\u00e9a qui ne se comprennent pas tout le temps et pourtant il faut faire en sorte que tout le monde s\u2019entende bien.<\/p>\n<p><span style=\"color: #00ccff;\">Tu penses que le milieu va \u00e9voluer de quelle mani\u00e8re ?<br \/>\n<\/span>Le gros concurrent des agences aujourd\u2019hui c\u2019est Google. Si je sch\u00e9matise, ils ont les tuyaux et les agences cr\u00e9ent des contenus \u00e0 mettre dans ces tuyaux. Aujourd\u2019hui les id\u00e9es viennent encore des agences mais je pense que le but de Google a moyen terme est de contr\u00f4ler toute la cha\u00eene, donc de r\u00e9cup\u00e9rer des talents. Le jour o\u00f9 Google aura de tr\u00e8s bons cr\u00e9atifs en interne ce sera compliqu\u00e9 de rivaliser pour les agences\u2026<br \/>\nApr\u00e8s, plus largement, c\u2019est vrai que le big data fait peur, mais il faut esp\u00e9rer que la cr\u00e9ativit\u00e9 et le pouvoir de l\u2019id\u00e9e vaincra l\u2019algorithme\u2026sinon on est mal barr\u00e9.<br \/>\nL\u2019intelligence artificiel aussi \u00e7a fait peur (en fait le futur fait vachement peur) heureusement l\u2019humour est l\u2019une des comp\u00e9tences les plus compliqu\u00e9s a reproduire pour une machine. On a donc peut \u00eatre une chance qu\u2019il existe encore des cr\u00e9atifs de pubs dans 50 ans\u2026<\/p>\n<p><span style=\"color: #00ccff;\">Si tu commen\u00e7ais la pub aujourd\u2019hui, tu irais ou ?<br \/>\n<\/span>Pour ceux qui voudraient une grosse structure internationale, je leur conseillerai Ogilvy Paris, mais commencer dans une grosse structure quand on est junior c\u2019est tr\u00e8s compliqu\u00e9 parce que les gros seniors monopolisent les gros sujets et il faut vraiment faire le pirate pour se faire remarquer. Sinon je leur dirai d\u2019aller chez Buzzman ou Sid lee Paris.<br \/>\nJe n\u2019y ai jamais travaill\u00e9 mais je pense que c\u2019est plus simple de chopper des plus petits sujets ultra cr\u00e9atifs pour faire son doss&rsquo; et se faire remarquer. En plus ce sont deux agences ou le digital est vraiment int\u00e9gr\u00e9, il n\u2019y a pas de cr\u00e9atifs digitaux et de cr\u00e9atifs non digitaux, ils travailleront avec des cr\u00e9atifs polyvalents sur tous les types de m\u00e9dia sans distinction. Cette polyvalence leur sera essentielle pour la suite. Sinon je leur dirai d\u2019aller \u00e0 l\u2019\u00e9tranger pour \u00eatre totalement bilingue et voir d\u2019autres m\u00e9thodes.<\/p>\n<p><span style=\"color: #00ccff;\">Que dirais-tu \u00e0 un team de stagiaire qui veut percer dans le milieu publicitaire ?<br \/>\n<\/span>Faire de la veille comme des porcs, surtout sur le digital. La veille \u00e7a doit \u00eatre comme de la gym, une petite demi heure tous les matins. Il n\u2019y a que \u00e7a pour rester dans la course. Sinon je leur dirai : est ce que vous \u00eates s\u00fbr de vouloir rester en team : \u00e0 l\u2019heure du digital, c\u00e9libataire c\u2019est sympa aussi, ca permet de travailler avec plein d\u2019AD diff\u00e9rents, d\u2019\u00eatre plus mobile et plus autonome.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour Guillaume, quel a \u00e9t\u00e9 ton parcours pro\/tes \u00e9tudes ? DEUG de droit, licence et ma\u00eetrise de sciences politiques, suivi un DESS de management des entreprises de communication et multimedia \u00e0 Dauphine. Je viens d\u2019une \u00e9poque ou l\u2019internet s\u2019appelait multim\u00e9dia ou \u00ab nouvelles technologies \u00bb .Apr\u00e8s mon DESS, j\u2019ai encha\u00een\u00e9 sur un stage de fin [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3562,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_uag_custom_page_level_css":"","footnotes":""},"categories":[44],"tags":[],"class_list":["post-3560","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-creatif"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guillaume Rebbot &#8226; C&#039;est qui les Cr\u00e9as ?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/guillaume-rebbot\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guillaume Rebbot &#8226; C&#039;est qui les Cr\u00e9as ?\" \/>\n<meta property=\"og:description\" content=\"Bonjour Guillaume, quel a \u00e9t\u00e9 ton parcours pro\/tes \u00e9tudes ? DEUG de droit, licence et ma\u00eetrise de sciences politiques, suivi un DESS de management des entreprises de communication et multimedia \u00e0 Dauphine. Je viens d\u2019une \u00e9poque ou l\u2019internet s\u2019appelait multim\u00e9dia ou \u00ab nouvelles technologies \u00bb .Apr\u00e8s mon DESS, j\u2019ai encha\u00een\u00e9 sur un stage de fin [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/guillaume-rebbot\/\" \/>\n<meta property=\"og:site_name\" content=\"C&#039;est qui les Cr\u00e9as ?\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CestquilesCreas\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-07T09:06:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-04-07T09:28:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"586\" \/>\n\t<meta property=\"og:image:height\" content=\"782\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gregory ferembach\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"gregory ferembach\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/guillaume-rebbot\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/guillaume-rebbot\\\/\"},\"author\":{\"name\":\"gregory ferembach\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/person\\\/228b651374249a02f20a1921f0e2516b\"},\"headline\":\"Guillaume Rebbot\",\"datePublished\":\"2015-04-07T09:06:10+00:00\",\"dateModified\":\"2015-04-07T09:28:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/guillaume-rebbot\\\/\"},\"wordCount\":3159,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/guillaume-rebbot\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/11134283_10152838622296973_1638631076_n.jpg\",\"articleSection\":[\".cr\u00e9atif\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/guillaume-rebbot\\\/\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/guillaume-rebbot\\\/\",\"name\":\"Guillaume Rebbot &#8226; C&#039;est qui les Cr\u00e9as ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/guillaume-rebbot\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/guillaume-rebbot\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/11134283_10152838622296973_1638631076_n.jpg\",\"datePublished\":\"2015-04-07T09:06:10+00:00\",\"dateModified\":\"2015-04-07T09:28:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/guillaume-rebbot\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/guillaume-rebbot\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/guillaume-rebbot\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/11134283_10152838622296973_1638631076_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/11134283_10152838622296973_1638631076_n.jpg\",\"width\":586,\"height\":782},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/guillaume-rebbot\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guillaume Rebbot\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#website\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\",\"name\":\"C'est qui les Cr\u00e9as ?\",\"description\":\"D\u00e9couvrez les cr\u00e9atifs, leurs parcours et leurs (en)vies...\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\",\"name\":\"C'est qui les Cr\u00e9as ?\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-cqlc-1024x368-3.png\",\"contentUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-cqlc-1024x368-3.png\",\"width\":1024,\"height\":368,\"caption\":\"C'est qui les Cr\u00e9as ?\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CestquilesCreas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/person\\\/228b651374249a02f20a1921f0e2516b\",\"name\":\"gregory ferembach\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"caption\":\"gregory ferembach\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guillaume Rebbot &#8226; C&#039;est qui les Cr\u00e9as ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/guillaume-rebbot\/","og_locale":"fr_FR","og_type":"article","og_title":"Guillaume Rebbot &#8226; C&#039;est qui les Cr\u00e9as ?","og_description":"Bonjour Guillaume, quel a \u00e9t\u00e9 ton parcours pro\/tes \u00e9tudes ? DEUG de droit, licence et ma\u00eetrise de sciences politiques, suivi un DESS de management des entreprises de communication et multimedia \u00e0 Dauphine. Je viens d\u2019une \u00e9poque ou l\u2019internet s\u2019appelait multim\u00e9dia ou \u00ab nouvelles technologies \u00bb .Apr\u00e8s mon DESS, j\u2019ai encha\u00een\u00e9 sur un stage de fin [&hellip;]","og_url":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/guillaume-rebbot\/","og_site_name":"C&#039;est qui les Cr\u00e9as ?","article_publisher":"https:\/\/www.facebook.com\/CestquilesCreas\/","article_published_time":"2015-04-07T09:06:10+00:00","article_modified_time":"2015-04-07T09:28:49+00:00","og_image":[{"width":586,"height":782,"url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n.jpg","type":"image\/jpeg"}],"author":"gregory ferembach","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"gregory ferembach","Dur\u00e9e de lecture estim\u00e9e":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/guillaume-rebbot\/#article","isPartOf":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/guillaume-rebbot\/"},"author":{"name":"gregory ferembach","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/person\/228b651374249a02f20a1921f0e2516b"},"headline":"Guillaume Rebbot","datePublished":"2015-04-07T09:06:10+00:00","dateModified":"2015-04-07T09:28:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/guillaume-rebbot\/"},"wordCount":3159,"commentCount":0,"publisher":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/guillaume-rebbot\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n.jpg","articleSection":[".cr\u00e9atif"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/guillaume-rebbot\/","url":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/guillaume-rebbot\/","name":"Guillaume Rebbot &#8226; C&#039;est qui les Cr\u00e9as ?","isPartOf":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/guillaume-rebbot\/#primaryimage"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/guillaume-rebbot\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n.jpg","datePublished":"2015-04-07T09:06:10+00:00","dateModified":"2015-04-07T09:28:49+00:00","breadcrumb":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/guillaume-rebbot\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/guillaume-rebbot\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/guillaume-rebbot\/#primaryimage","url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n.jpg","contentUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n.jpg","width":586,"height":782},{"@type":"BreadcrumbList","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/guillaume-rebbot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ferembach.com\/cestquilescreas\/"},{"@type":"ListItem","position":2,"name":"Guillaume Rebbot"}]},{"@type":"WebSite","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#website","url":"https:\/\/www.ferembach.com\/cestquilescreas\/","name":"C'est qui les Cr\u00e9as ?","description":"D\u00e9couvrez les cr\u00e9atifs, leurs parcours et leurs (en)vies...","publisher":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ferembach.com\/cestquilescreas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization","name":"C'est qui les Cr\u00e9as ?","url":"https:\/\/www.ferembach.com\/cestquilescreas\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/logo\/image\/","url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2020\/02\/logo-cqlc-1024x368-3.png","contentUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2020\/02\/logo-cqlc-1024x368-3.png","width":1024,"height":368,"caption":"C'est qui les Cr\u00e9as ?"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CestquilesCreas\/"]},{"@type":"Person","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/person\/228b651374249a02f20a1921f0e2516b","name":"gregory ferembach","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","caption":"gregory ferembach"}}]}},"uagb_featured_image_src":{"full":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n.jpg",586,782,false],"thumbnail":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n-120x120.jpg",120,120,true],"medium":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n-45x60.jpg",45,60,true],"medium_large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n.jpg",586,782,false],"large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n.jpg",586,782,false],"1536x1536":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n.jpg",586,782,false],"2048x2048":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n.jpg",586,782,false],"et-pb-post-main-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n-400x250.jpg",400,250,true],"et-pb-post-main-image-fullwidth":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n-586x675.jpg",586,675,true],"et-pb-portfolio-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n-400x284.jpg",400,284,true],"et-pb-portfolio-module-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n-510x382.jpg",510,382,true],"et-pb-portfolio-image-single":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n.jpg",586,782,false],"et-pb-gallery-module-image-portrait":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n-400x516.jpg",400,516,true],"et-pb-post-main-image-fullwidth-large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n.jpg",586,782,false],"et-pb-image--responsive--desktop":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n.jpg",540,720,false],"et-pb-image--responsive--tablet":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n.jpg",413,551,false],"et-pb-image--responsive--phone":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2015\/04\/11134283_10152838622296973_1638631076_n-480x641.jpg",202,270,true]},"uagb_author_info":{"display_name":"gregory ferembach","author_link":"https:\/\/www.ferembach.com\/cestquilescreas\/author\/gregoryferembach\/"},"uagb_comment_info":0,"uagb_excerpt":"Bonjour Guillaume, quel a \u00e9t\u00e9 ton parcours pro\/tes \u00e9tudes ? DEUG de droit, licence et ma\u00eetrise de sciences politiques, suivi un DESS de management des entreprises de communication et multimedia \u00e0 Dauphine. Je viens d\u2019une \u00e9poque ou l\u2019internet s\u2019appelait multim\u00e9dia ou \u00ab nouvelles technologies \u00bb .Apr\u00e8s mon DESS, j\u2019ai encha\u00een\u00e9 sur un stage de fin\u2026","_links":{"self":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts\/3560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/comments?post=3560"}],"version-history":[{"count":0,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts\/3560\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/media\/3562"}],"wp:attachment":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/media?parent=3560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/categories?post=3560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/tags?post=3560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}