{"id":4153,"date":"2017-10-17T19:32:56","date_gmt":"2017-10-17T17:32:56","guid":{"rendered":"http:\/\/www.ferembach.com\/cestquilescreas\/?p=4153"},"modified":"2017-10-18T15:57:51","modified_gmt":"2017-10-18T13:57:51","slug":"vincent-boursaud","status":"publish","type":"post","link":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/vincent-boursaud\/","title":{"rendered":"Vincent Boursaud"},"content":{"rendered":"<p><a href=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/bandeau-cqlc-boursaud-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4167\" src=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/bandeau-cqlc-boursaud-1.jpg\" alt=\"\" width=\"1000\" height=\"350\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/bandeau-cqlc-boursaud-1.jpg 1000w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/bandeau-cqlc-boursaud-1-600x210.jpg 600w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/bandeau-cqlc-boursaud-1-768x269.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><br \/>\n<span style=\"color: #00ccff;\"><br \/>\nBonjour Vincent, tu es directeur artistique chez Romance, quel a \u00e9t\u00e9 ton parcours ?<\/span><br \/>\nJ\u2019ai commenc\u00e9 la publicit\u00e9 tr\u00e8s tard, je travaille depuis 6 ans en agence.<br \/>\nJ\u2019ai commenc\u00e9 \u00e0 28 ans, avant j\u2019\u00e9tais \u00e9ducateur, je me suis occup\u00e9 d\u2019enfants en bas \u00e2ge pendant 7 ans.<br \/>\nJ\u2019ai chang\u00e9 de c\u00f4t\u00e9, maintenant j\u2019en suis un.<\/p>\n<p><span style=\"color: #00ccff;\">Comment en es-tu arriv\u00e9 \u00e0 vouloir faire de la pub\u00a0 ?<\/span><br \/>\nSur un coup de t\u00eate.<br \/>\nJ&rsquo;ai fait SupdePub pendant 2 ans puis je suis parti en stage chez Grey et je ne suis jamais retourn\u00e9 \u00e0 l&rsquo;\u00e9cole.<br \/>\nJ&rsquo;ai pr\u00e9sent\u00e9 mon doss&rsquo; avec Constantin de La Borde, et Jer\u00f4me Gonfond nous a pris sans discuter.<br \/>\nMerci J\u00e9r\u00f4me, clairement.<\/p>\n<p><span style=\"color: #00ccff;\">Tu as h\u00e9sit\u00e9 \u00e0 faire de la pub ?<br \/>\n<\/span>J\u2019y suis all\u00e9, et mieux vaut ne pas h\u00e9siter sinon \u00e7a devient vite l\u2019enfer.<br \/>\nC\u2019est des potes d\u2019enfance qui m\u2019ont motiv\u00e9, je suis venu \u00e0 Paris et je ne suis jamais reparti.<\/p>\n<p><span style=\"color: #00ccff;\">Tu aurais fait quoi \u00e0 la place de ce m\u00e9tier ?<\/span><br \/>\n\u00c9ducateur, j\u2019\u00e9tais parti pour.<br \/>\nSinon, j\u2019aurais ador\u00e9 \u00eatre astronaute, mais mes bulletins scolaires m\u2019ont rapidement convaincu que je ne serai jamais en team avec Thomas Pesquet.<\/p>\n<p><span style=\"color: #00ccff;\">Tu as travaill\u00e9 avec qui et sur quoi ? <\/span><br \/>\nJ\u2019ai donc commenc\u00e9 Chez Grey Paris en stage en team avec Constantin (qui bosse maintenant chez Havas Paris, c&rsquo;est d&rsquo;ailleurs le parrain de mon fils) sous la direction de cr\u00e9ation d&rsquo;Andr\u00e9a Stillacci. On a \u00e9t\u00e9 form\u00e9s par J\u00e9r\u00f4me Gonfond et <a href=\"http:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/benjamin-dessagne\/\">Benjamin Dessagne<\/a>. Et plus personnellement, j\u2019ai rencontr\u00e9 la m\u00e8re de mes enfants l\u00e0-bas, <a href=\"http:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/constance-godard\/\">Constance Godard<\/a> (l\u00e0 je marque des points pour sortir samedi soir).<\/p>\n<p>Ensuite, nous sommes partis chez Cake Paris avec Alban P\u00e9nicaut.<br \/>\nJe pense que \u00e7a restera humainement un des meilleurs souvenirs de ma carri\u00e8re de junior. On a fait notre premi\u00e8re campagne pour Canal+ BORGIA, on a gagn\u00e9 un Lion au festival de Cannes, et je me suis dit \u00ab\u00a0c\u2019est \u00e7a la pub\u00a0?\u00a0\u00bb<br \/>\nPar la suite j\u2019ai vite d\u00e9chant\u00e9.<\/p>\n<p>Ensuite on s\u2019est s\u00e9par\u00e9 et je me suis mis en team avec Damien Veillet, puis on est rapidement partis pour bosser chez Marcel sous la DC Anne de Maup\u00e9ou. Grosse pression et au final on s\u2019est \u00e9clat\u00e9.<br \/>\nEn tant que DA, Dimitri Guerassimov m\u2019a tout appris, et l\u00e0-bas on a travaill\u00e9 sur Orange, epoints, DS et Intermarche<\/p>\n<p>Puis est arriv\u00e9e Romance en 2015 sous la direction de cr\u00e9ation d&rsquo;Alexandre Herv\u00e9. On a boss\u00e9 sur Belin, Betclic, et surtout Intermarch\u00e9. Aujourd\u2019hui nous ne sommes plus en team avec Damien mais on est rest\u00e9 tr\u00e8s potes.<\/p>\n<p>Je bosse aussi souvent avec Julien Bon (un DA aussi). On a fait derni\u00e8rement la campagne Intermarch\u00e9. En gros on est pas en team mais on est assis \u00e0 c\u00f4t\u00e9, et j\u2019aime bien sa bouille\u00a0;))))))<br \/>\nNiveau r\u00e9partition des t\u00e2ches, il fait la DA et je fais la DA. Parfois il \u00e9crit et du coup moi aussi. Plus s\u00e9rieusement, on s\u2019adapte.<\/p>\n<p><span style=\"color: #00ccff;\">Parles nous de 2-3 choses que tu as faites :\u00a0<\/span><br \/>\nChez Cake Paris\u00a0:<br \/>\n<iframe loading=\"lazy\" title=\"BORGIA Discover what you should not have\" src=\"https:\/\/player.vimeo.com\/video\/41022315?dnt=1&amp;app_id=122963\" width=\"1080\" height=\"608\" frameborder=\"0\" allow=\"autoplay; fullscreen\" allowfullscreen><\/iframe><\/p>\n<p>Premi\u00e8re campagne pour Canal+, tournage assez \u00e9pique, des filles nues, des pr\u00eatres et des cur\u00e9s\u2026 Tout ce qu\u2019on veut voir sur un premier tournage.<\/p>\n<p>Chez Marcel\u00a0:<br \/>\n<iframe loading=\"lazy\" title=\"Relocklove by Orange\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/FSMuwXB2Q8A?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><br \/>\nPremi\u00e8re campagne chez Marcel pour Orange.<\/p>\n<p><iframe loading=\"lazy\" title=\"Merciduretard\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/msjKbgxsWqk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Une Campagne pour epoints sans budget mais dont on est fiers. Pour une fois qu\u2019on incite des gens \u00e0 lire.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Publicis Groupe - The Skippable Wishes\" src=\"https:\/\/player.vimeo.com\/video\/158000197?dnt=1&amp;app_id=122963\" width=\"1080\" height=\"608\" frameborder=\"0\" allow=\"autoplay; fullscreen\" allowfullscreen><\/iframe><\/p>\n<p>Et enfin la carte de v\u0153ux de Maurice, tr\u00e8s bon souvenir puisqu&rsquo;on tournait cette campagne pendant nos premiers jours de Romance. On \u00e9tait <span class=\"_3oh- _58nk\">avec Anne, <a class=\"_4lul\" href=\"https:\/\/www.messenger.com\/t\/vincent.boursaud#\">Dim<\/a>, Maurice et Pierre Marcus\u2026 rien de tel qu\u2019un tournage marrant pour se dire au revoir.<\/span><\/p>\n<p>Chez Romance\u00a0:<br \/>\nhttps:\/\/www.youtube.com\/watch?v=dW5qpedcnMA<\/p>\n<p>On ne pouvait pas ne pas le poster, c\u2019\u00e9tait notre premi\u00e8re campagne pour Intermarch\u00e9 qui arrivait chez Romance.<br \/>\nUne rencontre avec Katia Lewkowicz (chez Carnibird), je le souhaite \u00e0 beaucoup de cr\u00e9as. Et premier gros film avec Alexandre Herv\u00e9, je le souhaite aussi \u00e0 beaucoup de cr\u00e9as.<\/p>\n<p>Et la derni\u00e8re campagne Intermarch\u00e9, \u00e9t\u00e9 2017 :<\/p>\n<p><iframe loading=\"lazy\" title=\"Intermarch\u00e9 - D\u00e9couvrez les Bons L\u00e9gumes\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/bq0mqsh7iPY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><a href=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/intermarche.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4174\" src=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/intermarche.jpg\" alt=\"\" width=\"1000\" height=\"927\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/intermarche.jpg 1000w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/intermarche-600x556.jpg 600w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/intermarche-768x712.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p><span style=\"color: #00ccff;\">Le succ\u00e8s des prix dans les Festivals de Pub \u00e7a change quoi ?<\/span><br \/>\nIl y en a une tonne maintenant, mais qu\u2019on se le dise, pour bouger d\u2019agence, \u00e7a marche toujours, et ensuite pour l\u2019\u00e9go, \u00e7a marche aussi. Le must c\u2019est d\u2019allier les 2, campagne populaire et prim\u00e9e, \u00e7a fait vraiment plaisir.<br \/>\nApr\u00e8s tout d\u00e9pend des personnalit\u00e9s. Il y en a que \u00e7a peut rendre fou, et d\u2019autres qui s\u2019en foutent. Je l\u2019avoue, je pense que je fais partie de la premi\u00e8re cat\u00e9gorie, mais ce n\u2019est certainement pas la bonne option.<br \/>\nChacun trouve sa motivation quelque part.<\/p>\n<p><span style=\"color: #00ccff;\">Tu fais quelque chose en parall\u00e8le de ton m\u00e9tier, des projets, des passions ?<\/span><br \/>\nJe m\u2019occupe de mes 2 enfants.<br \/>\nEt en vrai, je regarde des pubs. Je sais c\u2019est horrible.<br \/>\nSi j&rsquo;avais plus de temps, j&rsquo;adorerais toucher \u00e0 la r\u00e9al ou \u00e9crire des films.<br \/>\nMais bon, c&rsquo;est un peu le cas de beaucoup de cr\u00e9as.<br \/>\nJ&rsquo;aimerais un peu plus voyager, clairement.<\/p>\n<p><span style=\"color: #00ccff;\">Dans ton m\u00e9tier quel est ton meilleur souvenir ? et le pire ?<\/span><br \/>\nJ\u2019en ai tellement. Franchement, je crois que c\u2019est un tournage au Maroc avec Alban P\u00e9nicaut, je n\u2019en dirai pas plus.<br \/>\nEt mon pire souvenir, je crois que c\u2019est aussi un tournage au Maroc avec Alban P\u00e9nicaut. Je n\u2019en dirai pas plus non plus.<br \/>\nMon premier Lion aussi j\u2019avoue, tr\u00e8s bon souvenir.<\/p>\n<p><span style=\"color: #00ccff;\">Le truc qui t&rsquo;as fait le plus halluciner ?<\/span><br \/>\nTRUMP, et surtout Neymar \u00e0 Paris.<\/p>\n<p><span style=\"color: #00ccff;\">Qu&rsquo;est ce que tu ferais si tu n&rsquo;avais pas peur ?<\/span><br \/>\nJe prendrais la place d\u2019Alexandre Herv\u00e9.<\/p>\n<p><span style=\"color: #00ccff;\">Que dirais-tu au Vincent de 20 ans ?<\/span><br \/>\nHappy birthday to you mon gars\u00a0!<\/p>\n<p><span style=\"color: #00ccff;\">Avoir des enfants \u00e7a change quoi en tant que publicitaire ?<\/span><br \/>\n\u00c7a change que les charettes c\u2019est plus compliqu\u00e9, et que tout \u00e0 coup, tu commences \u00e0 faire des campagnes avec des enfants partout.<\/p>\n<p><span style=\"color: #00ccff;\">Quelles sont les pubs qui t&rsquo;ont le plus marqu\u00e9es ?<\/span><br \/>\nEn vrai il y en a tellement\u2026<\/p>\n<p><iframe loading=\"lazy\" title=\"Disney Magic Happens Commercial\" width=\"1080\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/ynkUL7G68mI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"Levi&#039;s 2002 Odyseey (Haendel - Sarabande)\" width=\"1080\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/yNFUS05I-aw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"PUB INTEL ANGLAIS\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/G-2GhnngSOs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"Bud Light - Skydiving\" width=\"1080\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/CFgYd_s14Lo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"Swear Jar \u3010Bud Light\u00ae\u3011\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/KY0ztZQJ5p4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"Canal+ \/ Le Placard\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/VEiLGJrCxSY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>https:\/\/www.youtube.com\/watch?v=XNic4wf8AYg<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=SKL254Y_jtc<\/p>\n<p><iframe loading=\"lazy\" title=\"P&amp;G - Thank You Mama - Best Job 2012 HD 2M\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/0ruHOaHrGnQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"John Lewis - The Long Wait\" src=\"https:\/\/player.vimeo.com\/video\/31909633?dnt=1&amp;app_id=122963\" width=\"1080\" height=\"608\" frameborder=\"0\" allow=\"autoplay; fullscreen\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"A Harvey Nichols Christmas 2013 -- Sorry, I Spent It On Myself\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/ITyeI3YyYw8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"Jose Cuervo - Tomorrow is Overrated\" src=\"https:\/\/player.vimeo.com\/video\/207294836?dnt=1&amp;app_id=122963\" width=\"1080\" height=\"608\" frameborder=\"0\" allow=\"autoplay; fullscreen\" allowfullscreen><\/iframe><\/p>\n<p>https:\/\/vimeo.com\/140707332<\/p>\n<p><span style=\"color: #00ccff;\">Tu as des mod\u00e8les de cr\u00e9atifs dans la publicit\u00e9 ? et dehors, des gens qui t&rsquo;inspirent ?<\/span><br \/>\nSans h\u00e9sitation Patrice Dumas. Le meilleur r\u00e9dacteur de Paris je trouve.<br \/>\nCe mec pond des accroches \u00e0 la pelle, et c\u2019est rarement moyen.<br \/>\nSinon, je suis oblig\u00e9 de citer Alexandre Herv\u00e9, d\u00e9j\u00e0 pour \u00eatre augment\u00e9, et surtout parce qu\u2019il est vraiment tr\u00e8s fort. Tu d\u00e9barques dans son bureau avec une id\u00e9e que tu adores, et une que tu trouves pas dingue au cas o\u00f9 la premi\u00e8re passe pas, et bien il te jette la bonne pour prendre la nulle, et en fait il a raison, c\u2019est celle-ci qui est bien.<\/p>\n<p>En dehors des cr\u00e9atifs, je dirais des r\u00e9alisateurs, comme <a href=\"https:\/\/vimeo.com\/danielwolfe\" target=\"_blank\" rel=\"noopener\">Daniel Wolfe<\/a> ou <a href=\"https:\/\/vimeo.com\/search?q=Ringan+Ledwidge\" target=\"_blank\" rel=\"noopener\">Ringan Ledwidge<\/a>.<br \/>\nhttps:\/\/www.youtube.com\/watch?v=TsOyqSJkwUA<br \/>\nhttps:\/\/vimeo.com\/44030564<\/p>\n<p><span style=\"color: #00ccff;\">Tu vois quoi comme changement entre tes d\u00e9buts et maintenant ?<\/span><br \/>\n60m2<\/p>\n<p><span style=\"color: #00ccff;\">Tu penses que le milieu va \u00e9voluer de quelle mani\u00e8re ?<\/span><br \/>\nAucune id\u00e9e. Je me pose pas vraiment la question. Mais j\u2019aime bien le fait qu\u2019on revienne au film TV. C\u2019est quand m\u00eame l\u2019exercice le plus cool je trouve.<\/p>\n<p><span style=\"color: #00ccff;\">Si tu commen\u00e7ais la pub aujourd\u2019hui, tu irais ou ?<\/span><br \/>\n<span data-offset-key=\"303a1-0-0\">Romance (50 salari\u00e9s) parce que je pense qu&rsquo;en tr\u00e8s peu de temps, elle a fait ses preuves et que le projet de l&rsquo;agence est assez ambitieux. J&rsquo;y suis depuis 2 ans et la vitesse \u00e0 laquelle l&rsquo;agence grandit est impressionnante, mais ce qui la rend vraiment cool, c&rsquo;est de ne pas vouloir devenir une \u00e9norme usine et de rester un peu familiale. Ici tout le monde se conna\u00eet, et c&rsquo;est tr\u00e8s bien comme \u00e7a.<\/span><\/p>\n<div class=\"\" data-block=\"true\" data-editor=\"6b8sj\" data-offset-key=\"7jnhl-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"7jnhl-0-0\">\n<p><span data-offset-key=\"7jnhl-0-0\">Buzzman (120 salari\u00e9s), parce qu&rsquo;en 10 ans, Georges Mohammed-Ch\u00e9rif en a fait l&rsquo;agence ind\u00e9pendante la plus remarqu\u00e9e et cr\u00e9ative dans tous les sens du terme. Au d\u00e9but c&rsquo;\u00e9tait l&rsquo;agence qui tapait des one shot et petit \u00e0 petit elle est venue botter le cul de pas mal de grosses agences jusqu&rsquo;\u00e0 en devenir une r\u00e9f\u00e9rence.<br \/>\nEn gros c&rsquo;est une r\u00e9ussite totale, RESPECT.<br \/>\nJ&rsquo;aurais beaucoup aim\u00e9 y aller, comme tout le monde je pense.<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"6b8sj\" data-offset-key=\"etsp5-0-0\">\n<div class=\"\" data-block=\"true\" data-editor=\"6b8sj\" data-offset-key=\"1mea5-0-0\">\n<p><span data-offset-key=\"etsp5-0-0\">A l&rsquo;\u00e9tranger, W&amp;K portland, Adam&amp;eve, Droga5, Forsman&amp;Bodenfors, bref beaucoup d&rsquo;agences avec des &amp;.<\/span><\/p>\n<p>Mais en vrai, il faut commencer o\u00f9 on peut, et faire de son mieux pour pouvoir choisir l\u2019agence de ses r\u00eaves par la suite.<\/p>\n<\/div>\n<\/div>\n<p><span style=\"color: #00ccff;\">Que dirais-tu \u00e0 un team de stagiaire qui veut percer ?<\/span><br \/>\nDe rien l\u00e2cher et proposer \u00e9norm\u00e9ment d\u2019id\u00e9es.<br \/>\nMonter sur des vrais briefs et tenter le coup.<br \/>\nEt sinon, de se marrer un maximum parce que c\u2019est quand m\u00eame un boulot plut\u00f4t agr\u00e9able.<br \/>\nOn rencontre beaucoup de monde d\u2019univers diff\u00e9rents, et ce n\u2019est pas le cas partout.<\/p>\n<p>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour Vincent, tu es directeur artistique chez Romance, quel a \u00e9t\u00e9 ton parcours ? J\u2019ai commenc\u00e9 la publicit\u00e9 tr\u00e8s tard, je travaille depuis 6 ans en agence. J\u2019ai commenc\u00e9 \u00e0 28 ans, avant j\u2019\u00e9tais \u00e9ducateur, je me suis occup\u00e9 d\u2019enfants en bas \u00e2ge pendant 7 ans. J\u2019ai chang\u00e9 de c\u00f4t\u00e9, maintenant j\u2019en suis un. Comment [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4157,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_uag_custom_page_level_css":"","footnotes":""},"categories":[5,63],"tags":[],"class_list":["post-4153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-directeurs-artistiques","category-romance"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vincent Boursaud &#8226; C&#039;est qui les Cr\u00e9as ?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/vincent-boursaud\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vincent Boursaud &#8226; C&#039;est qui les Cr\u00e9as ?\" \/>\n<meta property=\"og:description\" content=\"Bonjour Vincent, tu es directeur artistique chez Romance, quel a \u00e9t\u00e9 ton parcours ? J\u2019ai commenc\u00e9 la publicit\u00e9 tr\u00e8s tard, je travaille depuis 6 ans en agence. J\u2019ai commenc\u00e9 \u00e0 28 ans, avant j\u2019\u00e9tais \u00e9ducateur, je me suis occup\u00e9 d\u2019enfants en bas \u00e2ge pendant 7 ans. J\u2019ai chang\u00e9 de c\u00f4t\u00e9, maintenant j\u2019en suis un. Comment [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/vincent-boursaud\/\" \/>\n<meta property=\"og:site_name\" content=\"C&#039;est qui les Cr\u00e9as ?\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CestquilesCreas\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-17T17:32:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-18T13:57:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gregory ferembach\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"gregory ferembach\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/vincent-boursaud\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/vincent-boursaud\\\/\"},\"author\":{\"name\":\"gregory ferembach\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/person\\\/228b651374249a02f20a1921f0e2516b\"},\"headline\":\"Vincent Boursaud\",\"datePublished\":\"2017-10-17T17:32:56+00:00\",\"dateModified\":\"2017-10-18T13:57:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/vincent-boursaud\\\/\"},\"wordCount\":1636,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/vincent-boursaud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Vincent.jpg\",\"articleSection\":[\".Directeur Artistique\",\"Romance\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/vincent-boursaud\\\/\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/vincent-boursaud\\\/\",\"name\":\"Vincent Boursaud &#8226; C&#039;est qui les Cr\u00e9as ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/vincent-boursaud\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/vincent-boursaud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Vincent.jpg\",\"datePublished\":\"2017-10-17T17:32:56+00:00\",\"dateModified\":\"2017-10-18T13:57:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/vincent-boursaud\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/vincent-boursaud\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/vincent-boursaud\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Vincent.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Vincent.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/vincent-boursaud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vincent Boursaud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#website\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\",\"name\":\"C'est qui les Cr\u00e9as ?\",\"description\":\"D\u00e9couvrez les cr\u00e9atifs, leurs parcours et leurs (en)vies...\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\",\"name\":\"C'est qui les Cr\u00e9as ?\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-cqlc-1024x368-3.png\",\"contentUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-cqlc-1024x368-3.png\",\"width\":1024,\"height\":368,\"caption\":\"C'est qui les Cr\u00e9as ?\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CestquilesCreas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/person\\\/228b651374249a02f20a1921f0e2516b\",\"name\":\"gregory ferembach\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"caption\":\"gregory ferembach\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vincent Boursaud &#8226; C&#039;est qui les Cr\u00e9as ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/vincent-boursaud\/","og_locale":"fr_FR","og_type":"article","og_title":"Vincent Boursaud &#8226; C&#039;est qui les Cr\u00e9as ?","og_description":"Bonjour Vincent, tu es directeur artistique chez Romance, quel a \u00e9t\u00e9 ton parcours ? J\u2019ai commenc\u00e9 la publicit\u00e9 tr\u00e8s tard, je travaille depuis 6 ans en agence. J\u2019ai commenc\u00e9 \u00e0 28 ans, avant j\u2019\u00e9tais \u00e9ducateur, je me suis occup\u00e9 d\u2019enfants en bas \u00e2ge pendant 7 ans. J\u2019ai chang\u00e9 de c\u00f4t\u00e9, maintenant j\u2019en suis un. Comment [&hellip;]","og_url":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/vincent-boursaud\/","og_site_name":"C&#039;est qui les Cr\u00e9as ?","article_publisher":"https:\/\/www.facebook.com\/CestquilesCreas\/","article_published_time":"2017-10-17T17:32:56+00:00","article_modified_time":"2017-10-18T13:57:51+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent.jpg","type":"image\/jpeg"}],"author":"gregory ferembach","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"gregory ferembach","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/vincent-boursaud\/#article","isPartOf":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/vincent-boursaud\/"},"author":{"name":"gregory ferembach","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/person\/228b651374249a02f20a1921f0e2516b"},"headline":"Vincent Boursaud","datePublished":"2017-10-17T17:32:56+00:00","dateModified":"2017-10-18T13:57:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/vincent-boursaud\/"},"wordCount":1636,"commentCount":1,"publisher":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/vincent-boursaud\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent.jpg","articleSection":[".Directeur Artistique","Romance"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/vincent-boursaud\/","url":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/vincent-boursaud\/","name":"Vincent Boursaud &#8226; C&#039;est qui les Cr\u00e9as ?","isPartOf":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/vincent-boursaud\/#primaryimage"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/vincent-boursaud\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent.jpg","datePublished":"2017-10-17T17:32:56+00:00","dateModified":"2017-10-18T13:57:51+00:00","breadcrumb":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/vincent-boursaud\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/vincent-boursaud\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/vincent-boursaud\/#primaryimage","url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent.jpg","contentUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/vincent-boursaud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ferembach.com\/cestquilescreas\/"},{"@type":"ListItem","position":2,"name":"Vincent Boursaud"}]},{"@type":"WebSite","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#website","url":"https:\/\/www.ferembach.com\/cestquilescreas\/","name":"C'est qui les Cr\u00e9as ?","description":"D\u00e9couvrez les cr\u00e9atifs, leurs parcours et leurs (en)vies...","publisher":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ferembach.com\/cestquilescreas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization","name":"C'est qui les Cr\u00e9as ?","url":"https:\/\/www.ferembach.com\/cestquilescreas\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/logo\/image\/","url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2020\/02\/logo-cqlc-1024x368-3.png","contentUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2020\/02\/logo-cqlc-1024x368-3.png","width":1024,"height":368,"caption":"C'est qui les Cr\u00e9as ?"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CestquilesCreas\/"]},{"@type":"Person","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/person\/228b651374249a02f20a1921f0e2516b","name":"gregory ferembach","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","caption":"gregory ferembach"}}]}},"uagb_featured_image_src":{"full":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent.jpg",1000,1000,false],"thumbnail":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent-290x290.jpg",120,120,true],"medium":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent-600x600.jpg",60,60,true],"medium_large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent-768x768.jpg",768,768,true],"large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent.jpg",1000,1000,false],"1536x1536":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent.jpg",1000,1000,false],"2048x2048":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent.jpg",1000,1000,false],"et-pb-post-main-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent.jpg",250,250,false],"et-pb-post-main-image-fullwidth":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent.jpg",675,675,false],"et-pb-portfolio-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent.jpg",284,284,false],"et-pb-portfolio-module-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent.jpg",382,382,false],"et-pb-portfolio-image-single":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent.jpg",1000,1000,false],"et-pb-gallery-module-image-portrait":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent.jpg",400,400,false],"et-pb-post-main-image-fullwidth-large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent.jpg",1000,1000,false],"et-pb-image--responsive--desktop":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent.jpg",720,720,false],"et-pb-image--responsive--tablet":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent.jpg",551,551,false],"et-pb-image--responsive--phone":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2017\/10\/Vincent.jpg",270,270,false]},"uagb_author_info":{"display_name":"gregory ferembach","author_link":"https:\/\/www.ferembach.com\/cestquilescreas\/author\/gregoryferembach\/"},"uagb_comment_info":1,"uagb_excerpt":"Bonjour Vincent, tu es directeur artistique chez Romance, quel a \u00e9t\u00e9 ton parcours ? J\u2019ai commenc\u00e9 la publicit\u00e9 tr\u00e8s tard, je travaille depuis 6 ans en agence. J\u2019ai commenc\u00e9 \u00e0 28 ans, avant j\u2019\u00e9tais \u00e9ducateur, je me suis occup\u00e9 d\u2019enfants en bas \u00e2ge pendant 7 ans. J\u2019ai chang\u00e9 de c\u00f4t\u00e9, maintenant j\u2019en suis un. Comment\u2026","_links":{"self":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts\/4153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/comments?post=4153"}],"version-history":[{"count":0,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts\/4153\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/media\/4157"}],"wp:attachment":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/media?parent=4153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/categories?post=4153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/tags?post=4153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}