{"id":76,"date":"2011-11-21T03:56:48","date_gmt":"2011-11-21T01:56:48","guid":{"rendered":"http:\/\/www.ferembach.com\/cestquilescreas\/?p=76"},"modified":"2011-11-22T20:59:07","modified_gmt":"2011-11-22T18:59:07","slug":"marianne-fonferrier","status":"publish","type":"post","link":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/marianne-fonferrier\/","title":{"rendered":"Marianne Fonferrier"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2083\" title=\"fonferrier\" src=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier1-600x210.jpg\" alt=\"\" width=\"600\" height=\"210\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier1-600x210.jpg 600w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier1.jpg 1000w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><span style=\"color: #5cc5ed;\">Bonjour Marianne, tu es Directrice Artistique chez TBWA, tu as eu quel parcours ?<\/span><br \/>\nApr\u00e8s des \u00e9tudes pas tr\u00e8s bonnes (redoubl\u00e9e 2 fois) je suis rentr\u00e9e  apr\u00e8s la 3\u00e8me \u00e0 Olivier de Serres (<a href=\"http:\/\/www.ensaama.net\/HTTP\/OdS_HTML\/Index.html\" target=\"_blank\">ENSAAMA<\/a>). Apr\u00e8s 3 ans j\u2019ai fait les Arts D\u00e9co \u00e0 Paris (<a href=\"http:\/\/www.ensad.fr\/\" target=\"_blank\">ENSAD<\/a>). Professionnellement Je n\u2019ai fait que 2  agences&#8230; &lsquo;Alice&rsquo; puis TBWA ou plut\u00f4t BDDP puis BDDP\/TBWA  et enfin TBWA : TBWA (p\u00e9riode Vervroegen), <a href=\"http:\/\/www.tbwa-france.com\/#gsi06697ci0q\" target=\"_blank\">TBWA<\/a> actuellement. En fait  plusieurs agences&#8230;.<\/p>\n<p><span style=\"color: #5cc5ed;\">Tu as de la famille des contacts proches qui travaillaient dans ce milieu avant d&rsquo;y entrer ?<\/span><br \/>\nEffectivement, mon p\u00e8re \u00e9tait roughman et je l\u2019accompagnais souvent \u00e0 ses livraisons dans les agences et c\u2019est l\u00e0 o\u00f9 un jour j\u2019ai d\u00e9cid\u00e9 d\u2019\u00eatre  DA.<\/p>\n<p><span style=\"color: #5cc5ed;\">Pourquoi vouloir \u00eatre DA plut\u00f4t que rough(wo)man ?<\/span><br \/>\nQuand j\u2019avais 14 ans nous avions livr\u00e9 un rough dans une agence, le D.A de l\u2019\u00e9poque revenait d\u2019un shooting o\u00f9 il \u00e9tait all\u00e9 au 4 coins du monde, son boulot avait l\u2019air d\u2019\u00eatre cool, c\u2019est l\u00e0 que j\u2019ai d\u00e9cid\u00e9 de faire ce m\u00e9tier.<\/p>\n<p><span style=\"color: #5cc5ed;\">Depuis combien d&rsquo;ann\u00e9es travailles tu dans le milieu de la publicit\u00e9 ?<\/span><br \/>\nH\u00e9 bien, \u00e0 peu pr\u00e9s 23 ans&#8230;&#8230;..<\/p>\n<p><span style=\"color: #5cc5ed;\">Tu travailles avec qui et sur quoi chez TBWA ?<\/span><br \/>\nActuellement je suis seule mais je fais un peu de direction de cr\u00e9ation sur certains  budgets. Je travaille sur \u00e0 peu pr\u00e9s tout. Je travaille sur de la beaut\u00e9  (Vichy) et en m\u00eame temps sur McDonald\u2019s ou U  ou Monaco ou Nissan&#8230;<\/p>\n<p><span style=\"color: #5cc5ed;\">Parles nous de deux trois choses que tu as faites :<\/span><br \/>\nUne campagne pour la principaut\u00e9 de Monaco tout r\u00e9cemment parce qu\u2019elle  m\u2019a permis de travailler avec un graphiste et de m\u2019\u00e9clater sur la DA.<br \/>\nUn film AIDES pour l\u2019Afrique, qui a \u00e9t\u00e9 une aventure magnifique et qui m\u2019a donn\u00e9 un Lion \u00e0 Cannes.<br \/>\nUne campagne SNCF Corail THEOZ o\u00f9 je me suis vraiment amus\u00e9. Et quelques  films (TGV, Nissan Crossover, La Redoute, Hollywood&#8230;)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2088\" title=\"201104220312406619\" src=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/201104220312406619-600x389.jpg\" alt=\"\" width=\"494\" height=\"319\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2087\" title=\"201104220312499559\" src=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/201104220312499559.jpg\" alt=\"\" width=\"500\" height=\"353\" srcset=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/201104220312499559.jpg 500w, http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/201104220312499559-480x339.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 500px, 100vw\" \/><\/p>\n<p>.<\/p>\n<p><iframe loading=\"lazy\" title=\"Africa Aids Ad - Old man.avi\" width=\"1080\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/9sC7q1OWo2I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><br \/>\n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2084\" title=\"SNCFbikers.preview\" src=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/SNCFbikers.preview.jpg\" alt=\"\" width=\"590\" height=\"384\" srcset=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/SNCFbikers.preview.jpg 590w, http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/SNCFbikers.preview-480x312.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 590px, 100vw\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2085\" title=\"SNCFhitchhiker.preview\" src=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/SNCFhitchhiker.preview.jpg\" alt=\"\" width=\"590\" height=\"384\" srcset=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/SNCFhitchhiker.preview.jpg 590w, http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/SNCFhitchhiker.preview-480x312.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 590px, 100vw\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2086\" title=\"SNCFlady.preview\" src=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/SNCFlady.preview.jpg\" alt=\"\" width=\"590\" height=\"384\" srcset=\"http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/SNCFlady.preview.jpg 590w, http:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/SNCFlady.preview-480x312.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 590px, 100vw\" \/><br \/>\n<iframe loading=\"lazy\" title=\"sncf tgv\" width=\"1080\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/jvsW8PQ_Osk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><br \/>\nhttp:\/\/youtu.be\/ckMdAhmSA0Y<br \/>\n<iframe loading=\"lazy\" title=\"hollywood sphere\" width=\"1080\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/DZB7GeeBcHA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><br \/>\n<iframe loading=\"lazy\" title=\"Pub TV LA Redoute\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/my2vArU2ZMg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><br \/>\n<iframe loading=\"lazy\" title=\"AIDES - &quot;A Life&quot;\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/UYWfEf2Dlbs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><span style=\"color: #5cc5ed;\"><br \/>\nTu fais quelques chose en parall\u00e8le de ton m\u00e9tier, une passion ?<\/span><br \/>\nDes voyages, un jardin, \u00e9lever des enfants, de la photo, mon homme et mes amis.<\/p>\n<p><span style=\"color: #5cc5ed;\">Dans ton m\u00e9tier quel est ton meilleur souvenir ?<\/span><br \/>\nUn film pour AIDES  projet\u00e9 dans le grand Audi de Cannes, qui est applaudi par les meilleurs publicitaires du monde lors de la remise des Lions.<br \/>\nUn tournage dans un d\u00e9sert de Namibie&#8230;<\/p>\n<p><span style=\"color: #5cc5ed;\">et le pire ?<\/span><br \/>\nLes p\u00e9riodes o\u00f9 l\u2019on ne sort rien, et il y en a quelques unes dans ce m\u00e9tier.<\/p>\n<p><span style=\"color: #5cc5ed;\">le truc qui t&rsquo;a fait le plus halluciner ?<\/span><br \/>\nUne semaine \u00e0 New York pour filmer un traveling dans une salade de thon&#8230;<\/p>\n<p><span style=\"color: #5cc5ed;\">ce que tu pensais pas faire un jour ?<\/span><br \/>\nTravailler pour de la cosm\u00e9to.<\/p>\n<p><span style=\"color: #5cc5ed;\">Quelle est, historiquement, la pub qui t&rsquo;as le plus marqu\u00e9e. <\/span><br \/>\nPlusieurs. Le film Dunlop de Tony Kay, la s\u00e9rie de films Honda, Guinness, le projet HBO voyeurisme&#8230;<\/p>\n<p><iframe loading=\"lazy\" title=\"Dunlop - Tested For The Unexpected\" width=\"1080\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/NLWWtgqDG2M?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"Honda - The Cog\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/_ve4M4UsJQo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><br \/>\n<iframe loading=\"lazy\" title=\"Honda Impossible Dream\" width=\"1080\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/fB_1gPRCLCo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"Guinness Surfer Ad (with Horses) 1998\" width=\"1080\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/Y9znA_dwjHw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><br \/>\n<iframe loading=\"lazy\" title=\"Guinness Swimmer Ad\" width=\"1080\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/6qTdam2g06U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"HBO Voyeur Project\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/EwkQpzgFaqs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><span style=\"color: #5cc5ed;\">Celle que tu aurais aim\u00e9 faire ?<\/span><br \/>\nDes tonnes&#8230;<\/p>\n<p><span style=\"color: #5cc5ed;\">Tu as des mod\u00e8les de cr\u00e9as dans la publicit\u00e9 ? des gens qui t&rsquo;inspire ? Pourquoi ?<\/span><br \/>\nOui \u00e9videmment, Mon ancien directeur de cr\u00e9ation Erik Vervroegen, un talent et un sens de la cr\u00e9ation exceptionnelle, <a title=\"Jorge Carre\u00f1o\" href=\"http:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/jorge-carreno\/\" target=\"_blank\">Jorge Carre\u00f1o<\/a> pour son travail de D.A, Remi Babinet pour l\u2019intelligence et la classe qu\u2019il met dans ce m\u00e9tier, des agences comme BBDO New York, Crispin, etc.<\/p>\n<p><span style=\"color: #5cc5ed;\">Si tu commen\u00e7ais la pub aujourd&rsquo;hui, tu irais ou ?<\/span><br \/>\nChez les pirates :<a href=\"http:\/\/fredfarid.com\/\" target=\"_blank\"> Fred et Farid<\/a>.<\/p>\n<p><span style=\"color: #5cc5ed;\">Avec qui aimerais tu travailler (cr\u00e9as r\u00e9al photographes illustrateurs&#8230;) ?<\/span><br \/>\nDes grands r\u00e9alisateurs comme <a href=\"http:\/\/theinspirationroom.com\/daily\/2004\/film-director-jonathan-glazer\/\" target=\"_blank\">Glazer<\/a>, <a href=\"http:\/\/www.youtube.com\/watch?v=uhmfWo5UKiQ\" target=\"_blank\">Kleinman<\/a> et d&rsquo;autres, des grands graphistes.  Ce que j&rsquo;aime avant tout dans ce m\u00e9tier, ce sont les rencontres et le potentiel parfois inattendu qu&rsquo;elles rec\u00e8lent. Des talents divers et vari\u00e9s qui t&rsquo;inspirent, t&#8217;emm\u00e8nent plus loin en exigeant toujours plus de toi. C&rsquo;est d&rsquo;ailleurs la fonction principale d&rsquo;un bon directeur de cr\u00e9ation.<\/p>\n<p><span style=\"color: #5cc5ed;\">Tu vois quoi comme changements entre tes d\u00e9buts et maintenant ?<\/span><br \/>\nLa r\u00e9volution Internet et les logiciels pour travailler. C&rsquo;est g\u00e9nial, tout est plus rapide et nous avons maintenant une libert\u00e9 de travail, d&rsquo;inspiration gigantesque. Quand j&rsquo;ai commenc\u00e9, il fallait 2 jours pour faire une pauvre maquette. En fait plus je travaille plus je m&rsquo;\u00e9clate, maintenant il faut les sujets\u2026<\/p>\n<p><span style=\"color: #5cc5ed;\">Tu penses que le milieu va \u00e9voluer de quelle mani\u00e8re ?<\/span><br \/>\nPeu m&rsquo;importe du moment que le talent reste la valeur clef !<\/p>\n<p><span style=\"color: #5cc5ed;\">Que dirais tu a un team de stagiaire qui veut percer dans le milieu publicitaire ?<\/span><br \/>\nBosse, nourris toi, amuse toi mais surtout ne pollue pas avec des campagnes mauvaises ou laides.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour Marianne, tu es Directrice Artistique chez TBWA, tu as eu quel parcours ? Apr\u00e8s des \u00e9tudes pas tr\u00e8s bonnes (redoubl\u00e9e 2 fois) je suis rentr\u00e9e apr\u00e8s la 3\u00e8me \u00e0 Olivier de Serres (ENSAAMA). Apr\u00e8s 3 ans j\u2019ai fait les Arts D\u00e9co \u00e0 Paris (ENSAD). Professionnellement Je n\u2019ai fait que 2 agences&#8230; &lsquo;Alice&rsquo; puis TBWA [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2082,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_uag_custom_page_level_css":"","footnotes":""},"categories":[5,12],"tags":[],"class_list":["post-76","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-directeurs-artistiques","category-tbwa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marianne Fonferrier &#8226; C&#039;est qui les Cr\u00e9as ?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/marianne-fonferrier\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marianne Fonferrier &#8226; C&#039;est qui les Cr\u00e9as ?\" \/>\n<meta property=\"og:description\" content=\"Bonjour Marianne, tu es Directrice Artistique chez TBWA, tu as eu quel parcours ? Apr\u00e8s des \u00e9tudes pas tr\u00e8s bonnes (redoubl\u00e9e 2 fois) je suis rentr\u00e9e apr\u00e8s la 3\u00e8me \u00e0 Olivier de Serres (ENSAAMA). Apr\u00e8s 3 ans j\u2019ai fait les Arts D\u00e9co \u00e0 Paris (ENSAD). Professionnellement Je n\u2019ai fait que 2 agences&#8230; &lsquo;Alice&rsquo; puis TBWA [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/marianne-fonferrier\/\" \/>\n<meta property=\"og:site_name\" content=\"C&#039;est qui les Cr\u00e9as ?\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CestquilesCreas\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-11-21T01:56:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-11-22T18:59:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"441\" \/>\n\t<meta property=\"og:image:height\" content=\"441\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gregory ferembach\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"gregory ferembach\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/marianne-fonferrier\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/marianne-fonferrier\\\/\"},\"author\":{\"name\":\"gregory ferembach\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/person\\\/228b651374249a02f20a1921f0e2516b\"},\"headline\":\"Marianne Fonferrier\",\"datePublished\":\"2011-11-21T01:56:48+00:00\",\"dateModified\":\"2011-11-22T18:59:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/marianne-fonferrier\\\/\"},\"wordCount\":862,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/marianne-fonferrier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/fonferrier.jpg\",\"articleSection\":[\".Directeur Artistique\",\"TBWA\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/marianne-fonferrier\\\/\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/marianne-fonferrier\\\/\",\"name\":\"Marianne Fonferrier &#8226; C&#039;est qui les Cr\u00e9as ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/marianne-fonferrier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/marianne-fonferrier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/fonferrier.jpg\",\"datePublished\":\"2011-11-21T01:56:48+00:00\",\"dateModified\":\"2011-11-22T18:59:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/marianne-fonferrier\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/marianne-fonferrier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/marianne-fonferrier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/fonferrier.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/fonferrier.jpg\",\"width\":441,\"height\":441},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/directeurs-artistiques\\\/marianne-fonferrier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marianne Fonferrier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#website\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\",\"name\":\"C'est qui les Cr\u00e9as ?\",\"description\":\"D\u00e9couvrez les cr\u00e9atifs, leurs parcours et leurs (en)vies...\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\",\"name\":\"C'est qui les Cr\u00e9as ?\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-cqlc-1024x368-3.png\",\"contentUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-cqlc-1024x368-3.png\",\"width\":1024,\"height\":368,\"caption\":\"C'est qui les Cr\u00e9as ?\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CestquilesCreas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/person\\\/228b651374249a02f20a1921f0e2516b\",\"name\":\"gregory ferembach\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"caption\":\"gregory ferembach\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marianne Fonferrier &#8226; C&#039;est qui les Cr\u00e9as ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/marianne-fonferrier\/","og_locale":"fr_FR","og_type":"article","og_title":"Marianne Fonferrier &#8226; C&#039;est qui les Cr\u00e9as ?","og_description":"Bonjour Marianne, tu es Directrice Artistique chez TBWA, tu as eu quel parcours ? Apr\u00e8s des \u00e9tudes pas tr\u00e8s bonnes (redoubl\u00e9e 2 fois) je suis rentr\u00e9e apr\u00e8s la 3\u00e8me \u00e0 Olivier de Serres (ENSAAMA). Apr\u00e8s 3 ans j\u2019ai fait les Arts D\u00e9co \u00e0 Paris (ENSAD). Professionnellement Je n\u2019ai fait que 2 agences&#8230; &lsquo;Alice&rsquo; puis TBWA [&hellip;]","og_url":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/marianne-fonferrier\/","og_site_name":"C&#039;est qui les Cr\u00e9as ?","article_publisher":"https:\/\/www.facebook.com\/CestquilesCreas\/","article_published_time":"2011-11-21T01:56:48+00:00","article_modified_time":"2011-11-22T18:59:07+00:00","og_image":[{"width":441,"height":441,"url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier.jpg","type":"image\/jpeg"}],"author":"gregory ferembach","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"gregory ferembach","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/marianne-fonferrier\/#article","isPartOf":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/marianne-fonferrier\/"},"author":{"name":"gregory ferembach","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/person\/228b651374249a02f20a1921f0e2516b"},"headline":"Marianne Fonferrier","datePublished":"2011-11-21T01:56:48+00:00","dateModified":"2011-11-22T18:59:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/marianne-fonferrier\/"},"wordCount":862,"commentCount":4,"publisher":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/marianne-fonferrier\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier.jpg","articleSection":[".Directeur Artistique","TBWA"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/marianne-fonferrier\/","url":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/marianne-fonferrier\/","name":"Marianne Fonferrier &#8226; C&#039;est qui les Cr\u00e9as ?","isPartOf":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/marianne-fonferrier\/#primaryimage"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/marianne-fonferrier\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier.jpg","datePublished":"2011-11-21T01:56:48+00:00","dateModified":"2011-11-22T18:59:07+00:00","breadcrumb":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/marianne-fonferrier\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/marianne-fonferrier\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/marianne-fonferrier\/#primaryimage","url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier.jpg","contentUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier.jpg","width":441,"height":441},{"@type":"BreadcrumbList","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/directeurs-artistiques\/marianne-fonferrier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ferembach.com\/cestquilescreas\/"},{"@type":"ListItem","position":2,"name":"Marianne Fonferrier"}]},{"@type":"WebSite","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#website","url":"https:\/\/www.ferembach.com\/cestquilescreas\/","name":"C'est qui les Cr\u00e9as ?","description":"D\u00e9couvrez les cr\u00e9atifs, leurs parcours et leurs (en)vies...","publisher":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ferembach.com\/cestquilescreas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization","name":"C'est qui les Cr\u00e9as ?","url":"https:\/\/www.ferembach.com\/cestquilescreas\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/logo\/image\/","url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2020\/02\/logo-cqlc-1024x368-3.png","contentUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2020\/02\/logo-cqlc-1024x368-3.png","width":1024,"height":368,"caption":"C'est qui les Cr\u00e9as ?"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CestquilesCreas\/"]},{"@type":"Person","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/person\/228b651374249a02f20a1921f0e2516b","name":"gregory ferembach","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","caption":"gregory ferembach"}}]}},"uagb_featured_image_src":{"full":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier.jpg",441,441,false],"thumbnail":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier-120x120.jpg",120,120,true],"medium":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier-60x60.jpg",60,60,true],"medium_large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier.jpg",441,441,false],"large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier.jpg",441,441,false],"1536x1536":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier.jpg",441,441,false],"2048x2048":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier.jpg",441,441,false],"et-pb-post-main-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier-400x250.jpg",400,250,true],"et-pb-post-main-image-fullwidth":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier.jpg",441,441,false],"et-pb-portfolio-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier-400x284.jpg",400,284,true],"et-pb-portfolio-module-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier-441x382.jpg",441,382,true],"et-pb-portfolio-image-single":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier.jpg",441,441,false],"et-pb-gallery-module-image-portrait":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier-400x441.jpg",400,441,true],"et-pb-post-main-image-fullwidth-large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier.jpg",441,441,false],"et-pb-image--responsive--desktop":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier.jpg",441,441,false],"et-pb-image--responsive--tablet":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier.jpg",441,441,false],"et-pb-image--responsive--phone":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2011\/05\/fonferrier.jpg",270,270,false]},"uagb_author_info":{"display_name":"gregory ferembach","author_link":"https:\/\/www.ferembach.com\/cestquilescreas\/author\/gregoryferembach\/"},"uagb_comment_info":4,"uagb_excerpt":"Bonjour Marianne, tu es Directrice Artistique chez TBWA, tu as eu quel parcours ? Apr\u00e8s des \u00e9tudes pas tr\u00e8s bonnes (redoubl\u00e9e 2 fois) je suis rentr\u00e9e apr\u00e8s la 3\u00e8me \u00e0 Olivier de Serres (ENSAAMA). Apr\u00e8s 3 ans j\u2019ai fait les Arts D\u00e9co \u00e0 Paris (ENSAD). Professionnellement Je n\u2019ai fait que 2 agences&#8230; &lsquo;Alice&rsquo; puis TBWA\u2026","_links":{"self":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts\/76","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/comments?post=76"}],"version-history":[{"count":0,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts\/76\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/media\/2082"}],"wp:attachment":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/media?parent=76"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/categories?post=76"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/tags?post=76"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}