{"id":8581,"date":"2021-01-12T18:13:00","date_gmt":"2021-01-12T16:13:00","guid":{"rendered":"https:\/\/www.ferembach.com\/cestquilescreas\/?p=8581"},"modified":"2021-01-13T15:13:31","modified_gmt":"2021-01-13T13:13:31","slug":"paris-new-york","status":"publish","type":"post","link":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/","title":{"rendered":"Paris &#x2708;&#xfe0f; New York"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">D\u00e9couvrez comment se passe la pub dans diff\u00e9rentes villes du monde, salaires, agences, loyers, cultures, etc. Nous parlons de tout avec des cr\u00e9atifs de partout. <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-texas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Austin<\/a> \/ <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/team\/paris-amsterdam\/\" target=\"_blank\" rel=\"noreferrer noopener\">Amsterdam<\/a> \/ <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/directrice-artistique\/paris-bruxelles\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bruxelles<\/a> \/ <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/directeur-de-creation\/paris-hambourg\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hambourg<\/a> \/ <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-bangkok\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bangkok<\/a> \/ <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-%e2%9c%88%ef%b8%8f-milan\/\" target=\"_blank\" rel=\"noreferrer noopener\">Milan<\/a> \/ <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-%e2%9c%88%ef%b8%8f-madrid\/\" target=\"_blank\" rel=\"noreferrer noopener\">Madrid<\/a> \/ <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-londres\/\" target=\"_blank\" rel=\"noreferrer noopener\">Londres<\/a> \/<a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/\" target=\"_blank\" rel=\"noreferrer noopener\"> New York <\/a>\/ <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-montreal\/\" target=\"_blank\" rel=\"noreferrer noopener\">Montr\u00e9al<\/a> \/ <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-buenos-aires\/\" target=\"_blank\" rel=\"noreferrer noopener\">Buenos Aires<\/a> \/ <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/\" target=\"_blank\" rel=\"noreferrer noopener\">Duba\u00ef<\/a><\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_SEYMvf4Csuw\"><div id=\"lyte_SEYMvf4Csuw\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FSEYMvf4Csuw%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/SEYMvf4Csuw\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FSEYMvf4Csuw%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">Pour se balader dans la vid\u00e9o (Merci Am\u00e9lie) <a href=\"https:\/\/www.youtube.com\/watch?v=SEYMvf4Csuw&amp;t=1s\">00:01<\/a> &#8211; Gabrielle Attia, pr\u00e9sentations <a href=\"https:\/\/www.youtube.com\/watch?v=SEYMvf4Csuw&amp;t=230s\">03:50<\/a> &#8211; BBDO face au coronavirus <a href=\"https:\/\/www.youtube.com\/watch?v=SEYMvf4Csuw&amp;t=585s\">09:45<\/a> &#8211; Et les autres agences ? <a href=\"https:\/\/www.youtube.com\/watch?v=SEYMvf4Csuw&amp;t=725s\">12:05<\/a> &#8211; Pourquoi les Etats Unis ? <a href=\"https:\/\/www.youtube.com\/watch?v=SEYMvf4Csuw&amp;t=940s\">15:40<\/a> &#8211; Les \u201cHeadhunters\u201d <a href=\"https:\/\/www.youtube.com\/watch?v=SEYMvf4Csuw&amp;t=1020s\">17:00<\/a> &#8211; Les salaires <a href=\"https:\/\/www.youtube.com\/watch?v=SEYMvf4Csuw&amp;t=1140s\">19:00<\/a> &#8211; Co\u00fbts de la vie aux Etats Unis <a href=\"https:\/\/www.youtube.com\/watch?v=SEYMvf4Csuw&amp;t=1463s\">24:23<\/a> &#8211; Le Visa O-1 <a href=\"https:\/\/www.youtube.com\/watch?v=SEYMvf4Csuw&amp;t=1625s\">27:05<\/a> &#8211; Etre junior aux Etats-unis (\u00e9cole, salaires,&#8230;) <a href=\"https:\/\/www.youtube.com\/watch?v=SEYMvf4Csuw&amp;t=1751s\">29:11<\/a> &#8211; Une team de DA fran\u00e7aises aux Etats Unis <a href=\"https:\/\/www.youtube.com\/watch?v=SEYMvf4Csuw&amp;t=2028s\">33:48<\/a> &#8211; Challenge cr\u00e9atif et relation client <a href=\"https:\/\/www.youtube.com\/watch?v=SEYMvf4Csuw&amp;t=2164s\">36:04<\/a> &#8211; \u00catre une femme publicitaire aux Etats-Unis <a href=\"https:\/\/www.youtube.com\/watch?v=SEYMvf4Csuw&amp;t=2518s\">41:58<\/a> &#8211; Rythme et volume de travail <a href=\"https:\/\/www.youtube.com\/watch?v=SEYMvf4Csuw&amp;t=3041s\">50:41<\/a> &#8211; Part du march\u00e9 pub aux Etats-Unis <a href=\"https:\/\/www.youtube.com\/watch?v=SEYMvf4Csuw&amp;t=3725s\">01:02:05<\/a> &#8211; Quel choix d\u2019agence ? <a href=\"https:\/\/www.youtube.com\/watch?v=SEYMvf4Csuw&amp;t=4308s\">01:11:48<\/a> &#8211; La ma\u00eetrise de l\u2019anglais<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.linkedin.com\/in\/gabrielleattia\/\" target=\"_blank\" rel=\"noreferrer noopener\"><br>Le profil linkedin de Gabrielle Attia<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>GABRIELLE ATTIA nous parle de New York et de ses salaires, agences, loyers, cultures\u2026<\/p>\n","protected":false},"author":4,"featured_media":8587,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_uag_custom_page_level_css":"","footnotes":""},"categories":[44,88,75],"tags":[],"class_list":["post-8581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-creatif","category-directrice-de-creation","category-redactrice"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paris &#x2708;&#xfe0f; New York &#8226; C&#039;est qui les Cr\u00e9as ?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paris &#x2708;&#xfe0f; New York &#8226; C&#039;est qui les Cr\u00e9as ?\" \/>\n<meta property=\"og:description\" content=\"GABRIELLE ATTIA nous parle de New York et de ses salaires, agences, loyers, cultures\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/\" \/>\n<meta property=\"og:site_name\" content=\"C&#039;est qui les Cr\u00e9as ?\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CestquilesCreas\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-12T16:13:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-13T13:13:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle.png\" \/>\n\t<meta property=\"og:image:width\" content=\"930\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"gregory ferembach\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"gregory ferembach\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-new-york\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-new-york\\\/\"},\"author\":{\"name\":\"gregory ferembach\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/person\\\/228b651374249a02f20a1921f0e2516b\"},\"headline\":\"Paris &#x2708;&#xfe0f; New York\",\"datePublished\":\"2021-01-12T16:13:00+00:00\",\"dateModified\":\"2021-01-13T13:13:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-new-york\\\/\"},\"wordCount\":165,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-new-york\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/gabrielle.png\",\"articleSection\":[\".cr\u00e9atif\",\".Directrice de cr\u00e9ation\",\".R\u00e9dactrice\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-new-york\\\/\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-new-york\\\/\",\"name\":\"Paris &#x2708;&#xfe0f; New York &#8226; C&#039;est qui les Cr\u00e9as ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-new-york\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-new-york\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/gabrielle.png\",\"datePublished\":\"2021-01-12T16:13:00+00:00\",\"dateModified\":\"2021-01-13T13:13:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-new-york\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-new-york\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-new-york\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/gabrielle.png\",\"contentUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/gabrielle.png\",\"width\":930,\"height\":530},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-new-york\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paris &#x2708;&#xfe0f; New York\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#website\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\",\"name\":\"C'est qui les Cr\u00e9as ?\",\"description\":\"D\u00e9couvrez les cr\u00e9atifs, leurs parcours et leurs (en)vies...\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\",\"name\":\"C'est qui les Cr\u00e9as ?\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-cqlc-1024x368-3.png\",\"contentUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-cqlc-1024x368-3.png\",\"width\":1024,\"height\":368,\"caption\":\"C'est qui les Cr\u00e9as ?\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CestquilesCreas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/person\\\/228b651374249a02f20a1921f0e2516b\",\"name\":\"gregory ferembach\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"caption\":\"gregory ferembach\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paris &#x2708;&#xfe0f; New York &#8226; C&#039;est qui les Cr\u00e9as ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/","og_locale":"fr_FR","og_type":"article","og_title":"Paris &#x2708;&#xfe0f; New York &#8226; C&#039;est qui les Cr\u00e9as ?","og_description":"GABRIELLE ATTIA nous parle de New York et de ses salaires, agences, loyers, cultures\u2026","og_url":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/","og_site_name":"C&#039;est qui les Cr\u00e9as ?","article_publisher":"https:\/\/www.facebook.com\/CestquilesCreas\/","article_published_time":"2021-01-12T16:13:00+00:00","article_modified_time":"2021-01-13T13:13:31+00:00","og_image":[{"width":930,"height":530,"url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle.png","type":"image\/png"}],"author":"gregory ferembach","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"gregory ferembach","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/#article","isPartOf":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/"},"author":{"name":"gregory ferembach","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/person\/228b651374249a02f20a1921f0e2516b"},"headline":"Paris &#x2708;&#xfe0f; New York","datePublished":"2021-01-12T16:13:00+00:00","dateModified":"2021-01-13T13:13:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/"},"wordCount":165,"publisher":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle.png","articleSection":[".cr\u00e9atif",".Directrice de cr\u00e9ation",".R\u00e9dactrice"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/","url":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/","name":"Paris &#x2708;&#xfe0f; New York &#8226; C&#039;est qui les Cr\u00e9as ?","isPartOf":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/#primaryimage"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle.png","datePublished":"2021-01-12T16:13:00+00:00","dateModified":"2021-01-13T13:13:31+00:00","breadcrumb":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/#primaryimage","url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle.png","contentUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle.png","width":930,"height":530},{"@type":"BreadcrumbList","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ferembach.com\/cestquilescreas\/"},{"@type":"ListItem","position":2,"name":"Paris &#x2708;&#xfe0f; New York"}]},{"@type":"WebSite","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#website","url":"https:\/\/www.ferembach.com\/cestquilescreas\/","name":"C'est qui les Cr\u00e9as ?","description":"D\u00e9couvrez les cr\u00e9atifs, leurs parcours et leurs (en)vies...","publisher":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ferembach.com\/cestquilescreas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization","name":"C'est qui les Cr\u00e9as ?","url":"https:\/\/www.ferembach.com\/cestquilescreas\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/logo\/image\/","url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2020\/02\/logo-cqlc-1024x368-3.png","contentUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2020\/02\/logo-cqlc-1024x368-3.png","width":1024,"height":368,"caption":"C'est qui les Cr\u00e9as ?"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CestquilesCreas\/"]},{"@type":"Person","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/person\/228b651374249a02f20a1921f0e2516b","name":"gregory ferembach","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","caption":"gregory ferembach"}}]}},"uagb_featured_image_src":{"full":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle.png",930,530,false],"thumbnail":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle-120x120.png",120,120,true],"medium":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle-60x34.png",60,34,true],"medium_large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle-768x438.png",768,438,true],"large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle.png",930,530,false],"1536x1536":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle.png",930,530,false],"2048x2048":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle.png",930,530,false],"et-pb-post-main-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle-400x250.png",400,250,true],"et-pb-post-main-image-fullwidth":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle.png",930,530,false],"et-pb-portfolio-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle-400x284.png",400,284,true],"et-pb-portfolio-module-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle-510x382.png",510,382,true],"et-pb-portfolio-image-single":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle.png",930,530,false],"et-pb-gallery-module-image-portrait":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle-400x516.png",400,516,true],"et-pb-post-main-image-fullwidth-large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle.png",930,530,false],"et-pb-image--responsive--desktop":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle.png",930,530,false],"et-pb-image--responsive--tablet":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle.png",930,530,false],"et-pb-image--responsive--phone":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/01\/gabrielle-480x274.png",473,270,true]},"uagb_author_info":{"display_name":"gregory ferembach","author_link":"https:\/\/www.ferembach.com\/cestquilescreas\/author\/gregoryferembach\/"},"uagb_comment_info":0,"uagb_excerpt":"GABRIELLE ATTIA nous parle de New York et de ses salaires, agences, loyers, cultures\u2026","_links":{"self":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts\/8581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/comments?post=8581"}],"version-history":[{"count":0,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts\/8581\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/media\/8587"}],"wp:attachment":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/media?parent=8581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/categories?post=8581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/tags?post=8581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}