{"id":8623,"date":"2021-02-05T10:38:33","date_gmt":"2021-02-05T08:38:33","guid":{"rendered":"https:\/\/www.ferembach.com\/cestquilescreas\/?p=8623"},"modified":"2025-09-23T14:08:02","modified_gmt":"2025-09-23T12:08:02","slug":"paris-singapour","status":"publish","type":"post","link":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-singapour\/","title":{"rendered":"Paris &#x2708;&#xfe0f; Singapour"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">D\u00e9couvrez comment se passe la pub dans diff\u00e9rentes villes du monde, salaires, agences, loyers, cultures, etc. Nous parlons de tout avec des cr\u00e9atifs de partout. <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-texas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Austin<\/a> \/ <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/team\/paris-amsterdam\/\" target=\"_blank\" rel=\"noreferrer noopener\">Amsterdam<\/a> \/ <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/directrice-artistique\/paris-bruxelles\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bruxelles<\/a> \/ <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/directeur-de-creation\/paris-hambourg\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hambourg<\/a> \/ <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-bangkok\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bangkok<\/a> \/ <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-%e2%9c%88%ef%b8%8f-milan\/\" target=\"_blank\" rel=\"noreferrer noopener\">Milan<\/a> \/ <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-%e2%9c%88%ef%b8%8f-madrid\/\" target=\"_blank\" rel=\"noreferrer noopener\">Madrid<\/a> \/ <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-londres\/\" target=\"_blank\" rel=\"noreferrer noopener\">Londres<\/a> \/<a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/\" target=\"_blank\" rel=\"noreferrer noopener\"> New York <\/a>\/ <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-montreal\/\" target=\"_blank\" rel=\"noreferrer noopener\">Montr\u00e9al<\/a> \/ <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-buenos-aires\/\" target=\"_blank\" rel=\"noreferrer noopener\">Buenos Aires<\/a> \/ <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-new-york\/\" target=\"_blank\" rel=\"noreferrer noopener\">Duba\u00ef<\/a><\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_T62UPGLPmmU\"><div id=\"lyte_T62UPGLPmmU\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FT62UPGLPmmU%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/T62UPGLPmmU\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FT62UPGLPmmU%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.linkedin.com\/in\/jocelyn-chabanis-b1a43b4b\/?originalSubdomain=sg\" target=\"_blank\" rel=\"noreferrer noopener\"><a href=\"https:\/\/www.linkedin.com\/in\/jocelyn-chabanis-b1a43b4b\/?originalSubdomain=sg\" target=\"_blank\" rel=\"noreferrer noopener\">Profil linkedin de Jocelyn Chabanis<\/a><\/a><\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>JOCELYN CHABANIS nous parle de Singapour et de ses salaires, agences, loyers, cultures\u2026<\/p>\n","protected":false},"author":4,"featured_media":8625,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_uag_custom_page_level_css":"","footnotes":""},"categories":[44,115],"tags":[],"class_list":["post-8623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-creatif","category-inter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paris &#x2708;&#xfe0f; Singapour &#8226; C&#039;est qui les Cr\u00e9as ?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-singapour\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paris &#x2708;&#xfe0f; Singapour &#8226; C&#039;est qui les Cr\u00e9as ?\" \/>\n<meta property=\"og:description\" content=\"JOCELYN CHABANIS nous parle de Singapour et de ses salaires, agences, loyers, cultures\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-singapour\/\" \/>\n<meta property=\"og:site_name\" content=\"C&#039;est qui les Cr\u00e9as ?\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CestquilesCreas\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-05T08:38:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-23T12:08:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"379\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"gregory ferembach\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"gregory ferembach\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-singapour\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-singapour\\\/\"},\"author\":{\"name\":\"gregory ferembach\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/person\\\/228b651374249a02f20a1921f0e2516b\"},\"headline\":\"Paris &#x2708;&#xfe0f; Singapour\",\"datePublished\":\"2021-02-05T08:38:33+00:00\",\"dateModified\":\"2025-09-23T12:08:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-singapour\\\/\"},\"wordCount\":61,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-singapour\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/jocelyn.png\",\"articleSection\":[\".cr\u00e9atif\",\"inter\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-singapour\\\/\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-singapour\\\/\",\"name\":\"Paris &#x2708;&#xfe0f; Singapour &#8226; C&#039;est qui les Cr\u00e9as ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-singapour\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-singapour\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/jocelyn.png\",\"datePublished\":\"2021-02-05T08:38:33+00:00\",\"dateModified\":\"2025-09-23T12:08:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-singapour\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-singapour\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-singapour\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/jocelyn.png\",\"contentUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/jocelyn.png\",\"width\":700,\"height\":379},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/paris-singapour\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paris &#x2708;&#xfe0f; Singapour\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#website\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\",\"name\":\"C'est qui les Cr\u00e9as ?\",\"description\":\"D\u00e9couvrez les cr\u00e9atifs, leurs parcours et leurs (en)vies...\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\",\"name\":\"C'est qui les Cr\u00e9as ?\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-cqlc-1024x368-3.png\",\"contentUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-cqlc-1024x368-3.png\",\"width\":1024,\"height\":368,\"caption\":\"C'est qui les Cr\u00e9as ?\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CestquilesCreas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/person\\\/228b651374249a02f20a1921f0e2516b\",\"name\":\"gregory ferembach\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"caption\":\"gregory ferembach\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paris &#x2708;&#xfe0f; Singapour &#8226; C&#039;est qui les Cr\u00e9as ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-singapour\/","og_locale":"fr_FR","og_type":"article","og_title":"Paris &#x2708;&#xfe0f; Singapour &#8226; C&#039;est qui les Cr\u00e9as ?","og_description":"JOCELYN CHABANIS nous parle de Singapour et de ses salaires, agences, loyers, cultures\u2026","og_url":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-singapour\/","og_site_name":"C&#039;est qui les Cr\u00e9as ?","article_publisher":"https:\/\/www.facebook.com\/CestquilesCreas\/","article_published_time":"2021-02-05T08:38:33+00:00","article_modified_time":"2025-09-23T12:08:02+00:00","og_image":[{"width":700,"height":379,"url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn.png","type":"image\/png"}],"author":"gregory ferembach","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"gregory ferembach","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-singapour\/#article","isPartOf":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-singapour\/"},"author":{"name":"gregory ferembach","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/person\/228b651374249a02f20a1921f0e2516b"},"headline":"Paris &#x2708;&#xfe0f; Singapour","datePublished":"2021-02-05T08:38:33+00:00","dateModified":"2025-09-23T12:08:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-singapour\/"},"wordCount":61,"publisher":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-singapour\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn.png","articleSection":[".cr\u00e9atif","inter"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-singapour\/","url":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-singapour\/","name":"Paris &#x2708;&#xfe0f; Singapour &#8226; C&#039;est qui les Cr\u00e9as ?","isPartOf":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-singapour\/#primaryimage"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-singapour\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn.png","datePublished":"2021-02-05T08:38:33+00:00","dateModified":"2025-09-23T12:08:02+00:00","breadcrumb":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-singapour\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-singapour\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-singapour\/#primaryimage","url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn.png","contentUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn.png","width":700,"height":379},{"@type":"BreadcrumbList","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/paris-singapour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ferembach.com\/cestquilescreas\/"},{"@type":"ListItem","position":2,"name":"Paris &#x2708;&#xfe0f; Singapour"}]},{"@type":"WebSite","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#website","url":"https:\/\/www.ferembach.com\/cestquilescreas\/","name":"C'est qui les Cr\u00e9as ?","description":"D\u00e9couvrez les cr\u00e9atifs, leurs parcours et leurs (en)vies...","publisher":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ferembach.com\/cestquilescreas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization","name":"C'est qui les Cr\u00e9as ?","url":"https:\/\/www.ferembach.com\/cestquilescreas\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/logo\/image\/","url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2020\/02\/logo-cqlc-1024x368-3.png","contentUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2020\/02\/logo-cqlc-1024x368-3.png","width":1024,"height":368,"caption":"C'est qui les Cr\u00e9as ?"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CestquilesCreas\/"]},{"@type":"Person","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/person\/228b651374249a02f20a1921f0e2516b","name":"gregory ferembach","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","caption":"gregory ferembach"}}]}},"uagb_featured_image_src":{"full":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn.png",700,379,false],"thumbnail":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn-120x120.png",120,120,true],"medium":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn-60x32.png",60,32,true],"medium_large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn.png",700,379,false],"large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn.png",700,379,false],"1536x1536":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn.png",700,379,false],"2048x2048":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn.png",700,379,false],"et-pb-post-main-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn-400x250.png",400,250,true],"et-pb-post-main-image-fullwidth":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn.png",700,379,false],"et-pb-portfolio-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn-400x284.png",400,284,true],"et-pb-portfolio-module-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn-510x379.png",510,379,true],"et-pb-portfolio-image-single":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn.png",700,379,false],"et-pb-gallery-module-image-portrait":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn-400x379.png",400,379,true],"et-pb-post-main-image-fullwidth-large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn.png",700,379,false],"et-pb-image--responsive--desktop":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn.png",700,379,false],"et-pb-image--responsive--tablet":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn.png",700,379,false],"et-pb-image--responsive--phone":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2021\/02\/jocelyn-480x260.png",480,260,true]},"uagb_author_info":{"display_name":"gregory ferembach","author_link":"https:\/\/www.ferembach.com\/cestquilescreas\/author\/gregoryferembach\/"},"uagb_comment_info":0,"uagb_excerpt":"JOCELYN CHABANIS nous parle de Singapour et de ses salaires, agences, loyers, cultures\u2026","_links":{"self":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts\/8623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/comments?post=8623"}],"version-history":[{"count":1,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts\/8623\/revisions"}],"predecessor-version":[{"id":11738,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts\/8623\/revisions\/11738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/media\/8625"}],"wp:attachment":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/media?parent=8623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/categories?post=8623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/tags?post=8623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}