{"id":9338,"date":"2023-01-26T22:03:39","date_gmt":"2023-01-26T20:03:39","guid":{"rendered":"https:\/\/www.ferembach.com\/cestquilescreas\/?p=9338"},"modified":"2023-01-27T11:49:06","modified_gmt":"2023-01-27T09:49:06","slug":"antoine-barth-benoit-jung","status":"publish","type":"post","link":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/antoine-barth-benoit-jung\/","title":{"rendered":"Antoine Barth et Benoit Jung"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"350\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung-1.jpg\" alt=\"\" class=\"wp-image-9400\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung-1.jpg 1000w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung-1-980x343.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung-1-480x168.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Vous \u00eates respectivement CR et DA chez Steve, vous venez d&rsquo;o\u00f9 ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Barth : <\/strong>J\u2019ai grandi dans les Yvelines \u00e0 l\u2019ouest de Paris. J\u2019ai fait toute ma scolarit\u00e9 dans ce coin-l\u00e0 except\u00e9 une ann\u00e9e de fin de coll\u00e8ge dans un internat horrible en Normandie. Mes parents avaient jug\u00e9 bon d\u2019un petit recadrage car je n\u2019\u00e9tais pas un tr\u00e8s grand fan de l\u2019\u00e9cole. Ce n\u2019est qu\u2019apr\u00e8s que j\u2019ai pu leur dire merci. C\u2019est ingrat les gosses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des parents aimants, une petite s\u0153ur aimante \u00e0 sa fa\u00e7on (keur), des copains, des copines, des amis. Je n\u2019ai jamais manqu\u00e9 de rien et j\u2019ai eu une enfance heureuse. Bravo et merci papa maman. Apr\u00e8s le bac, je suis directement all\u00e9 \u00e0 Sup De Pub et j&rsquo;y suis rest\u00e9 5 ans.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benoit : <\/strong>Je suis n\u00e9 et j\u2019ai grandi en banlieue parisienne dans une famille tr\u00e8s \u00e9loign\u00e9e de la cr\u00e9ation, de la publicit\u00e9 ou de l\u2019art. Quand ma m\u00e8re a remarqu\u00e9 que je passais des heures \u00e0 dessiner, elle a commenc\u00e9 \u00e0 m\u2019emmener r\u00e9guli\u00e8rement dans les mus\u00e9es parisiens. Et comme je n\u2019ai jamais cess\u00e9 de dessiner et que je n\u2019\u00e9tais pas si bon que \u00e7a en math, j\u2019ai convaincu mes parents et mes profs de m&rsquo;orienter vers un bac arts appliqu\u00e9s o\u00f9 j\u2019ai eu de bien meilleurs r\u00e9sultats. Apr\u00e8s le bac, je suis entr\u00e9 \u00e0 l\u2019ENSAMAA (ou Olivier de Serres pour les intimes) pour 2 ans. J\u2019ai profit\u00e9 \u00e0 fond de cette \u00e9cole en m\u2019inscrivant \u00e0 tous les ateliers suppl\u00e9mentaires (photo, sculpture&#8230;) en plus des cours, battant ainsi le record de pr\u00e9sence dans cette \u00e9cole.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u2019ai ensuite int\u00e9gr\u00e9 l\u2019ESDI pour passer un master et faire pas mal de stages, notamment chez Carr\u00e9 Noir, o\u00f9 j\u2019ai pu c\u00f4toyer B\u00e9atrice Mariotti et aussi Albert Boton et son cigare. Cette exp\u00e9rience explique ma petite obsession pour le graphisme, la typographie et le logotype et me vaut les titres tr\u00e8s officieux et bien moqueurs de \u00ab\u00a0head of picto\u201d et \u00ab\u00a0Head of mentions l\u00e9gales\u00a0\u00bb chez Steve.<br>Pendant ma derni\u00e8re ann\u00e9e d\u2019\u00e9tudes, je cherchais une alternance, j\u2019ai alors rencontr\u00e9 Gr\u00e9goire Soufflet (actuel Co-directeur de Steve) et Nancy Sospedra (DC chez Steve) qui venait de monter leur premi\u00e8re agence.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Tu as commenc\u00e9 quand la pub ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Barth : <\/strong>J\u2019ai fini mes \u00e9tudes en 2019. Donc \u00e7a fait \u00e0 peu pr\u00e8s 4 ans que je fais de la pub dont un petit break au Canada. Je suis parti \u00e0 Montr\u00e9al pour travailler dans les agences qu\u00e9b\u00e9coises, mais au moment o\u00f9 j&rsquo;ai atterri, les infos parlaient d\u2019un petit virus en Chine&#8230; 4 mois apr\u00e8s, j\u2019ai \u00e9t\u00e9 rapatri\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour l&rsquo;anecdote, c\u2019est ce cher Benoit qui m\u2019a recrut\u00e9 chez Steve pour \u00eatre son assistant DA (il me confiera plus tard que c\u2019\u00e9tait parce que j\u2019\u00e9tais le seul dispo). Et apr\u00e8s 3 mois de stage pass\u00e9s \u00e0 ses c\u00f4t\u00e9s, j\u2019ai voulu devenir CR. Oui, il m\u2019a traumatis\u00e9. Ou alors c\u2019est avec lui que j\u2019ai d\u00e9couvert que j\u2019avais une certaine app\u00e9tence pour la conception-r\u00e9daction. En plus, les CR avaient des Macbook, ce qui \u00e9tait bien plus pratique qu\u2019un iMac pour pouvoir bosser dans un canap\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benoit : <\/strong>C\u2019est une question pas si simple pour moi, parce que j\u2019ai longtemps \u00e9t\u00e9 touche-\u00e0-tout. J\u2019ai commenc\u00e9 en agence de communication il y a une vingtaine d\u2019ann\u00e9es. J\u2019ai eu des exp\u00e9riences tr\u00e8s vari\u00e9es, en agence ou, notamment, quand j\u2019\u00e9tais free. Du branding, du digital, de l\u2019UX, de l\u2019illustration, de la promo, de la sc\u00e9nographie et m\u00eame de l\u2019architecture&#8230; Alors, on peut dire que je fais de la pub \u00e0 temps plein depuis 7\/8 ans et que j\u2019en ai fait \u00e9pisodiquement avant. Et j\u2019en suis tr\u00e8s content, surtout que depuis le confinement, j\u2019ai aussi un Macbook, ainsi qu\u2019un \u00e9cran 24\u201d mais ce n&rsquo;est pas un concours.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>As-tu h\u00e9sit\u00e9 \u00e0 faire de la pub, tu aurais fait quoi \u00e0 la place ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Barth : <\/strong>Pas vraiment. Ma premi\u00e8re id\u00e9e de m\u00e9tier \u00e9tait dresseur de dinosaures. Les adultes ont vite bris\u00e9 mes r\u00eaves et l\u2019envie de faire de la pub est arriv\u00e9e assez vite. \u00c0 la base, je suis rentr\u00e9 en \u00e9cole de pub pour faire la musique dans la pub. Je faisais beaucoup de batterie et de percussions avec mon ami Fr\u00e9d\u00e9ric Prados qui est producteur et r\u00e9alisateur son chez Prodigious. Je trouvais son travail beaucoup trop cool. Mais apr\u00e8s mes 2 premi\u00e8res ann\u00e9es en BTS, j\u2019en ai appris un peu plus sur le m\u00e9tier de cr\u00e9atif et c\u2019est vers l\u00e0 que je me suis orient\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si aujourd&rsquo;hui je devais faire autre chose, \u00e7a serait quelque chose qui ne serait ni \u00e0 Paris, ni dans une grande ville. Je n\u2019aime pas la ville mais j\u2019aime la pub et l\u2019agence de pub. Je vis donc \u00e0 Paris par n\u00e9cessit\u00e9. D\u2019ailleurs, les planeurs de l\u2019agence me qualifient de \u201cgenzeder rural\u201d. J\u2019accepte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mon utopie : Une agence de pub dans un petit village. Aller, je prends aussi si c\u2019est une petite ville tranquille du moment que je peux habiter pas loin avec une maison et un jardin sans perdre 2h00 pour aller bosser. Alors oui, je pourrais faire du freelance depuis une long\u00e8re en Normandie ou \u00e0 Noirmoutier. Mais je suis pour le moment assez attach\u00e9 \u00e0 l\u2019\u00e9mulsion de l\u2019agence et au confort mental d\u2019un C.D.I. Et des petites coupures urbaines en TT, \u00e7a peut s\u2019organiser.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benoit : <\/strong>Vu ma r\u00e9ponse pr\u00e9c\u00e9dente, on peut dire que oui, j\u2019ai h\u00e9sit\u00e9. Ou plut\u00f4t j\u2019ai h\u00e9sit\u00e9 \u00e0 ne faire que de la pub. On peut exercer sa cr\u00e9ativit\u00e9 de plein de fa\u00e7ons diff\u00e9rentes. Cela dit, la publicit\u00e9 r\u00e9unit beaucoup de disciplines. On travaille avec des CR, des photographes, des r\u00e9alisateurs, des musiciens, des acteurs qui ont tous un talent immense. Pour un DA c\u2019est une exp\u00e9rience folle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si je n\u2019avais pas \u00e9t\u00e9 DA, je pense que je me serais int\u00e9ress\u00e9 \u00e0 un m\u00e9tier d\u2019artisanat, histoire de crafter des trucs quand m\u00eame. Ou peut-\u00eatre un m\u00e9tier en rapport avec l\u2019histoire de l\u2019art. Adolescent, j\u2019\u00e9tais fascin\u00e9 par l\u2019arch\u00e9ologie.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Tu travailles sur quels budgets, avec qui ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><br>Barth : <\/strong>Sur les diff\u00e9rents budgets de l\u2019agence et sur les comp\u00e8tes. Au programme<br>en ce moment : Evaneos, MayTea, Netto, Le Parc Ast\u00e9rix et un annonceur <em>new biz<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je n\u2019ai pas de budget attitr\u00e9 et j&rsquo;appr\u00e9cie \u00e9norm\u00e9ment cette fa\u00e7on de travailler. Une des raisons qui me fait aimer ce m\u00e9tier, c\u2019est la pluralit\u00e9 des sujets. Dior le matin, Justin Bridou l\u2019apr\u00e8m.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Souvent sous la direction de cr\u00e9ation de Guillaume Lartigue, parfois sous celle d\u2019Edouard Dorbais ou de Nancy Sosp\u00e9dra, et plus r\u00e9cemment sous celle d\u2019Emmanuel Courteau et <a href=\"https:\/\/www.ferembach.com\/cestquilescreas\/redacteur\/jean-francois-bouchet\/\">Jean-Fran\u00e7ois Bouchet <\/a>qui ont rejoint l&rsquo;agence il y a quelques mois. Ils sont \u00e9videmment tous beaux, forts, intelligents et cr\u00e9atifs (\u00e7a, c\u2019est pour mon salaire).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Concernant mon bin\u00f4me DA, je suis un CR volant comme on dit. Mais c\u2019est un sujet et nous \u0153uvrons en ce moment pour trouver mon \u00e2me s\u0153ur cr\u00e9ative. Je travaille donc pour le moment avec d\u2019autres DA volants de l\u2019agence en fonction des briefs. Avec Beno\u00eet, nous n\u2019avons pas une relation exclusive, mais nous aimons nous retrouver sur certains sujets et notamment sur Vision Du Monde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benoit : <\/strong>Je travaille principalement avec Edouard Dorbais (DC) sur les clients et le new biz de l\u2019agence. Au programme en ce moment : B for Bank et Zeplug.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">On vient de sortir Vision du Monde pour la seconde ann\u00e9e cons\u00e9cutive avec Barth (en vrai il s&rsquo;appelle Antoine et moi je l\u2019appelle Toinou comme sa maman) et Edouard Dorbais ainsi qu\u2019Emmanuel Courteau et Jean-Fran\u00e7ois Bouchet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R\u00e9cemment, j\u2019ai travaill\u00e9 avec Aymeric Druaux (CR) pour Marc Dorcel sous la direction de cr\u00e9ation de Jean-Fran\u00e7ois Bouchet et Emmanuel Courteau. Mais aussi avec Thomas Eliaou (CR) sur Flunch notamment. Barth et moi venons de prendre un brief Parc Asterix&#8230; bref il y a du taf. C\u2019est une gymnastique intellectuelle de travailler avec diff\u00e9rents CR et DC de l\u2019agence. Ils ont tous leurs fa\u00e7ons de r\u00e9fl\u00e9chir, leurs styles, leurs petites obsessions publicitaires. C\u2019est tr\u00e8s riche pour moi. Avec Barth, c\u2019est une relation un peu particuli\u00e8re, je l\u2019ai recrut\u00e9 et je l\u2019ai traumatis\u00e9 apparemment (alors que je suis sympa en vrai, surtout le lundi matin). J\u2019aime bien le retrouver sur des projets, on r\u00e9fl\u00e9chit facilement ensemble.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Tu peux citer quelques-unes de tes campagnes :<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Barth et Benoit :<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve2-1024x683.jpg\" alt=\"\" class=\"wp-image-9339\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve2-980x653.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve2-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"9341\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve3-1024x683.jpg\" alt=\"\" class=\"wp-image-9341\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve3-980x653.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve3-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"9340\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve1-1024x683.jpg\" alt=\"\" class=\"wp-image-9340\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve1-980x653.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve1-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_eQKXjigruyo\"><div id=\"lyte_eQKXjigruyo\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FeQKXjigruyo%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/eQKXjigruyo\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FeQKXjigruyo%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_lZP_SprhbDw\"><div id=\"lyte_lZP_SprhbDw\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FlZP_SprhbDw%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/lZP_SprhbDw\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FlZP_SprhbDw%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_xPwdviBuOAc\"><div id=\"lyte_xPwdviBuOAc\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FxPwdviBuOAc%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/xPwdviBuOAc\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FxPwdviBuOAc%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" data-id=\"9344\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve4-1024x681.jpg\" alt=\"\" class=\"wp-image-9344\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve4-980x651.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve4-480x319.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"680\" data-id=\"9345\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve5-1024x680.jpg\" alt=\"\" class=\"wp-image-9345\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve5-980x651.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve5-480x319.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" data-id=\"9342\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve6-1024x681.jpg\" alt=\"\" class=\"wp-image-9342\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve6-980x651.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve6-480x319.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"525\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve7-1024x525.jpg\" alt=\"\" class=\"wp-image-9343\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve7-980x503.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve7-480x246.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Barth : <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">avec Julie Greffier\u00a0<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_MavdyQ3uYlo\"><div id=\"lyte_MavdyQ3uYlo\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FMavdyQ3uYlo%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/MavdyQ3uYlo\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FMavdyQ3uYlo%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"653\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/aperowatch-presse-1024x653.jpg\" alt=\"\" class=\"wp-image-9408\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/aperowatch-presse-1024x653.jpg 1024w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/aperowatch-presse-980x625.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/aperowatch-presse-480x306.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La carte Swile lanc\u00e9e pendant le confinement ou tous les restaurants, boutiques, th\u00e9\u00e2tres, cin\u00e9mas, salles de sport et cie \u00e9taient ferm\u00e9s.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" data-id=\"9347\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/campagne-print-steve-jupdlc-1024x536.webp\" alt=\"\" class=\"wp-image-9347\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/campagne-print-steve-jupdlc-1024x536.webp 1024w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/campagne-print-steve-jupdlc-980x513.webp 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/campagne-print-steve-jupdlc-480x251.webp 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Javec Sandra Clua\u00a0<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL__3F1wcSjDkk\"><div id=\"lyte__3F1wcSjDkk\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2F_3F1wcSjDkk%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/_3F1wcSjDkk\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2F_3F1wcSjDkk%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benoit <\/strong>:<br>Avec Dany Huang et Lauren Hatton<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"753\" data-id=\"9349\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve11-1024x753.jpg\" alt=\"\" class=\"wp-image-9349\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve11-1024x753.jpg 1024w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve11-980x721.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve11-480x353.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"753\" data-id=\"9350\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve9-1024x753.jpg\" alt=\"\" class=\"wp-image-9350\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve9-1024x753.jpg 1024w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve9-980x721.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve9-480x353.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"753\" data-id=\"9348\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve10-1024x753.jpg\" alt=\"\" class=\"wp-image-9348\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve10-1024x753.jpg 1024w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve10-980x721.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve10-480x353.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"598\" data-id=\"9351\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve12.jpg\" alt=\"\" class=\"wp-image-9351\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve12.jpg 900w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve12-480x319.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" data-id=\"9352\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve13.jpg\" alt=\"\" class=\"wp-image-9352\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve13.jpg 900w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve13-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"585\" data-id=\"9356\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve14.jpg\" alt=\"\" class=\"wp-image-9356\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve14.jpg 900w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/steve14-480x312.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" \/><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Tu fais quelque chose en parall\u00e8le de ton m\u00e9tier, des projets, des passions ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Barth : <\/strong>Rien de tr\u00e8s original, j\u2019en ai peur. J\u2019aime les films, les s\u00e9ries, les livres. Parfois je joue \u00e0 la switch o\u00f9 je sors voir un spectacle. J\u2019aime \u00eatre avec mon amoureuse et j\u2019aime partir en week-end avec les amis. Quand on ne part pas, il y a toujours un moment pour aller voir la famille dans l\u2019Ouest parisien (tr\u00e8s original, j\u2019avais pr\u00e9venu).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Peut-\u00eatre qu\u2019on pourrait mettre \u201cmanger\u201d dans mes passions. Pas forc\u00e9ment cuisiner, except\u00e9 le barbecue (rural on a dit), mais je suis assez attach\u00e9 \u00e0 la symbolique de la table o\u00f9 tout le monde se retrouve, partage et mange ensemble.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Du coup, quand on aime manger, on essaie de ne pas devenir trop gros. J\u2019essaie donc de faire un peu de sport. J\u2019ai d\u2019ailleurs d\u00e9couvert le Padel l\u2019ann\u00e9e derni\u00e8re et je le recommande \u00e0 tout le monde. C\u2019est une sorte de tennis sans les contraintes du<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">tennis. \u00c7a se joue sur un court plus petit qui est entour\u00e9 de plaques en verre. \u00c7a a d\u2019ailleurs \u00e9t\u00e9 invent\u00e9 par un Mexicain qui n\u2019avait pas assez de place dans son jardin et qui a donc construit un petit court qu\u2019il a emmur\u00e9 pour \u00e9viter d\u2019aller chercher les balles. La contrainte, la flemme, deux fabuleux vecteurs de cr\u00e9ation. Be flemmard.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tisane ? Si certains pr\u00e9f\u00e8rent les bienfaits d\u2019autres plantes pour r\u00e9fl\u00e9chir, je pr\u00e9f\u00e8re de loin me d\u00e9foncer \u00e0 grands coups de thym, romarin ou autre m\u00e9lange de citron et de menthe poivr\u00e9e. En plus, c\u2019est bon pour la sant\u00e9. Buvez de la tisane.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ah si, j\u2019adore les chats. J\u2019ai d\u2019ailleurs r\u00e9alis\u00e9 mon m\u00e9moire de fin d\u2019\u00e9tudes sur les chats dans la publicit\u00e9. Je n\u2019ai jamais trop compris comment le sujet avait \u00e9t\u00e9 accept\u00e9, mais c\u2019est pass\u00e9. Et \u00e9videmment, j\u2019adore encore plus mon chat, Mocky. Il participe r\u00e9guli\u00e8rement aux diff\u00e9rents briefs et il est parfois pr\u00e9sent \u00e0 quelques r\u00e9unions zoom.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/chat-barth.jpg\" alt=\"\" class=\"wp-image-9405\" width=\"389\" height=\"441\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benoit : <\/strong>Je suis hyper occup\u00e9 par 3 side projects. 3 enfants \u00e0 qui je donne autant de temps que je peux, et ma compagne qui est tr\u00e8s importante pour moi. Ce n\u2019est pas toujours simple de trouver le bon \u00e9quilibre entre sa vie pro et sa vie perso quand on travaille en agence donc je ne fais plus vraiment de projet parall\u00e8le comme avant. M\u00eame s\u2019il y a des exceptions et que je me laisse souvent tenter par un bon proac. Je me concentre sur ma famille et mes amis pour profiter de la vie, bien manger et voyager. Et puis ceux qui nous entourent sont aussi une belle source d\u2019inspiration. \u201cAll work and no play makes Jack a dull boy\u201d Pour les fans de Shining&#8230;.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Quel est le truc qui t&rsquo;a fait le plus halluciner ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Barth : <\/strong>C&rsquo;est technique \u00e7a comme question.<br>\u00c9videmment que ce qui fait halluciner, c\u2019est la connerie humaine, la m\u00e9chancet\u00e9, la guerre, l\u2019urgence climatique&#8230; On peut aussi halluciner en passant par Porte de la Chapelle un peu tard, ou dans un autre registre, avec l\u2019IA chatGPT de ce brave Elon qui va potentiellement me mettre au ch\u00f4mage dans les prochaines ann\u00e9es. Mais \u00e7a ne serait peut-\u00eatre pas tr\u00e8s positif comme sujet et je pr\u00e9f\u00e8re halluciner de fa\u00e7on positive.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je vais donc choisir One Piece.<br>Eiichir\u014d Oda. Son \u0153uvre a commenc\u00e9 \u00e0 \u00eatre publi\u00e9e en 1997. J\u2019avais 1 an. \u00c7a fait 25 ans qu\u2019il \u00e9crit son manga. 25 ans que Luffy cherche le One Piece. Oda fait des r\u00e9f\u00e9rences aujourd&rsquo;hui \u00e0 des chapitres qu\u2019il a \u00e9crits des ann\u00e9es en arri\u00e8re. C\u2019est compl\u00e8tement fou. Il sait o\u00f9 il va depuis le d\u00e9but et on est des millions \u00e0 travers le monde \u00e0 attendre religieusement chaque chapitre pour en d\u00e9couvrir toujours un peu plus sur le One Piece.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/image-2-1-1024x456.jpg\" alt=\"\" class=\"wp-image-9409\" width=\"613\" height=\"273\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benoit : <\/strong>Comme dit Barth, on vit \u00e0 une \u00e9poque hallucinante. Pendant qu\u2019on invente des IA capables de remplacer les humains, d\u2019autres plongent dans un obscurantisme tout ce qu\u2019il y a de plus moyen\u00e2geux.<br>Pour moi, je vais retenir les images du James Webb Space Telescope. C\u2019est hallucinant de remonter si loin dans le temps et dans l\u2019espace, de se dire que l\u2019on d\u00e9couvre les secrets de l\u2019univers. Que l\u2019\u00eatre humain va maintenant trouver des r\u00e9ponses \u00e0 des questions mill\u00e9naires. Et que tout \u00e7a passe par des images, des images magnifiques en plus. J\u2019avais \u00e9t\u00e9 tr\u00e8s touch\u00e9 par<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Un_point_bleu_p%C3%A2le\"> \u201ca pale blue dot\u201d <\/a>cette photo de la terre prise par Voyager1 en 1990 \u00e0 6 milliards de km nous montre presque po\u00e9tiquement \u00e0 quel point nous sommes petits. Alors voir de la po\u00e9sie dans l\u2019astrophysique alors qu\u2019on n\u2019y conna\u00eet rien, c\u2019est peut-\u00eatre \u00e7a halluciner. Et dire qu\u2019il y a des platistes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/image-2-2.jpg\" alt=\"\" class=\"wp-image-9415\" width=\"524\" height=\"592\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/image-2-2.jpg 524w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/image-2-2-480x542.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 524px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-medium-font-size wp-block-paragraph\">&#8230;<strong>et<\/strong> <strong>dans ton m\u00e9tier de publicitaire ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Barth : <\/strong>Quand on n&rsquo;ach\u00e8te pas mes id\u00e9es.<br>Plus s\u00e9rieusement, c\u2019est peut-\u00eatre tous ces annonceurs pr\u00eats \u00e0 d\u00e9penser une fortune pour passer inaper\u00e7us avec des pubs sans saveurs et sans id\u00e9es. Oui c\u2019est tr\u00e8s 99F, mais h\u00e9las, c\u2019est factuel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benoit : <\/strong>Je pense que la premi\u00e8re fois que je suis all\u00e9 sur un tournage, j\u2019ai hallucin\u00e9. C\u2019\u00e9tait une toute petite prod et pourtant voir les moyens d\u00e9ploy\u00e9s, les techniciens bosser, l\u2019\u00e9quipe g\u00e9rer les enfants infernaux qui devait tourner (et g\u00e9rer les parents infernaux aussi). Le r\u00e9alisateur, le chef op, la d\u00e9co&#8230; \u00e7a m&rsquo;a fait halluciner. Un des enfants m\u2019a mordu le bras et le r\u00e9sultat n\u2019\u00e9tait vraiment pas terrible mais j\u2019\u00e9tais tellement heureux d\u2019avoir particip\u00e9 \u00e0 un film que j\u2019ai ressenti une fiert\u00e9 assez mal plac\u00e9e. Le revoir aujourd\u2019hui me procurerait s\u00fbrement le sentiment inverse, question de maturit\u00e9.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Quelles sont les pubs que tu pr\u00e9f\u00e8res, tes classiques ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Barth : <\/strong>J&rsquo;ai beau avoir d\u00e9j\u00e0 fait l&rsquo;exercice plein de fois dans ma t\u00eate. C\u2019est comme choisir son meilleur film, son meilleur roman, son plat pr\u00e9f\u00e9r\u00e9 (magret de canard ros\u00e9, patate de Noirmoutier et sauce au miel). Et en plus, mon classement change assez r\u00e9guli\u00e8rement, car \u00e9videmment que je d\u00e9couvre encore des pubs. Voil\u00e0 donc une s\u00e9lection non exhaustive :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_ZzV7Qg_e500\"><div id=\"lyte_ZzV7Qg_e500\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FZzV7Qg_e500%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/ZzV7Qg_e500\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FZzV7Qg_e500%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"715\" data-id=\"9355\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/3ml3xjzkxy4x69fo49nxqrk2c8g0-1024x715.jpg\" alt=\"\" class=\"wp-image-9355\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/3ml3xjzkxy4x69fo49nxqrk2c8g0-1024x715.jpg 1024w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/3ml3xjzkxy4x69fo49nxqrk2c8g0-980x684.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/3ml3xjzkxy4x69fo49nxqrk2c8g0-480x335.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"715\" data-id=\"9353\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/5kp2fegpb4pck0tla2kb4f0qqb28-1024x715.jpg\" alt=\"\" class=\"wp-image-9353\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/5kp2fegpb4pck0tla2kb4f0qqb28-1024x715.jpg 1024w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/5kp2fegpb4pck0tla2kb4f0qqb28-980x684.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/5kp2fegpb4pck0tla2kb4f0qqb28-480x335.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"715\" data-id=\"9354\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/ptbmwa9zpdgxnnqczhwgj8790uxq-1024x715.jpg\" alt=\"\" class=\"wp-image-9354\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/ptbmwa9zpdgxnnqczhwgj8790uxq-1024x715.jpg 1024w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/ptbmwa9zpdgxnnqczhwgj8790uxq-980x684.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/ptbmwa9zpdgxnnqczhwgj8790uxq-480x335.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_GY6uJlI-t14\"><div id=\"lyte_GY6uJlI-t14\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FGY6uJlI-t14%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/GY6uJlI-t14\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FGY6uJlI-t14%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"485\" data-id=\"9361\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/7l4lre2fkbdheheqmj80uxgyfepm.jpg\" alt=\"\" class=\"wp-image-9361\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/7l4lre2fkbdheheqmj80uxgyfepm.jpg 750w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/7l4lre2fkbdheheqmj80uxgyfepm-480x310.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 750px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"485\" data-id=\"9362\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/8sv6dsnnn7sndcoq1dr6n6mwuzoi.jpg\" alt=\"\" class=\"wp-image-9362\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/8sv6dsnnn7sndcoq1dr6n6mwuzoi.jpg 750w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/8sv6dsnnn7sndcoq1dr6n6mwuzoi-480x310.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 750px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"485\" data-id=\"9363\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/a4fj6r22k7pbbathsyfjo6rdl7rd.jpg\" alt=\"\" class=\"wp-image-9363\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/a4fj6r22k7pbbathsyfjo6rdl7rd.jpg 750w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/a4fj6r22k7pbbathsyfjo6rdl7rd-480x310.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 750px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"485\" data-id=\"9366\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/aq0vgfw6znrp5462cm4knj8ooic1.jpg\" alt=\"\" class=\"wp-image-9366\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/aq0vgfw6znrp5462cm4knj8ooic1.jpg 750w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/aq0vgfw6znrp5462cm4knj8ooic1-480x310.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 750px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"485\" data-id=\"9367\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/bkltghj3lwr8vavkhyqvota9thj6.jpg\" alt=\"\" class=\"wp-image-9367\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/bkltghj3lwr8vavkhyqvota9thj6.jpg 750w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/bkltghj3lwr8vavkhyqvota9thj6-480x310.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 750px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"485\" data-id=\"9368\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/keigy9ybncauvyscgrjz2lidwwcp.jpg\" alt=\"\" class=\"wp-image-9368\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/keigy9ybncauvyscgrjz2lidwwcp.jpg 750w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/keigy9ybncauvyscgrjz2lidwwcp-480x310.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 750px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"485\" data-id=\"9365\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/jui09b9e1kj376yde1mym9je7xso.jpg\" alt=\"\" class=\"wp-image-9365\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/jui09b9e1kj376yde1mym9je7xso.jpg 750w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/jui09b9e1kj376yde1mym9je7xso-480x310.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 750px, 100vw\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/9s0jbl760lmrvxa7byvqy18id2g3.jpg\" alt=\"\" class=\"wp-image-9364\" width=\"836\" height=\"541\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/9s0jbl760lmrvxa7byvqy18id2g3.jpg 836w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/9s0jbl760lmrvxa7byvqy18id2g3-480x310.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 836px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_SqqroFfqKRc\"><div id=\"lyte_SqqroFfqKRc\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FSqqroFfqKRc%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/SqqroFfqKRc\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FSqqroFfqKRc%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_W5Z7esEVqLA\"><div id=\"lyte_W5Z7esEVqLA\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FW5Z7esEVqLA%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/W5Z7esEVqLA\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FW5Z7esEVqLA%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-8 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"9359\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/i4ged7sbvtr31n5w91xur0n8mpiq-1024x683.jpg\" alt=\"\" class=\"wp-image-9359\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/i4ged7sbvtr31n5w91xur0n8mpiq-980x653.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/i4ged7sbvtr31n5w91xur0n8mpiq-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"9357\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/qk4itu2rlmjqrdns1ohvr72cf5tj-1024x683.jpg\" alt=\"\" class=\"wp-image-9357\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/qk4itu2rlmjqrdns1ohvr72cf5tj-980x653.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/qk4itu2rlmjqrdns1ohvr72cf5tj-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"9360\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/4ahajodztw39qe9sueejsrwge9qv-1024x683.jpg\" alt=\"\" class=\"wp-image-9360\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/4ahajodztw39qe9sueejsrwge9qv-980x653.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/4ahajodztw39qe9sueejsrwge9qv-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"9358\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/baft3rytlmxnp6j8u64k3x7x66fw-1024x683.jpg\" alt=\"\" class=\"wp-image-9358\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/baft3rytlmxnp6j8u64k3x7x66fw-980x653.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/baft3rytlmxnp6j8u64k3x7x66fw-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_2WYdJP97n44\"><div id=\"lyte_2WYdJP97n44\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2F2WYdJP97n44%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/2WYdJP97n44\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2F2WYdJP97n44%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default wp-block-gallery-9 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"477\" height=\"600\" data-id=\"6326\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/slider10\/eurostar-3.jpeg\" alt=\"\" class=\"wp-image-6326\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"422\" height=\"600\" data-id=\"6329\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/slider10\/eurostar-7.jpeg\" alt=\"\" class=\"wp-image-6329\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"443\" height=\"600\" data-id=\"6323\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/slider10\/eurostar-6.jpeg\" alt=\"\" class=\"wp-image-6323\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"817\" height=\"600\" data-id=\"6328\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/slider10\/eurostar-9.jpeg\" alt=\"\" class=\"wp-image-6328\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/slider10\/eurostar-9.jpeg 817w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/slider10\/eurostar-9-600x441.jpeg 600w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/slider10\/eurostar-9-768x564.jpeg 768w\" sizes=\"auto, (max-width: 817px) 100vw, 817px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"812\" height=\"600\" data-id=\"6327\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/slider10\/eurostar-8.jpeg\" alt=\"\" class=\"wp-image-6327\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/slider10\/eurostar-8.jpeg 812w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/slider10\/eurostar-8-600x443.jpeg 600w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/slider10\/eurostar-8-768x567.jpeg 768w\" sizes=\"auto, (max-width: 812px) 100vw, 812px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"786\" height=\"600\" data-id=\"6324\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/slider10\/eurostar-2.jpeg\" alt=\"\" class=\"wp-image-6324\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/slider10\/eurostar-2.jpeg 786w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/slider10\/eurostar-2-600x458.jpeg 600w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/slider10\/eurostar-2-768x586.jpeg 768w\" sizes=\"auto, (max-width: 786px) 100vw, 786px\" \/><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-10 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"836\" height=\"520\" data-id=\"9373\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/Campagne-publicitaire-Heinz.jpg\" alt=\"\" class=\"wp-image-9373\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/Campagne-publicitaire-Heinz.jpg 836w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/Campagne-publicitaire-Heinz-480x299.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 836px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"9375\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/heinz-07-1024x576.jpg\" alt=\"\" class=\"wp-image-9375\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/heinz-07-980x551.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/heinz-07-480x270.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"9374\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/heinz-05-1024x576.jpg\" alt=\"\" class=\"wp-image-9374\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/heinz-05-980x551.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/heinz-05-480x270.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_APoGHH1Ns2M\"><div id=\"lyte_APoGHH1Ns2M\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FAPoGHH1Ns2M%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/APoGHH1Ns2M\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FAPoGHH1Ns2M%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_VTWDw6NIbPU\"><div id=\"lyte_VTWDw6NIbPU\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FVTWDw6NIbPU%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/VTWDw6NIbPU\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FVTWDw6NIbPU%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">\u00c7a, j\u2019ai pleur\u00e9.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_ZEbYEGrmkPg\"><div id=\"lyte_ZEbYEGrmkPg\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FZEbYEGrmkPg%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/ZEbYEGrmkPg\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FZEbYEGrmkPg%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benoit : <\/strong>C\u2019est une question casse-t\u00eate, je vais surtout compiler celle que j\u2019ai re-re-re-regard\u00e9 r\u00e9cemment, il doit y avoir une raison. Allez, ce n&rsquo;est pas tr\u00e8s original, mais commen\u00e7ons par un grand classique qui fait r\u00e9fl\u00e9chir :<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"597\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/slider27\/harley-davidson-1.jpeg\" alt=\"\" class=\"wp-image-6460\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/slider27\/harley-davidson-1.jpeg 900w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/slider27\/harley-davidson-1-600x398.jpeg 600w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/slider27\/harley-davidson-1-768x509.jpeg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et ensuite celle que les DC m\u2019ont le plus montr\u00e9e dans ma vie, jusqu\u2019au dernier en date, il y a une semaine. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/axa-insurance-the-2200eur-pistachios-33fc585aa69c9402fb0822789f.jpg\" alt=\"\" class=\"wp-image-9376\" width=\"697\" height=\"494\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/axa-insurance-the-2200eur-pistachios-33fc585aa69c9402fb0822789f.jpg 697w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/axa-insurance-the-2200eur-pistachios-33fc585aa69c9402fb0822789f-480x340.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 697px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parce que c\u2019est fou en terme d\u2019image et que \u00e7a dit des choses sur notre m\u00e9tier.<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_YexcHrwxP-o\"><div id=\"lyte_YexcHrwxP-o\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FYexcHrwxP-o%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/YexcHrwxP-o\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FYexcHrwxP-o%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En petit hommage \u00e0 l\u2019immense talent d\u2019Ale Burset<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-11 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"726\" height=\"1024\" data-id=\"9378\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/BK_birthday_clowns_ENGLISH_01-768x1083-1-726x1024.jpg\" alt=\"\" class=\"wp-image-9378\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/BK_birthday_clowns_ENGLISH_01-768x1083-1-726x1024.jpg 726w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/BK_birthday_clowns_ENGLISH_01-768x1083-1-480x677.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 726px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"726\" height=\"1024\" data-id=\"9379\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/BK_birthday_clowns_ENGLISH_03-768x1083-1-726x1024.jpg\" alt=\"\" class=\"wp-image-9379\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/BK_birthday_clowns_ENGLISH_03-768x1083-1-726x1024.jpg 726w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/BK_birthday_clowns_ENGLISH_03-768x1083-1-480x677.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 726px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"726\" height=\"1024\" data-id=\"9377\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/BK_birthday_clowns_ENGLISH_04-768x1083-1-726x1024.jpg\" alt=\"\" class=\"wp-image-9377\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/BK_birthday_clowns_ENGLISH_04-768x1083-1-726x1024.jpg 726w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/BK_birthday_clowns_ENGLISH_04-768x1083-1-480x677.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 726px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"726\" height=\"1024\" data-id=\"9380\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/BK_birthday_clowns_ENGLISH_05-768x1083-1-726x1024.jpg\" alt=\"\" class=\"wp-image-9380\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/BK_birthday_clowns_ENGLISH_05-768x1083-1-726x1024.jpg 726w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/BK_birthday_clowns_ENGLISH_05-768x1083-1-480x677.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 726px, 100vw\" \/><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Plus r\u00e9cent c\u2019est tr\u00e8s beau, subtil et tr\u00e8s malin en copy et en DA.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-12 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" data-id=\"9381\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/davidmadrid-burgerking-temps-confus-1-724x1024.jpg\" alt=\"\" class=\"wp-image-9381\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/davidmadrid-burgerking-temps-confus-1-724x1024.jpg 724w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/davidmadrid-burgerking-temps-confus-1-480x679.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 724px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" data-id=\"9382\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/davidmadrid-burgerking-temps-confus-2-724x1024.jpg\" alt=\"\" class=\"wp-image-9382\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/davidmadrid-burgerking-temps-confus-2-724x1024.jpg 724w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/davidmadrid-burgerking-temps-confus-2-480x679.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 724px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" data-id=\"9383\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/davidmadrid-burgerking-temps-confus-3-724x1024.jpg\" alt=\"\" class=\"wp-image-9383\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/davidmadrid-burgerking-temps-confus-3-724x1024.jpg 724w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/davidmadrid-burgerking-temps-confus-3-480x679.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 724px, 100vw\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Le degr\u00e9s Z\u00e9ro de la r\u00e9daction, le visuel qui dit tout et pas de produit<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-13 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"735\" data-id=\"9387\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/u_PJR4_7OF0gVZHfLy0MALxnW9NFWwsLt2wMkByvdI4-1024x735.jpg\" alt=\"\" class=\"wp-image-9387\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/u_PJR4_7OF0gVZHfLy0MALxnW9NFWwsLt2wMkByvdI4-980x704.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/u_PJR4_7OF0gVZHfLy0MALxnW9NFWwsLt2wMkByvdI4-480x345.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"734\" data-id=\"9384\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/mediarepo_34557799_fd7f552d73f5ee3e_web-1024x734.jpg\" alt=\"\" class=\"wp-image-9384\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/mediarepo_34557799_fd7f552d73f5ee3e_web-1024x734.jpg 1024w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/mediarepo_34557799_fd7f552d73f5ee3e_web-980x702.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/mediarepo_34557799_fd7f552d73f5ee3e_web-480x344.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"734\" data-id=\"9385\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/mediarepo_34557801_b7643cb4136e9c05_web-1024x734.jpg\" alt=\"\" class=\"wp-image-9385\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/mediarepo_34557801_b7643cb4136e9c05_web-1024x734.jpg 1024w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/mediarepo_34557801_b7643cb4136e9c05_web-980x702.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/mediarepo_34557801_b7643cb4136e9c05_web-480x344.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"735\" data-id=\"9386\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/Jgr3ZQi8_MMRm_EVtCvibAQ1LnAfDK3h0WiQAguIzi4-1024x735.jpg\" alt=\"\" class=\"wp-image-9386\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/Jgr3ZQi8_MMRm_EVtCvibAQ1LnAfDK3h0WiQAguIzi4-980x704.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/Jgr3ZQi8_MMRm_EVtCvibAQ1LnAfDK3h0WiQAguIzi4-480x345.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Celle-ci que j&rsquo;ai d\u00e9couvert tr\u00e8s r\u00e9cemment en travaillant sur Vision du monde, j\u2019adore l\u2019accroche. <br><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"495\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/Capture-decran-2023-01-26-a-20.54.01-1024x495.jpg\" alt=\"\" class=\"wp-image-9388\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/Capture-decran-2023-01-26-a-20.54.01-980x474.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/Capture-decran-2023-01-26-a-20.54.01-480x232.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c7a c\u2019est le genre de raccourcie visuel que j\u2019adore<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>https:\/\/www.adsoftheworld.com\/campaigns\/truck-9b3675d2-4b46-4d78-84a0-3f 92b1cc47ba<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9norme craft<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-14 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"679\" data-id=\"9389\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/nfoi0q0b40qiy1u32czoskmfzxkt-1024x679.jpg\" alt=\"\" class=\"wp-image-9389\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/nfoi0q0b40qiy1u32czoskmfzxkt-980x650.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/nfoi0q0b40qiy1u32czoskmfzxkt-480x318.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"679\" data-id=\"9390\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/xu26vj6a7873zucodivc6mgigvgt-1024x679.jpg\" alt=\"\" class=\"wp-image-9390\" srcset=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/xu26vj6a7873zucodivc6mgigvgt-980x650.jpg 980w, https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/xu26vj6a7873zucodivc6mgigvgt-480x318.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Ces deux-l\u00e0 me font rire pour toujours<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_Y1xorK_IETs\"><div id=\"lyte_Y1xorK_IETs\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FY1xorK_IETs%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/Y1xorK_IETs\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FY1xorK_IETs%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_3393O1uD_w8\"><div id=\"lyte_3393O1uD_w8\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2F3393O1uD_w8%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/3393O1uD_w8\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2F3393O1uD_w8%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">Et \u00e7a, c&rsquo;est \u00e9videmment un pur chef-d\u2019\u0153uvre.<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_18CGnEpeRfI\"><div id=\"lyte_18CGnEpeRfI\" data-src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2F18CGnEpeRfI%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/18CGnEpeRfI\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2F18CGnEpeRfI%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Tu as des mod\u00e8les de cr\u00e9atifs dans la publicit\u00e9 ? ou en dehors, des gens qui t&rsquo;inspirent ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Barth : <\/strong>Mod\u00e8le. Un mot fort.<br>Et bien pour \u00eatre original, prenons le p\u00e8re fondateur : Doyle Dane Bernbach. J\u2019ai une annonce originale Volkswagen de 1964 accroch\u00e9e au mur avec comme accroche <em>\u201cPourquoi la VW p\u00e8se-t-elle si lourd\u201d. <\/em>On ne va pas refaire toute sa carri\u00e8re et son g\u00e9nie, mais pour r\u00e9sumer vulgairement son travail en une ligne : c\u2019est lui qui a invent\u00e9 la bonne pub.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je dois avouer que je suis assez fan de l\u2019agence Maximum Effort de Ryan Reynolds. Est-ce que \u00e7a marcherait si ce n\u2019\u00e9tait pas Reynolds dans tous les spots ? J\u2019aime \u00e0 croire que oui.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sur une note moins publicitaire, j\u2019aime beaucoup Fabrice Luchini. Sa folie, son obsession du mot et tout son travail pour restituer et faire vivre les grands textes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Peut-\u00eatre aussi South Park de Trey Parker et Matt Stone. Si ces deux-l\u00e0 avaient fait de la pub, ce seraient certainement eux mes mod\u00e8les de cr\u00e9atifs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benoit : <\/strong>Comme Barth m\u2019a piqu\u00e9 Bernbach, je vais citer des gens qui ont r\u00e9volutionn\u00e9 leur m\u00e9tier, dont le travail a d\u00e9pass\u00e9 le cadre de leur discipline et qui<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">influencent encore notre vision : Raymond Loewy, \u201cla laideur se vend mal\u201d c\u2019est une bonne accroche. Frank Lloyd Wright aussi. Et en ce moment je lis pas mal de livres sur la vie d\u2019un petit illustrateur du 16\u00e8me si\u00e9cle, Le Caravage, tu connais ? J\u2019admire ses cadrages, ses lumi\u00e8res et ses choix symboliques dans ses tableaux. Mais bon ce n\u2019est pas vraiment un mod\u00e8le de vie. Cela dit, le fait qu\u2019un peintre du 16\u00e8me si\u00e8cle parle \u00e0 un DA en 2023 me conforte dans l\u2019id\u00e9e que les images ont la magie de nous rassembler.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>A ton avis, le milieu publicitaire va \u00e9voluer de quelle mani\u00e8re ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Barth : <\/strong>Pendant le confinement en 2020, je m\u2019\u00e9tais amus\u00e9 \u00e0 \u00e9crire une petite fiction :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/jai-un-pote-dans-la.com\/la-pub-apres-le-coronavirus-imaginee-par-un-jeune-creatif-de-24-ans\/\">https:\/\/jai-un-pote-dans-la.com\/la-pub-apres-le-coronavirus-imaginee-par-un-jeune-creatif-de-24-ans\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bon la pub sur Netflix, c\u2019\u00e9tait facile, ok.<br>Le truc assez pr\u00e9occupant, c\u2019est que dans beaucoup de secteurs, on a du mal \u00e0 cr\u00e9er. Ou du moins, la cr\u00e9ation a du mal \u00e0 se faire acheter. On fait des suites, des pr\u00e9quelles, des remakes et \u00e7a ne pr\u00e9sage rien de bon. Donc \u00e9tant d\u2019un \u00e9ternel optimiste, je pense qu\u2019on va r\u00e9ussir \u00e0 se sortir de cette mauvaise boucle et que les annonceurs recommenceront \u00e0 commander l&rsquo;inattendue, car \u00e7a sera \u00e0 la demande g\u00e9n\u00e9rale du public.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019id\u00e9e primera toujours. C\u2019est le moteur. Et m\u00eame si parfois certains pr\u00e9f\u00e8rent la bouder \u00e0 grands coups de stats et de tableurs excel, ceux qui l&rsquo;utilisent sont tellement r\u00e9compens\u00e9s que \u00e7a ne peut qu\u2019influencer les autres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benoit : <\/strong>Le milieu publicitaire change doucement, et plut\u00f4t en bien. Il suit les questions que se pose notre soci\u00e9t\u00e9. Sur l\u2019\u00e9galit\u00e9 de salaire, le harc\u00e8lement, la place des femmes, le racisme, le respect de l&rsquo;environnement. J\u2019ai l\u2019impression de travailler avec des gens et pour des gens plus conscients des enjeux, plus attentifs et aussi plus engag\u00e9s, qui veulent que leurs id\u00e9aux transparaissent dans leur cr\u00e9ation. On peut sembler mal plac\u00e9 en agence parce que l\u2019on est au c\u0153ur du syst\u00e8me de consommation mais on est aussi tr\u00e8s bien plac\u00e9 pour accompagner les changements soci\u00e9taux par nos choix cr\u00e9atifs, par ce que l\u2019on repr\u00e9sente dans nos pubs. Et je pense que la plupart de nos clients ont aussi besoin de s\u2019engager, \u00e7a tombe bien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Un conseil pour r\u00e9ussir dans ce m\u00e9tier ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Barth : <\/strong>Oui, moi et ma tr\u00e8s longue carri\u00e8re dans la pub, nous avons un conseil. Sinc\u00e8rement, je pense que la curiosit\u00e9 est la clef. C&rsquo;est bateau mais c\u2019est tellement vrai. Tout peut servir pour avoir une id\u00e9e. Il ne faut pas avoir peur de poser des questions, surtout \u00e0 ses a\u00een\u00e9es et essayer le plus possible de rencontrer les gens du m\u00e9tier. \u00c9videmment, il y aura des vents, mais ce n&rsquo;est pas bien grave car seul l\u2019ego est touch\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benoit : <\/strong>Un conseil de senior : il faut \u00e9couter les seniors, et si possible les couvrir d\u2019attention et de cadeaux comme Barth l&rsquo;a fait avec moi. Plus s\u00e9rieusement, \u00e9couter les gens qui ont de l&rsquo;exp\u00e9rience fait progresser, ce sont des raccourcis pour le cerveau.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si on n\u2019est pas en accord avec ce qu\u2019on produit, si on n\u2019aime pas ce que l\u2019on fait, il ne faut pas h\u00e9siter \u00e0 changer d\u2019agence, \u00e0 partir \u00e0 l\u2019aventure. Sinon on perd son temps.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il faut piger, beaucoup piger, regarder tout ce qui sort, plusieurs fois pour en comprendre les m\u00e9caniques cr\u00e9atives. Il faut aller voir qui produit les campagnes, qui est le r\u00e9al, qui est le photographe&#8230; se faire une culture publicitaire et en discuter avec les autres cr\u00e9as. Et bien s\u00fbr, il ne faut pas s&rsquo;arr\u00eater l\u00e0, s\u2019enrichir de tout. L\u2019inspiration se trouve partout, il suffit d\u2019\u00eatre curieux. Il faut enrichir son travail de son exp\u00e9rience personnelle, sinon on r\u00e9p\u00e8te juste les m\u00eames mod\u00e8les et on manque d\u2019originalit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour finir, ne pas \u00eatre d\u00e9\u00e7u trop longtemps si un projet \u00e9choue, on jette 90% de ce que l\u2019on produit, \u00e7a fait mal des fois, mais il ne faut pas que \u00e7a emp\u00eache d\u2019avancer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce qui est jug\u00e9, c&rsquo;est votre travail, pas vous, et la logique des annonceurs n\u2019est pas celle des cr\u00e9atifs. La meilleure cr\u00e9ation n\u2019est pas forc\u00e9ment celle qui sort alors, gardez un peu de distance.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Pour les contacter et les d\u00e9baucher un jour : <a href=\"mailto:antoinebarth01@gmail.com\">antoinebarth01@gmail.com<\/a> et <a href=\"mailto:benoit.jung@gmail.com\">benoit.jung@gmail.com<\/a><br><\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vous \u00eates respectivement CR et DA chez Steve, vous venez d&rsquo;o\u00f9 ?<\/p>\n","protected":false},"author":4,"featured_media":9394,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_uag_custom_page_level_css":"","footnotes":""},"categories":[44,5,6,107],"tags":[],"class_list":["post-9338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-creatif","category-directeurs-artistiques","category-redacteur","category-steve"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Antoine Barth et Benoit Jung &#8226; C&#039;est qui les Cr\u00e9as ?<\/title>\n<meta name=\"description\" content=\"Vous \u00eates respectivement CR et DA chez Steve, vous venez d&#039;o\u00f9 ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/antoine-barth-benoit-jung\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C&#039;est qui les Cr\u00e9as ? &#8226; Antoine Barth et Benoit Jung\" \/>\n<meta property=\"og:description\" content=\"Vous \u00eates respectivement CR et DA chez Steve, vous venez d&#039;o\u00f9 ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/antoine-barth-benoit-jung\/\" \/>\n<meta property=\"og:site_name\" content=\"C&#039;est qui les Cr\u00e9as ?\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CestquilesCreas\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-26T20:03:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-27T09:49:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1111\" \/>\n\t<meta property=\"og:image:height\" content=\"790\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gregory ferembach\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"C&#039;est qui les Cr\u00e9as ? &#8226; Antoine Barth et Benoit Jung\" \/>\n<meta name=\"twitter:description\" content=\"Vous \u00eates respectivement CR et DA chez Steve, vous venez d&#039;o\u00f9 ?\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"gregory ferembach\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"30 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/antoine-barth-benoit-jung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/antoine-barth-benoit-jung\\\/\"},\"author\":{\"name\":\"gregory ferembach\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/person\\\/228b651374249a02f20a1921f0e2516b\"},\"headline\":\"Antoine Barth et Benoit Jung\",\"datePublished\":\"2023-01-26T20:03:39+00:00\",\"dateModified\":\"2023-01-27T09:49:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/antoine-barth-benoit-jung\\\/\"},\"wordCount\":4001,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/antoine-barth-benoit-jung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/barth-jung.jpg\",\"articleSection\":[\".cr\u00e9atif\",\".Directeur Artistique\",\".R\u00e9dacteur\",\"Steve\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/antoine-barth-benoit-jung\\\/\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/antoine-barth-benoit-jung\\\/\",\"name\":\"Antoine Barth et Benoit Jung &#8226; C&#039;est qui les Cr\u00e9as ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/antoine-barth-benoit-jung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/antoine-barth-benoit-jung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/barth-jung.jpg\",\"datePublished\":\"2023-01-26T20:03:39+00:00\",\"dateModified\":\"2023-01-27T09:49:06+00:00\",\"description\":\"Vous \u00eates respectivement CR et DA chez Steve, vous venez d'o\u00f9 ?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/antoine-barth-benoit-jung\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/antoine-barth-benoit-jung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/antoine-barth-benoit-jung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/barth-jung.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/barth-jung.jpg\",\"width\":1111,\"height\":790},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/creatif\\\/antoine-barth-benoit-jung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Antoine Barth et Benoit Jung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#website\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\",\"name\":\"C'est qui les Cr\u00e9as ?\",\"description\":\"D\u00e9couvrez les cr\u00e9atifs, leurs parcours et leurs (en)vies...\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#organization\",\"name\":\"C'est qui les Cr\u00e9as ?\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-cqlc-1024x368-3.png\",\"contentUrl\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-cqlc-1024x368-3.png\",\"width\":1024,\"height\":368,\"caption\":\"C'est qui les Cr\u00e9as ?\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CestquilesCreas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ferembach.com\\\/cestquilescreas\\\/#\\\/schema\\\/person\\\/228b651374249a02f20a1921f0e2516b\",\"name\":\"gregory ferembach\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g\",\"caption\":\"gregory ferembach\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Antoine Barth et Benoit Jung &#8226; C&#039;est qui les Cr\u00e9as ?","description":"Vous \u00eates respectivement CR et DA chez Steve, vous venez d'o\u00f9 ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/antoine-barth-benoit-jung\/","og_locale":"fr_FR","og_type":"article","og_title":"C&#039;est qui les Cr\u00e9as ? &#8226; Antoine Barth et Benoit Jung","og_description":"Vous \u00eates respectivement CR et DA chez Steve, vous venez d'o\u00f9 ?","og_url":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/antoine-barth-benoit-jung\/","og_site_name":"C&#039;est qui les Cr\u00e9as ?","article_publisher":"https:\/\/www.facebook.com\/CestquilesCreas\/","article_published_time":"2023-01-26T20:03:39+00:00","article_modified_time":"2023-01-27T09:49:06+00:00","og_image":[{"width":1111,"height":790,"url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung.jpg","type":"image\/jpeg"}],"author":"gregory ferembach","twitter_card":"summary_large_image","twitter_title":"C&#039;est qui les Cr\u00e9as ? &#8226; Antoine Barth et Benoit Jung","twitter_description":"Vous \u00eates respectivement CR et DA chez Steve, vous venez d'o\u00f9 ?","twitter_image":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung.jpg","twitter_misc":{"\u00c9crit par":"gregory ferembach","Dur\u00e9e de lecture estim\u00e9e":"30 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/antoine-barth-benoit-jung\/#article","isPartOf":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/antoine-barth-benoit-jung\/"},"author":{"name":"gregory ferembach","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/person\/228b651374249a02f20a1921f0e2516b"},"headline":"Antoine Barth et Benoit Jung","datePublished":"2023-01-26T20:03:39+00:00","dateModified":"2023-01-27T09:49:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/antoine-barth-benoit-jung\/"},"wordCount":4001,"publisher":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/antoine-barth-benoit-jung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung.jpg","articleSection":[".cr\u00e9atif",".Directeur Artistique",".R\u00e9dacteur","Steve"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/antoine-barth-benoit-jung\/","url":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/antoine-barth-benoit-jung\/","name":"Antoine Barth et Benoit Jung &#8226; C&#039;est qui les Cr\u00e9as ?","isPartOf":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/antoine-barth-benoit-jung\/#primaryimage"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/antoine-barth-benoit-jung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung.jpg","datePublished":"2023-01-26T20:03:39+00:00","dateModified":"2023-01-27T09:49:06+00:00","description":"Vous \u00eates respectivement CR et DA chez Steve, vous venez d'o\u00f9 ?","breadcrumb":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/antoine-barth-benoit-jung\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/antoine-barth-benoit-jung\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/antoine-barth-benoit-jung\/#primaryimage","url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung.jpg","contentUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung.jpg","width":1111,"height":790},{"@type":"BreadcrumbList","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/creatif\/antoine-barth-benoit-jung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ferembach.com\/cestquilescreas\/"},{"@type":"ListItem","position":2,"name":"Antoine Barth et Benoit Jung"}]},{"@type":"WebSite","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#website","url":"https:\/\/www.ferembach.com\/cestquilescreas\/","name":"C'est qui les Cr\u00e9as ?","description":"D\u00e9couvrez les cr\u00e9atifs, leurs parcours et leurs (en)vies...","publisher":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ferembach.com\/cestquilescreas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#organization","name":"C'est qui les Cr\u00e9as ?","url":"https:\/\/www.ferembach.com\/cestquilescreas\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/logo\/image\/","url":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2020\/02\/logo-cqlc-1024x368-3.png","contentUrl":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2020\/02\/logo-cqlc-1024x368-3.png","width":1024,"height":368,"caption":"C'est qui les Cr\u00e9as ?"},"image":{"@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CestquilesCreas\/"]},{"@type":"Person","@id":"https:\/\/www.ferembach.com\/cestquilescreas\/#\/schema\/person\/228b651374249a02f20a1921f0e2516b","name":"gregory ferembach","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/605c4bda0e1d2a91637e7bb2eb4af75b09419585355d212ee36e067ca646749c?s=96&d=mm&r=g","caption":"gregory ferembach"}}]}},"uagb_featured_image_src":{"full":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung.jpg",1111,790,false],"thumbnail":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung-120x120.jpg",120,120,true],"medium":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung-60x43.jpg",60,43,true],"medium_large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung-768x546.jpg",768,546,true],"large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung-1024x728.jpg",1024,728,true],"1536x1536":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung.jpg",1111,790,false],"2048x2048":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung.jpg",1111,790,false],"et-pb-post-main-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung-400x250.jpg",400,250,true],"et-pb-post-main-image-fullwidth":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung-1080x675.jpg",1080,675,true],"et-pb-portfolio-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung-400x284.jpg",400,284,true],"et-pb-portfolio-module-image":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung-510x382.jpg",510,382,true],"et-pb-portfolio-image-single":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung-1080x768.jpg",1080,768,true],"et-pb-gallery-module-image-portrait":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung-400x516.jpg",400,516,true],"et-pb-post-main-image-fullwidth-large":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung.jpg",1111,790,false],"et-pb-image--responsive--desktop":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung.jpg",1013,720,false],"et-pb-image--responsive--tablet":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung-980x697.jpg",775,551,true],"et-pb-image--responsive--phone":["https:\/\/www.ferembach.com\/cestquilescreas\/wp-content\/uploads\/2023\/01\/barth-jung-480x341.jpg",380,270,true]},"uagb_author_info":{"display_name":"gregory ferembach","author_link":"https:\/\/www.ferembach.com\/cestquilescreas\/author\/gregoryferembach\/"},"uagb_comment_info":0,"uagb_excerpt":"Vous \u00eates respectivement CR et DA chez Steve, vous venez d'o\u00f9 ?","_links":{"self":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts\/9338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/comments?post=9338"}],"version-history":[{"count":0,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/posts\/9338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/media\/9394"}],"wp:attachment":[{"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/media?parent=9338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/categories?post=9338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ferembach.com\/cestquilescreas\/wp-json\/wp\/v2\/tags?post=9338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}